{"id":4867,"date":"2018-12-10T17:29:03","date_gmt":"2018-12-10T17:29:03","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=4867"},"modified":"2023-07-21T14:34:42","modified_gmt":"2023-07-21T19:34:42","slug":"consiguieron-lo-que-nunca-antes","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/consiguieron-lo-que-nunca-antes\/","title":{"rendered":"Consiguieron lo que nunca antes."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.semmexico.com\/gallery-post.php?id=6610#\">Redacci\u00f3n<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 10 diciembre 2018.- Legisladores federales exhortaron a la Comisi\u00f3n Nacional de Cultura F\u00edsica y Deporte (Conade) para que otorgue un reconocimiento a las integrantes de la Selecci\u00f3n Nacional Sub 17 de futbol, y su equipo t\u00e9cnico, por el subcampeonato alcanzado en el Mundial femenil, por haber puesto en alto el nombre de nuestro pa\u00eds al obtener el subcampeonato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diputada Ver\u00f3nica Beatriz Ju\u00e1rez Pi\u00f1a y Jos\u00e9 Ricardo Gallardo Cardona, ambos del PRD resaltaron que, a diferencia de pasados torneos mundiales de futbol integrados por varones, la Selecci\u00f3n Mexicana Femenil Sub 17 en su primera participaci\u00f3n en este tipo de competencia, logr\u00f3 llegar hasta la final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl tricolor consigui\u00f3 algo nunca antes visto en la historia del balompi\u00e9 nacional: un subcampeonato del mundo en dicha categor\u00eda femenil, as\u00ed tambi\u00e9n, las mexicanas se instalaron por primera vez en su historia en la fase de las cuatro mejores selecciones de futbol femenil\u201d, indicaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComo mujeres han llegado al lugar m\u00e1s alto, reservado hist\u00f3ricamente para los hombres, donde son ellos los que se llevan el reconocimiento social, los mejores patrocinios y la atenci\u00f3n generalizada de los medios de comunicaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ju\u00e1rez Pi\u00f1a y Gallardo Cardona se pronunciaron porque este ejemplo sea replicado ampliamente no s\u00f3lo en el futbol, sino dentro de todos los espacios deportivos p\u00fablicos y privados para generar en todas y todos mayor confianza y compromiso por alcanzar las metas, anhelos, esperanzas y sue\u00f1os que toda persona quiere hacer realidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, destacaron la importancia de que legisladoras y legisladores de la LXIV Legislatura reconozcan p\u00fablicamente a las jugadoras, as\u00ed como felicitar a su cuerpo t\u00e9cnico. La propuesta fue turnada a la Comisi\u00f3n de Deporte para su dictamen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n SemM\u00e9xico, Cd. de M\u00e9xico, 10 diciembre 2018.- Legisladores federales exhortaron a la Comisi\u00f3n Nacional de Cultura F\u00edsica y Deporte (Conade) para que otorgue un reconocimiento a las integrantes de la Selecci\u00f3n Nacional Sub 17 de futbol, y su equipo t\u00e9cnico, por el subcampeonato alcanzado en el Mundial femenil, por haber puesto en alto el [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[689,50],"tags":[],"class_list":["post-4867","post","type-post","status-publish","format-standard","has-post-thumbnail","category-689","category-congreso"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/4867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=4867"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/4867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/4868"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=4867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=4867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=4867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}