{"id":48593,"date":"2022-04-18T07:18:26","date_gmt":"2022-04-18T13:18:26","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=48593"},"modified":"2023-07-21T19:02:28","modified_gmt":"2023-07-22T00:02:28","slug":"miradas-de-reportero-libertad-de-prensa-las-encuestas-muestran-que-ha-crecido","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/miradas-de-reportero-libertad-de-prensa-las-encuestas-muestran-que-ha-crecido\/","title":{"rendered":"Miradas de reportero| Libertad de prensa. Las encuestas muestran que ha crecido"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&nbsp;Rogelio Hern\u00e1ndez L\u00f3pez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 18 de abril, 2022.- Colegas \u00bfpor qu\u00e9 no nos asomamos al informe m\u00e1s reciente de Art\u00edculo 19 sobre libertad de expresi\u00f3n y lo contrastamos con lo que dicen dos encuestas sobre el tema?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, la organizaci\u00f3n de origen ingl\u00e9s asegura que esta libertad ha disminuido en el actual sexenio, mientras que dos mediciones de la percepci\u00f3n popular indican que ha crecido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que creerles m\u00e1s a las encuestas porque est\u00e1 probado, hasta el cansancio, que la percepci\u00f3n de los habitantes de un pa\u00eds refleja mejor la realidad y que no hay mejor manera de evaluar el estado de \u00e1nimo social que por medio de las encuestas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se ha demostrado en sentido contrario, que todos los an\u00e1lisis siempre reflejar\u00e1n los sesgos culturales, ideol\u00f3gicos y pol\u00edticos del momento de las personas que los elaboran.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso siempre ser\u00e1 m\u00e1s recomendable basarse en las encuestas para obtener una mejor aproximaci\u00f3n de la realidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El contraste<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre el tema de libertad de expresi\u00f3n y su enfoque de libertad de prensa tomemos los datos de las empresas Consulta Mitofsky y Parametr\u00eda. Ambas han demostrado seriedad en la utilizaci\u00f3n de los m\u00e9todos de las ciencias exactas para detectar los estados de \u00e1nimo social de cada momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 22 de febrero la empresa que dirige Roy Campos difundi\u00f3 su encuesta sobre Libertad de prensa. En ella registr\u00f3 que el 66 por ciento de las personas encuestadas <em>\u201ccree que existe mucha\/regular libertad de la prensa para publicar, difundir, informar y comentar en M\u00e9xico.\u201d <\/em>Estoes 27 por ciento m\u00e1s que cinco a\u00f1os antes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La empresa Parametr\u00eda que dirige Francisco Abundis, realiza una encuesta similar regularmente. Y el 27 de mayo de 2017 registr\u00f3 que solo el 39 por ciento de la poblaci\u00f3n encuestada asum\u00eda que si exist\u00eda libertad de prensa. <em>\u201cLa encuesta realizada cara a cara en vivienda, indica que el 61 por ciento dijo que no hab\u00eda libertad de prensa en M\u00e9xico<\/em>.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En contraste, el informe anual de Art\u00edculo 19 sobre la libertad de expresi\u00f3n y de prensa en 2021, difundido los primeros d\u00edas de abril de 2022 asegura que <em>\u201ca pesar de la negaci\u00f3n <\/em>(del gobierno federal)<em>, hoy el ejercicio de la libertad de expresi\u00f3n no tiene mejores condiciones que antes del 2018\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos colegas me preguntaron por qu\u00e9 coment\u00e9 que Art\u00edculo 19 sesg\u00f3 m\u00e1s de lo acostumbrado su informe anual de 2021. Por eso contrasto aqu\u00ed su afirmaci\u00f3n central con las percepciones sociales registradas por dos de las empresas encuestadoras m\u00e1s serias que act\u00faan en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo hago sin \u00e1nimo de minusvalorar el trabajo de Art\u00edculo 19 y de su actual director para M\u00e9xico, Leopoldo Maldonado porque sus trayectorias han aportado bastante en la defensa del derecho a expresarse libremente en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero tambi\u00e9n creo que las y los periodistas tenemos la obligaci\u00f3n de contrastar informaciones de asuntos muy trascendentes y m\u00e1s cuando ata\u00f1en a nuestro eco ambiente del periodismo y, por supuesto, a nuestras propias percepciones para ejercer nuestra obligaci\u00f3n de informar lo m\u00e1s veros\u00edmil posible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lo qu\u00e9 dicen periodistas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Hace unos d\u00edas tambi\u00e9n, el 7 de abril de 2022, la Facultad de Ciencias Pol\u00edticas y Sociales (FCPyS) de la Universidad Aut\u00f3noma del Estado de M\u00e9xico (UAEM) organiz\u00f3 un panel con ocho periodistas activos en esa entidad con el tema; \u00bfQu\u00e9 opinan los periodistas sobre la libertad de expresi\u00f3n antes y despu\u00e9s de la 4T?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y las reflexiones all\u00ed expuestas son bastante indicativas de estados de \u00e1nimo compartidos por periodistas de otras entidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la nota period\u00edstica del panel firmada por Fernando Sol\u00eds para El Sol de Toluca se registraron varios consensos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201clas limitaciones y restricciones a libertad de expresi\u00f3n no pueden considerarse privativas o exclusivas de un gobierno, pues en M\u00e9xico existe una tendencia hist\u00f3rica donde en el pasado las \u00e9lites gobernantes han instrumentado distintos controles hacia medios de comunicaci\u00f3n y periodistas.\u201d<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cEste ejercicio de reflexi\u00f3n se realiz\u00f3 en el sal\u00f3n de Consejos de la FCPyS. Participaron los periodistas Eduardo Gardu\u00f1o, columnista de Milenio; Claudia Ballesteros, coordinadora de la oficina regional de AMX Noticias; Israel D\u00e1vila, corresponsal en el Estado de M\u00e9xico de La Jornada; y V\u00edctor Gamboa, reportero de El Universal.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cTambi\u00e9n estuvieron presentes Enrique I. G\u00f3mez, subdirector de El Sol de Toluca; Rebeca Jim\u00e9nez, corresponsal de El Universal; Jos\u00e9 P\u00e9rez, corresponsal del Noreste.net; y Ra\u00fal Fraga, conductor del programa \u201cLa Agenda del Emprendedor\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el texto se eligieron expresiones sintetizadoras de aquel di\u00e1logo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cGardu\u00f1o indic\u00f3 que la libertad de expresi\u00f3n se entiende como un derecho multifac\u00e9tico, pues no s\u00f3lo consiste en el derecho de difundir informaci\u00f3n e ideas, sino tambi\u00e9n incluye el derecho a recibirlas. Se\u00f1al\u00f3 que lamentablemente la libertad de expresi\u00f3n se convierte para muchos en su principal amenaza de vida, tanto para periodistas, como para defensores de los derechos humanos.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cSin embargo, Jim\u00e9nez indic\u00f3 que fue en la d\u00e9cada de los noventa cuando la censura era mucho mayor. Adem\u00e1s, record\u00f3 los sexenios de los exgobernadores Enrique Pe\u00f1a Nieto y Eruviel \u00c1vila Villegas, pues fue en esa \u00e9poca cuando en los eventos p\u00fablicos se instalaron vallas met\u00e1licas.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cEn su oportunidad, Enrique I. G\u00f3mez se\u00f1al\u00f3 que en el gobierno de la Cuarta Transformaci\u00f3n existen contrastes en materia de la libertad de expresi\u00f3n, pero dicha situaci\u00f3n no s\u00f3lo es responsabilidad de la administraci\u00f3n federal, sino de los gobiernos estatales y municipales, donde el ejercicio period\u00edstico suele convivir con visiones contrarias a la libertad de expresi\u00f3n. Indic\u00f3 que para responder si en el actual gobierno federal hay m\u00e1s libertad de expresi\u00f3n deben evitarse las respuestas simples. Por el contrario, debe analizarse la herencia de limitaciones que en esta materia le heredaron otras administraciones, adem\u00e1s de los cambios que est\u00e1n en proceso<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cA su vez, Ballesteros<\/em> (contrast\u00f3) <em>que actualmente es dif\u00edcil ejercer el derecho a la libertad de expresi\u00f3n. Consider\u00f3 que el periodismo antes se hac\u00eda libremente. Desde su perspectiva coment\u00f3 que luego de tres d\u00e9cadas como comunicadora, nunca antes como hoy hab\u00eda sentido que no se tiene esa libertad.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cG\u00f3mez coment\u00f3 que, entre los aspectos positivos del actual gobierno federal, en materia de libertad de expresi\u00f3n, la Secretar\u00eda de Gobernaci\u00f3n (Segob) y el Congreso de la Uni\u00f3n est\u00e1n en el proceso para integrar una nueva ley de protecci\u00f3n para periodistas y defensores de los derechos humanos.\u201d<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cEs un proceso muy interesante, porque en sus extremos, esta reforma permitir\u00eda una modificaci\u00f3n constitucional para que el periodismo se considere como una actividad de inter\u00e9s p\u00fablico, derivado de que la libertad de expresi\u00f3n es una materia que compete a todos, pues estamos hablando de derechos humanos\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cRefiri\u00f3 que es necesario una pol\u00edtica nacional en materia de libertad de expresi\u00f3n para no s\u00f3lo sancionar los agresiones o ataques hacia los periodistas, sino para institucionalizar y normalizar la importancia del periodismo dentro de la vida p\u00fablica de M\u00e9xico.\u201d *<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(ver la nota en https:\/\/www.elsoldetoluca.com.mx\/local\/que-opinan-los-periodistas-sobre-la-libertad-de-expresion-antes-y-despues-de-la-4t-8108232.html)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y ustedes colegas \u00bfQu\u00e9 opinan?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Rogelio Hern\u00e1ndez L\u00f3pez SemM\u00e9xico, Cd. de M\u00e9xico, 18 de abril, 2022.- Colegas \u00bfpor qu\u00e9 no nos asomamos al informe m\u00e1s reciente de Art\u00edculo 19 sobre libertad de expresi\u00f3n y lo contrastamos con lo que dicen dos encuestas sobre el tema? Al respecto, la organizaci\u00f3n de origen ingl\u00e9s asegura que esta libertad ha disminuido en el [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":38348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,106,35,85],"tags":[459],"class_list":["post-48593","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-mirada-de-reportero","category-opinion","category-rogelio-hernandez-lopez","tag-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/48593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=48593"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/48593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/38348"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=48593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=48593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=48593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}