{"id":46760,"date":"2022-03-07T10:35:40","date_gmt":"2022-03-07T16:35:40","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=46760"},"modified":"2023-07-21T19:00:03","modified_gmt":"2023-07-22T00:00:03","slug":"miradas-de-reportero-proteccion-a-periodistas-cambiemos-el-enfoque","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/miradas-de-reportero-proteccion-a-periodistas-cambiemos-el-enfoque\/","title":{"rendered":"Miradas de reportero| Protecci\u00f3n a periodistas. Cambiemos el enfoque"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Rogelio Hern\u00e1ndez L\u00f3pez<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 7 de marzo, 2022.- En 22 a\u00f1os de observar las dificultades de periodistas para ejercer en M\u00e9xico, no hab\u00eda registrado siete asesinatos en los primeros tres meses, ni tampoco tal intensidad de expresiones de protesta y de foros para recriminar las oquedades del Estado. Empero, en medio de esta atm\u00f3sfera tr\u00e1gica aparecen visos para cambiar las formas de observar y tratar a las personas periodistas en riesgo. Se observan unas peque\u00f1as luces en el sombr\u00edo t\u00fanel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">UNO. El cambio de enfoque desde el gobierno federal proviene de la <em>Subsecretar\u00eda de Derechos Humanos de la Secretar\u00eda de Gobernaci\u00f3n<\/em> a cargo de Alejandro Encinas, que decidi\u00f3 tomar recoger directamente las opiniones de personas defensoras de los derechos humanos y periodistas en al menos siete foros de di\u00e1logos para perfilar mejor otra Ley General que cambie el car\u00e1cter reactivo del Mecanismo actual por uno m\u00e1s preventivo y m\u00e1s rector de un sistema nacional de protecci\u00f3n que obligue a cumplir sus obligaciones a gobiernos estatales y municipales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De lograrse esto, para fines de 2022 cristalizar\u00eda un cambio radical desde el Estado en las formas de ver y actuar frente a los riesgos de estas poblaciones, (un golpe de tim\u00f3n, como dice el lugar com\u00fan). Para lograrlo a cabalidad tendr\u00e1 que convencerse al Presidente de la Rep\u00fablica de que sus cr\u00edticas a ciertas empresas de prensa y algunos periodistas tienen demasiado peso pol\u00edtico, estimulan climas pol\u00edticos de odio y alientan indirectamente a perpetradores, tanto verbales como f\u00edsicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DOS. Otro cambio de enfoque proviene de la organizaci\u00f3n internacional de origen franc\u00e9s <em>Reporteros sin Fronteras<\/em> (RsF) que el 4 de marzo present\u00f3 p\u00fablicamente los resultados de su estudio \u201c<em>Desaf\u00edos del Mecanismo Federal para la Protecci\u00f3n de Personas Defensoras de Derechos Humanos y Periodistas\u201d<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En \u00e1ngulo que eligieron los expertos de RsF elude muchas recriminaciones que suelen hacer los organismos internacionales, coincide con el diagn\u00f3stico y las decisiones de la Subsecretar\u00eda de Encinas sobre las omisiones de otras \u00e1reas del Estado Mexicano. M\u00e1s sobresaliente es que sus recomendaciones coinciden con las intenciones de cambio radical del gobierno federal. Por ejemplo, sostiene en la primera<em>: \u201cLa responsabilidad de la protecci\u00f3n de los periodistas debe repartirse mejor entre los niveles federal y local. Esto exige una mayor y mejor coordinaci\u00f3n institucional y una voluntad real del Estado mexicano, que debe tener <strong>una visi\u00f3n integral<\/strong> de la protecci\u00f3n de los beneficiarios\u201d. (subrayados de RHL)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TRES. Otro cambio de actitud interesante proviene de la Agencia de los Estados Unidos para el Desarrollo Internacional (USAID seg\u00fan sus siglas en ingl\u00e9s) que en lugar de estimular cr\u00edticas al Estado Mexicano se propuso desplegar un programa de jornadas por la libertad de expresi\u00f3n con universidades p\u00fablicas y privadas financi\u00e1ndolas para que realicen acciones con el enfoque de <strong>prevenci\u00f3n<\/strong> y con la intenci\u00f3n de \u201c<em>incrementar las capacidades de <strong>autogesti\u00f3n<\/strong> de la seguridad f\u00edsica, digital, y el bienestar psicoemocional de las personas defensoras de derechos humanos y periodistas, ayudando tambi\u00e9n a reducir la exposici\u00f3n innecesaria a riesgos\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CUATRO. Entre periodistas se perciben tambi\u00e9n algunos cambios de mirada y del qu\u00e9 hacer frente a los asesinatos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las jornadas de protesta por los primeros cuatro asesinatos del a\u00f1o mostraron que decenas de colegas han construido redes para acciones conjuntas en 62 ciudades de 22 entidades. Esto podr\u00eda significar que consciente o intuitivamente comienzan a asumir que necesitan transformar la concepci\u00f3n de ser objetos de protecci\u00f3n del Estado a sujetos de acciones propias para protegerse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esa actitud de unidad y prevenci\u00f3n periodistas de Hidalgo realizaron la Semana del Periodismo en Pachuca para examinar \u00e1ngulos y dificultades del ejercicio. Por otro lado, algunos colegas (normalmente refractarios a la unidad y solidaridad) decidieron convocar a un <em>Encuentro Nacional<\/em> en San Crist\u00f3bal de las Casas, Chiapas apoyados por organizaciones defensoras de derechos humanos y de libertad de expresi\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"cambiemos-el-enfoque\"><strong>Cambiemos el enfoque<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ese tipo de reacciones podr\u00edan estimularse m\u00e1s cuando las y los periodistas asuman como parte de su identidad profesional ser sujetos de acciones propias para su protecci\u00f3n. Por ejemplo, madurar una propuesta que se ha hecho desde 2010: <strong>crear una red de redes<\/strong> en la que, adem\u00e1s de facilitar reacciones r\u00e1pidas ante amenazas o agresiones, pueda derivar planes para elevar capacidades profesionales y para disminuir otras vulnerabilidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese mismo sentido, desde hace a\u00f1os algunos colegas estamos proponiendo a distintas instancias del Estado (y as\u00ed lo ratificaremos en los di\u00e1logos por la nueva ley de protecci\u00f3n) que confirmen su enfoque sobre periodistas privilegiando la prevenci\u00f3n, no solo con medidas cautelares sino con m\u00e1s pol\u00edticas p\u00fablicas que ayuden a reducir esas seis grandes vulnerabilidades que facilitan las agresiones y aumenten sus fortalezas para su autoprotecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo m\u00e1s apremiante de este cambio de enfoque en instancias del Estado es ampliar la definici\u00f3n de periodista, distinguiendo claramente a quienes hacen labor esencial de conseguir informaci\u00f3n (reportear) con quienes son colaboradores period\u00edsticos o usuarios de la libertad de expresi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos de esas pol\u00edticas p\u00fablicas, tambi\u00e9n urgentes, son definir un programa que involucre a universidades para la actualizaci\u00f3n profesional continua y, por otro lado, madurar los cambios ya iniciados en el Senado de la ley laboral para reconocer derechos para el ejercicio profesional del periodismo y para reducir la precariedad que ha crecido monumentalmente en dos d\u00e9cadas. Reducir incapacidades profesionales y precariedad laboral ser\u00eda lo realmente preventivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La intensidad<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El medio ambiente entre periodistas y en escenarios vinculados ha sido muy intenso desde los primeros d\u00edas de 2022. Fueron por una atm\u00f3sfera de miedo que se estimul\u00f3 con varios factores: por la oleada criminal en varios estados y distintos perpetradores; por los climas temporales de la crisis en las relaciones entre algunos medios industrializados con el gobierno federal; por las ofensivas opositoras que utiliza todo eso para seguir desgajando la aceptaci\u00f3n social del presidente y su movimiento pol\u00edtico, previo al refer\u00e9ndum de abril y a las elecciones pr\u00f3ximas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para quienes tambi\u00e9n siguen los asuntos de periodismo y periodistas, les ser\u00e1n \u00fatiles los siguientes hechos que reflejan una intensidad pocas veces vista:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Enero<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 12. Asesinato de Jos\u00e9 Luis Gamboa Arenas, reportero para redes sociales en Veracruz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 17. Asesinato de Margarito Esquivel Mart\u00ednez, fotoperiodista del semanario <em>Zeta, Radio Cadena Noticias y Diario Frontera<\/em> en Tijuana, Baja California.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00edas 17 y 18. La <em>Subsecretar\u00eda de Derechos Humanos<\/em> de la Segob inicia los di\u00e1logos regionales en la CDMX por otra ley de protecci\u00f3n. Comienzan a emerger denuncias de agravios y quejas contra servidores p\u00fablicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 23. Asesinato de Lourdes Maldonado, periodista de <em>Sintoniza sin Fronteras<\/em> y para redes sociales, en Tijuana, Baja California.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 31. Asesinato de Roberto Toledo en Zit\u00e1cuaro, colaborador del portal <em>Monitor Michoac\u00e1n<\/em> y trabajador de un bufete jur\u00eddico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Febrero<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 10. Asesinato de Heber L\u00f3pez V\u00e1squez en Salina Cruz, Oaxaca, reportero y director del Portal <em>RCP Noticias<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 15. Por inquisici\u00f3n de periodistas el Presidente promete en su conferencia matutina, que se rendir\u00e1n informes cada 15 d\u00edas sobre cr\u00edmenes contra periodistas, defensores y mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00edas 15 y 16. Se efect\u00faa en Oaxaca el segundo Dialogo Regional de la Segob por una nueva ley de protecci\u00f3n. Destacan las quejas contra el gobierno estatal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 16. Roy Campos, director de Consulta Mitofsky, informa en una entrevista que la popularidad del presidente estuvo por meses arriba del 60 por ciento, pero registra tendencia a la baja de 3 puntos desde la publicaci\u00f3n de la investigaci\u00f3n sobre la &#8216;Casa Gris&#8217; y por sus cr\u00edticas a algunos medios y periodistas. Al 28 de febrero el promedio de las encuestas m\u00e1s serias le reconoc\u00edan 58 por ciento de aceptaci\u00f3n y 39 por ciento en desaprobaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 22. El Presidente informa que se est\u00e1 examinando la iniciativa de un periodista de Tijuana para crear un fondo especial que cubra el derecho a la salud y pensi\u00f3n de periodistas con bajos ingresos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 22. &nbsp;El senador del Grupo Plural, Emilio \u00c1lvarez Icaza, presenta una iniciativa construida con periodistas para reformar la Ley Federal del Trabajo y la Ley del Impuesto sobre la Renta, para reconocer derechos para el ejercicio del periodismo, garantizar los laborales y abrir oportunidades de autoempleo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 24. Asesinato de Jorge Camero Zazueta en Empalme, Sonora, director del portal <em>El Informativo<\/em> y exsecretario particular dos meses antes del alcalde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 25. Cierre de la <em>Semana de Periodismo<\/em> de Pachuca, organizada por periodistas de la Fundaci\u00f3n para la Comunicaci\u00f3n y el Periodismo de Hidalgo. El tema de viejos y nuevos riesgos es abordado por Gerardo Albarr\u00e1n de Alba, Rogelio Hern\u00e1ndez L\u00f3pez, Humberto Musacchio, Jos\u00e9 Reveles y Alberto Witvrun. <a href=\"https:\/\/www.facebook.com\/periodismohidalgo\/videos\/296734622558117\/\">https:\/\/www.facebook.com\/periodismohidalgo\/videos\/296734622558117\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Marzo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00edas 1 y 2. En Hermosillo, Sonora, Segob realiza el tercer dialogo regional. Participan un poco m\u00e1s de periodistas y contin\u00faan las quejas. Se ofrecen jornadas de capacitaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 2. Se difunde el programa Debate 22 conducido por Jacaranda Correa en el canal del Estado, un debate sobre la actuaci\u00f3n de medios y periodistas mexicanos que atizan la polarizaci\u00f3n pol\u00edtica. Participan la periodista Daniela Pastrana, el analista Hern\u00e1n G\u00f3mez y el reportero Rogelio Hern\u00e1ndez L\u00f3pez. <a href=\"https:\/\/www.youtube.com\/watch?v=abvBBAxd0uA\">https:\/\/www.youtube.com\/watch?v=abvBBAxd0uA<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 3. Se realiza la presentaci\u00f3n del informe de Reporteros sin Frontera&nbsp; <em>\u201cDesaf\u00edos del Mecanismo Federal para la Protecci\u00f3n de Personas Defensoras de Derechos Humanos y Periodistas\u201d <\/em>con la participaci\u00f3n de Balbina Flores, Bia Barbosa y Emmanuel Colombi\u00e9 de RsF; Daniel Zapico de la oficina del Alto Comisionado de las Naciones Unidas sobre Derechos Humanos en M\u00e9xico; Erik Javier Mart\u00edn, director del Mecanismo federal de protecci\u00f3n: Sara Mendiola, directora de <em>Propuesta C\u00edvica<\/em>; Paula Saucedo, oficial de protecci\u00f3n y defensa de <em>Articulo 19<\/em> y Rogelio Hern\u00e1ndez L\u00f3pez, reportero. <a href=\"https:\/\/www.facebook.com\/reporterossinfronterasenespanol\/videos\/509382337239170\">https:\/\/www.facebook.com\/reporterossinfronterasenespanol\/videos\/509382337239170<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 3. Se realiza en el foro <em>Di\u00e1logo y Consenso<\/em> un intercambio sobre \u201c<em>La protecci\u00f3n en M\u00e9xico de Periodistas y defensores de los Derechos Humanos\u201d<\/em>. Participan Mariclaire Acosta, investigadora del CIDE y presidenta de Oxfam M\u00e9xico; Ang\u00e9lica de la Pe\u00f1a, ex diputada del PRD especializada en derechos humanos; Michael W Chamberlin, Etn\u00f3logo y Maestro en Derechos Humanos y Democracia y Luc\u00eda Lagunes Huerta, soci\u00f3loga diplomada en Derechos Humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 3. En los espacios de televisi\u00f3n de la alianza <em>Bloomberg-El Financiero<\/em> se efect\u00faa el debate \u201c<em>Prensa y poder en tiempos de conflicto\u201d<\/em>. Conduce el periodista Enrique Quintana y participan Adela Navarro, directora del semanario Z; Julio (Astillero) Hern\u00e1ndez L\u00f3pez, Ricardo Raphael, articulista y conductor de programas period\u00edsticos; Raymundo Riva Palacio, director de Eje Central y conductor de <em>Estrictamente Personal<\/em> en canal 4. <a href=\"https:\/\/www.elfinanciero.com.mx\/video\/tv\/ef-meetpoint\/2022\/03\/03\/ef-meet-point-prensa-y-poder-en-tiempos-de-conflicto\/\">https:\/\/www.elfinanciero.com.mx\/video\/tv\/ef-meetpoint\/2022\/03\/03\/ef-meet-point-prensa-y-poder-en-tiempos-de-conflicto\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 4. Asesinato de Juan Carlos Mu\u00f1iz en Fresnillo, Zacatecas, reportero del portal <em>Testigo Minero<\/em> y taxista como segundo empleo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00eda 5. Se efect\u00faa el primer <em>Encuentro Nacional de Periodistas<\/em> en San Crist\u00f3bal de Las Casas, Chiapas al que llegaron m\u00e1s de cien personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y le faltan d\u00edas a marzo. Habr\u00e1 foros en las universidades Aut\u00f3noma de Quer\u00e9taro y la Aut\u00f3noma de Coahuila; m\u00e1s manifestaciones y coloquios en l\u00ednea de periodistas. Seguir\u00e1 la intensidad en los asuntos del periodismo y por la integridad de las y los periodistas. Colegas, sigamos cambiando el enfoque para ser sujetos de acci\u00f3n en defensa propia y del periodismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 22 a\u00f1os de observar las dificultades de periodistas para ejercer en M\u00e9xico, no hab\u00eda registrado siete asesinatos en los primeros tres meses<\/p>\n","protected":false},"author":3,"featured_media":38348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,106,35,85],"tags":[459],"class_list":["post-46760","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-mirada-de-reportero","category-opinion","category-rogelio-hernandez-lopez","tag-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/46760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=46760"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/46760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/38348"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=46760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=46760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=46760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}