{"id":45905,"date":"2022-02-18T19:01:02","date_gmt":"2022-02-19T01:01:02","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=45905"},"modified":"2023-07-21T18:59:15","modified_gmt":"2023-07-21T23:59:15","slug":"toman-la-calle-periodistas-para-exigir-justicia-en-oaxaca","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/toman-la-calle-periodistas-para-exigir-justicia-en-oaxaca\/","title":{"rendered":"Toman la calle periodistas para exigir justicia en Oaxaca"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>* Autoridades se lavan las manos con sangre, dice Pedro Mat\u00edas. \u00bfQui\u00e9n sigue? Pregunta Soledad Jarqu\u00edn<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>* Gobiernos y poderes f\u00e1cticos han asesinado a 15 informadores en 20 a\u00f1os<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>* Vinculan a proceso a probables asesinos materiales de Heber L\u00f3pez y agreden a otro comunicador en Oaxaca<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mar\u00eda Luna<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 28 de febrero, 2021.- El gremio period\u00edstico de Oaxaca volvi\u00f3 a las calles, la herida sigue abierta y las expresiones de justicia para Heber L\u00f3pez V\u00e1squez, asesinado el pasado 10 de febrero en Salina Cruz provoca indignaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al frente una carrosa f\u00fanebre y dentro un ata\u00fad en reflejo del sentimiento de luto de las y los periodistas de la entidad, donde de acuerdo a Art\u00edculo 19 suman 15 los informadores asesinados, siendo las m\u00e1s letales en agresiones las regiones del Istmo y la Cuenca, donde desde hace m\u00e1s de 20 a\u00f1os se han asentaron los c\u00e1rteles del narco y se recrucen las intervenciones de poderes f\u00e1cticos y actores pol\u00edticos contra quienes escriben con verdad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las calles del centro hist\u00f3rico caminaron al menos tres generaciones de informadores, fot\u00f3grafos y camar\u00f3grafos, hombres y mujeres, para exigir un alto a las agresiones y llamar a la sociedad a la solidaridad: \u201csi callan a la prensa, calla toda la sociedad\u201d. Desde el Llano y hasta la Alameda de Le\u00f3n, bajo un intenso sol, se efectu\u00f3 una marcha de informadores vestidos de negro, en silencio la mayor parte del tiempo, con cientos de pancartas con reclamos diversos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Cu\u00e9ntennos bien no somos 10!, dec\u00edan algunas cartulinas en alusi\u00f3n a una reuni\u00f3n convocada por el gobernador Alejandro Murat el pasado martes 15 y la que asistieron algunos informadores. Ah\u00ed, y a solo unos meses de concluir su mandato \u201cexplic\u00f3\u201d sus acciones para el futuro y \u201cprometi\u00f3\u201d justicia para Heber L\u00f3pez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese mismo d\u00eda, Murat no asisti\u00f3 al Foro para impulsar una iniciativa de ley general de prevenci\u00f3n y protecci\u00f3n ante agravios a personas defensoras de derechos humanos y periodistas, organizado por el Mecanismo de la Secretar\u00eda de Gobernaci\u00f3n, por la noche del martes, propuso crear un fideicomiso de 10 millones de pesos para las v\u00edctimas indirectas de las y los periodistas asesinados.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"45910\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/02\/WhatsApp-Image-2022-02-18-at-6.22.17-PM.jpeg\" alt=\"\" class=\"wp-image-45910\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"381\" data-id=\"45906\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/02\/Captura-de-pantalla-2022-02-18-a-las-17.17.55.png\" alt=\"\" class=\"wp-image-45906\"\/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En cambio, algunos de los asistentes pidieron reformas a la ley para que se tipifique como delito grave las agresiones a informadores y que la Fiscal\u00eda General del Estado establezca una mesa especial para atender estos casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el mitin en la alameda, se coloc\u00f3 el ata\u00fad frente a la catedral de esta ciudad. Desde ah\u00ed hubo 12 pronunciamientos, todos encaminados a esclarecer los hechos en que han sido asesinados los 15 periodistas desde el a\u00f1o 2000 a la fecha en Oaxaca y otras muchas como amenazas, intimidaci\u00f3n y agresiones f\u00edsicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Se lavan las manos con la sangre de los periodistas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un sentido mensaje Pedro Mat\u00edas dijo que quienes ejercen esta profesi\u00f3n \u201csomos el blanco y el gobierno se lava las manos con la sangre de los periodistas\u201d porque asegur\u00f3 que todos los casos siguen en la impunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El corresponsal de la revista Proceso hizo un airado reclamo a las organizaciones sindicales, cit\u00f3 el caso espec\u00edfico de la secci\u00f3n 22 del SNTE y la secci\u00f3n 35 de los trabajadores de Salud, \u201cnos llaman a la hora que sea y vamos\u2026 \u201c\u00bfd\u00f3nde est\u00e1n ahora? Hoy estamos solos, no nos ven, si nos silencian (a las y los periodistas) nos silencian a todos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQui\u00e9n sigue?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Soledad Jarqu\u00edn Edgar de SemM\u00e9xico afirm\u00f3: \u201cHoy estamos aqu\u00ed por Heber L\u00f3pez \u00bfpor qui\u00e9n m\u00e1s vamos a salir para exigir justicia despu\u00e9s? Dijo que el gobernador de Oaxaca (Alejandro Murat) no ha demostrado nada en los hechos, las iniciativas propuestas durante a\u00f1os para proteger a periodistas siguen guardadas en el Congreso y el poder Judicial nos niega la justicia porque no les importamos\u201d, se\u00f1al\u00f3 en referencia a los poderes del Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Libertad de expresi\u00f3n aliada de la democracia<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alejandro L\u00f3pez, dirigente de la APO, dijo \u201cestamos a tiempo de evitar que m\u00e1s compa\u00f1eros y compa\u00f1eras sufran violencia por parte de quienes agazapados en las sombras pretendan mediante el terror silenciar una aliada de la democracia, la libertad de expresi\u00f3n\u201d. Exigi\u00f3 castigo a los asesinos de Heber y de otros periodistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No podemos callarnos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Citlalli L\u00f3pez, reportera de Noticias, destac\u00f3 que la libertad de expresi\u00f3n es un derecho humano por lo que \u201cno podemos callarnos\u201d. Destac\u00f3 la importancia de la labor period\u00edstica y cit\u00f3 los ejemplos de Ayotzinapa (donde 43 estudiantes fueron desaparecidos) y la forma en que las periodistas dan voz a las v\u00edctimas indirectas del feminicidio, \u201cnuestro silencio nos har\u00eda c\u00f3mplices\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No somos enemigos de nadie<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hiram Moreno, de la regi\u00f3n del Istmo, fue enf\u00e1tico al se\u00f1alar que las y los periodistas no son enemigos de nadie y exigi\u00f3 al presidente mexicano Andr\u00e9s Manuel L\u00f3pez Obrador \u201cdetener la espiral de violencia que se promueve desde la m\u00e1s alta tribuna del pa\u00eds, porque todos los d\u00edas el Presidente se la pasa acosando, denostando y desacreditando el trabajo de compa\u00f1eros a los que hace unos a\u00f1os celebraba como paladines de la libertad de expresi\u00f3n cuando dieron a conocer lo de la casa blanca y ahora se espanta\u201d. \u201c\u00a1Pare la violencia, nos est\u00e1n matando!\u201d, exigi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En Oaxaca tambi\u00e9n nos matan<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Roberto Polo, de la Cuenca del Papaloapan, dijo que antes se dec\u00eda que en Veracruz matan periodistas y que en Oaxaca los agreden, \u201choy tenemos que decir que en Oaxaca nos matan y en Veracruz tambi\u00e9n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Las balas han callado periodistas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alejandro L\u00f3pez L\u00f3pez, de la regi\u00f3n de la Mixteca, apunt\u00f3 que el reclamo de las y los periodistas oaxaque\u00f1os es por aquellos \u201ca los que las balas han callado, nosotros no somos c\u00f3mplices de los gobiernos corruptos que han silenciado nuestros compa\u00f1eros\u201d. Hizo un en\u00e9rgico llamado a detener la violencia al gobernador de Oaxaca y al presidente de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Solidaridad con el gremio que trabaja en el Istmo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por la regi\u00f3n de la Costa intervino Jos\u00e9 Torrentera, quien destac\u00f3 la importancia de la manifestaci\u00f3n, la unidad gremial y se\u00f1al\u00f3 que de esta forma las y los periodistas de Oaxaca se solidarizan con quienes ejercen esta labor en la regi\u00f3n del Istmo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a1Justicia!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oscar Vergara llam\u00f3 a los \u00f3rganos de gobierno e instituciones a garantizar la libertad de expresi\u00f3n y a responder a las exigencias, en especial, a la demanda de justicia para los compa\u00f1eros asesinados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/02\/WhatsApp-Image-2022-02-18-at-2.09.55-PM.jpeg\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2022\/02\/WhatsApp-Image-2022-02-18-at-2.09.55-PM-768x1024.jpeg\" alt=\"\" class=\"wp-image-45909\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El poder se incomoda<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nadia Zarabia record\u00f3 que la violencia contra la prensa tiene un largo camino. \u201cNos quieren matar, porque al poder le incomoda la verdad\u201d. Apunt\u00f3 que la corrupci\u00f3n que impera en Oaxaca aumenta el riesgo para las y los periodistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Llaman a reinstalar la Comisi\u00f3n en el Congreso<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su intervenci\u00f3n Said Hern\u00e1ndez, ley\u00f3 un pronunciamiento que se entregar\u00eda m\u00e1s tarde. En este destac\u00f3 que en Oaxaca prevalece la inseguridad y la falta de acceso a la justicia para los trabajadores de los medios. Entre las peticiones destac\u00f3 que sean las v\u00edctimas indirectas de los periodistas asesinados quienes encabecen las reuniones de trabajo con las autoridades. Y que el Congreso local reinstale la Comisi\u00f3n Especial de Atenci\u00f3n a Periodistas eliminada por la 62 Legislatura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Llamado a la no agresi\u00f3n vs agresi\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El fotoperiodista Jos\u00e9 Luis Plata llam\u00f3 a las organizaciones sociales y pol\u00edticas a respetar el trabajo de los fot\u00f3grafos y dijo que durante las manifestaciones muchas veces son agredidos. No nos van a callar y no vamos a permitir que nos agredan, y cit\u00f3 el caso de normalistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las palabras no fueron escuchadas. Una hora m\u00e1s tarde, se inform\u00f3 que estudiantes de normales hab\u00edan tomado uno de los accesos a la capital oaxaque\u00f1a, en Viguera, al poniente, donde agredieron al reportero Javier Santiago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vinculados a proceso presuntos asesinos de Heber<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fiscal\u00eda General del Estado de Oaxaca (FGEO) inform\u00f3 esta misma tarde que un Juez de Control dict\u00f3 auto de vinculaci\u00f3n a proceso contra dos hombres identificados como R. G. R., y R. E. C., se\u00f1alados como probables responsables del delito de homicidio calificado en agravio del periodista Heber L\u00f3pez V\u00e1squez hechos que sucedieron en el puerto de Salina Cruz, en la regi\u00f3n del Istmo de Tehuantepec.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con la carpeta de investigaci\u00f3n 4748\/FIST\/SALINA\/2022, los hechos ocurrieron el 10 de febrero de 2022, en el Barrio El Espinal del municipio de Salina Cruz, cuando los probables responsables interceptaron a la v\u00edctima y le dispararon cuando ingresaba a un domicilio. Cabe mencionar que las heridas infligidas le provocaron la muerte a Heber L\u00f3pez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/ml\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>* Autoridades se lavan las manos con sangre, dice Pedro Mat\u00edas. \u00bfQui\u00e9n sigue? Pregunta Soledad Jarqu\u00edn * Gobiernos y poderes f\u00e1cticos han asesinado a 15 informadores en 20 a\u00f1os * Vinculan a proceso a probables asesinos materiales de Heber L\u00f3pez y agreden a otro comunicador en Oaxaca Mar\u00eda Luna SemM\u00e9xico, Oaxaca, 28 de febrero, 2021.- [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":45907,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,47,48],"tags":[146],"class_list":["post-45905","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-no-mas-impunidad","category-no-mas-impunidad-no-mas-impunidad","tag-oaxaca"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/45905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=45905"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/45905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/45907"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=45905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=45905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=45905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}