{"id":45813,"date":"2022-02-16T14:53:52","date_gmt":"2022-02-16T20:53:52","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=45813"},"modified":"2023-07-21T18:59:16","modified_gmt":"2023-07-21T23:59:16","slug":"no-utilizar-los-asesinatos-de-periodistas-para-atacar-al-gobierno-al-que-represento-responde-amlo-a-la-protesta-en-palacio-nacional","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/no-utilizar-los-asesinatos-de-periodistas-para-atacar-al-gobierno-al-que-represento-responde-amlo-a-la-protesta-en-palacio-nacional\/","title":{"rendered":"No utilizar los asesinatos de periodistas para atacar al gobierno al que represento. Responde Amlo a la protesta en Palacio Nacional"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Rodolfo Montes, periodista de UNONoticias le anunci\u00f3 \u201cno le vamos a preguntar nada\u201d, en solidaridad con las y los ca\u00eddos<\/strong><\/li><li><strong>Inusitada acci\u00f3n: en pleno Palacio Nacional, en la ma\u00f1anera, minuto de silencio del gremio y otra vez \u201cvivos los queremos\u201d<a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fbillieparkernoticias.com%2Fperiodistas-de-la-mananera-protestan-por-agresiones-a-la-prensa-mexicana%2F\"><\/a><\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sara Lovera<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 16 de febrero, 2022.- &nbsp;Sin temor, sereno, firme, Rodolfo Montes, periodista Uno Noticias, le dijo al presidente \u201choy no le vamos a preguntar nada\u201d, actitud semejante a lo que lo hicieron ayer los reporteros del Congreso, ello en protesta por los y las colegas ca\u00eddas, por la impunidad y porque el mecanismo de protecci\u00f3n a periodistas no funciona y \u201cbien sabe el mecanismo que son los funcionarios p\u00fablicos quienes agreden a periodistas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paralelamente, en Tijuana, inform\u00f3 la periodista Roc\u00edo Galv\u00e1n, de Radio F\u00f3rmula, se prepara para ma\u00f1ana, cuando est\u00e9 ah\u00ed L\u00f3pez Obrador, una protesta, porque la Fiscal\u00eda del Estado, dice que necesita 40 d\u00edas para analizar la situaci\u00f3n de 3 presuntos asesinos materiales y para investigar a los autores intelectuales del asesinato de Lourdes Maldonado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;L\u00f3pez Obrador, ante lo dicho por Rodolfo \u201cel negro\u201d, Montes, se desconcert\u00f3 visiblemente, enjuto las cejas, se balance\u00f3 y primero dijo que en su gobierno es bienvenida la protesta y que no es un gobierno \u201crepresor\u201d, pero se alarg\u00f3 en la respuesta para advertir: \u201cNo \u2013se deben-&nbsp; utilizar estos lamentables hechos \u2013los asesinatos de periodistas- para atacar al gobierno al que represento. Nosotros respetamos la vida, no somos represores, no es el m\u00e1talos en caliente \u2013recordando a Porfirio D\u00edaz-. La violencia se tiene que ir resolviendo\u2026\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero esta misma ma\u00f1ana, y lo dijo a Montes, \u201cser\u00eda bueno saber cu\u00e1nto gana, ese periodista de Univisi\u00f3n \u2013empresa estadounidense y de Estados Unidos-, el veracruzano Jorge Ramos, quien hace meses en ese mismo escenario, el Sal\u00f3n Tesorer\u00eda de Palacio Nacional, increp\u00f3 un d\u00eda al presidente, sobre la mala pol\u00edtica de salud frente al Covid 19.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"un-minuto-de-silencio\"><strong>Un minuto de silencio<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando termin\u00f3 de hablar L\u00f3pez Obrador, y dej\u00f3 solos a los periodistas \u2013mayor\u00eda suplentes porque los titulares ya andan de gira- &nbsp;las y los colegas asistentes al Palacio Nacional hicieron un minuto de silencio por los asesinados y se oy\u00f3 en trasmisi\u00f3n nacional \u201clos queremos vivos\u201d, \u201cjusticia.\u201d. Montes anunci\u00f3 que el fin de semana, en Chiapas, se llamar\u00e1 a una reuni\u00f3n nacional para exigir que no haya impunidad, en todos los casos pendientes como el de asesinato de Fredy L\u00f3pez Ar\u00e9valo ultimado a balazos el 28 de octubre de 2021, ahora sin justicia. Y puntualiz\u00f3 que la protesta no era por un periodista en particular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Previamente el jefe del ejecutivo, -cuando no hab\u00eda preguntas- &nbsp;aprovech\u00f3 su ma\u00f1anera para continuar con lo que ya es cotidiano, sumando en la lista de se\u00f1alamientos personales y en la mira de averiguar cuanto les pagan sus empresas, a Ciro G\u00f3mez Leyva y Joaqu\u00edn L\u00f3pez D\u00f3riga, de Radio F\u00f3rmula, a Carmen Aristegui, &#8211; agredida antes y ahora tambi\u00e9n y a Jorge Ramos, de Univisi\u00f3n, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n acus\u00f3 a medios extranjeros como el Washington Post y The Economist por criticar a su gobierno por la supuesta censura y la persecuci\u00f3n a los medios de comunicaci\u00f3n: \u201cDicen que con Calder\u00f3n y con Pe\u00f1a Nieto hab\u00eda m\u00e1s democracia\u2026\u201d &nbsp;se burl\u00f3. Para dejar en claro que \u2013nosotros, \u00e9l- \u201csiempre vamos a garantizar el derecho a disentir y no va a haber represi\u00f3n para nadie y censura, no va a pasar lo que le hicieron a Carmen Aristegui ni a Guti\u00e9rrez Viv\u00f3\u2026y dijo que G\u00f3mez Leyva podr\u00e1 tener problemas con los due\u00f1os de la empresa donde trabaja, a lo mejor quiere que le paguen m\u00e1s, pero nosotros no nos metemos en eso\u2026\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los periodistas actuar\u00e1n, dijo en su momento el \u201cNegro\u201d Montes, en contra de agresiones y asesinatos de comunicadores, por eso llam\u00f3 a todos a una reuni\u00f3n nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Montes, mesurado, fue claro: \u201cNo le queremos formular preguntas, queremos replicar la protesta, abstenernos de hacerle preguntas presidente, con todo respeto\u201d, emulando a quienes protestaron ayer en la sesi\u00f3n de la C\u00e1mara de Diputado, y en el marco nacional de la exigencia de seguridad y justicia en muchas ciudades del pa\u00eds, tras el asesinato de seis periodistas asesinados en los primeros 46 d\u00edas de este a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La respuesta presidencial, como una cacofon\u00eda, fue la ya conocida, reitero que en su gobierno se vale \u201chay que manifestarse, tienes todo mi respeto y es mi responsabilidad cuidarlos, pero lo \u00fanico que se debe considerar es que el Gobierno Federal no manda aniquilar a nadie. Ya no es el Estado violador de los derechos humanos y si hay pruebas se castigan,\u201d y agreg\u00f3 \u201cNosotros no somos represores y vamos a seguir protegiendo a periodistas, -pero no pudo evitarlo-, dijo lo mismo desde hace 10 d\u00edas en que se ha dedicado a defender a su hijo, por las revelaciones de que vive como rey, lo que no permitir\u00e1, y alzando el dedo ante las c\u00e1maras, advirti\u00f3 que no se pueden \u201cutilizar estos lamentables hechos para atacar al gobierno al que represento\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"la-mananera-de-hoy-mas-de-lo-mismo\"><strong>La ma\u00f1anera de hoy, m\u00e1s de lo mismo<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Abri\u00f3 su ma\u00f1anera amagando al Instituto Nacional de Transparencia y Acceso a la Informaci\u00f3n, que, al cierre de esta informaci\u00f3n, sesionaba para dar respuesta a la demanda de AMLO para conocer, no s\u00f3lo su salario, sino los bienes de Carlos Loret de Mola \u2013quien investig\u00f3 los lujos de su hijo- y los bienes de su familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asunto que a juicio de la ex gobernadora de Yucat\u00e1n Dulce Mar\u00eda Sauri Riancho, se inscribe un abuso de poder; exceso sin medida que desborda lo que se ha observado cotidianamente en las \u201cma\u00f1aneras\u201d presidenciales, devenidas en tribunal de Torquemada, de donde sale la orden para arder en la hoguera de las redes sociales, mandato que cumplen los boots que respaldan al gobierno de L\u00f3pez Obrador, sea por convicci\u00f3n leg\u00edtima o por inter\u00e9s econ\u00f3mico. Todo contra los medios y personas que critican los hierros de su gobierno, que se puede leer: <a href=\"https:\/\/redsemlac.com\/semmexico\/opinion-amlo-ante-la-ley\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/redsemlac.com\/semmexico\/opinion-amlo-ante-la-ley\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay quienes dicen, escriben, analizan y protestan desde el 11 de febrero cuando el jefe del gobierno revel\u00f3 informaci\u00f3n \u2013\u201cque me dio el pueblo\u201d- sobre los supuestos ingresos de Loret de Mola, a quien reiteradamente llama \u201cgolpeador\u201d, y hay quienes consideran que estamos viviendo en M\u00e9xico una crisis doble, por la ola de ejecuciones de periodistas mexicanos y la violencia verbal del primer mandatario, desde hace 3 a\u00f1os.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"amago-al-inai\"><strong>AMAGO AL INAI<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre la petici\u00f3n para que el INAI transparente y responda sobre los ingresos del periodista Carlos Loret de Mola que seg\u00fan reiter\u00f3 hoy\u201d por \u00e9tica lo deber\u00eda hacer\u201d, en diversas entrevistas de radio, televisi\u00f3n y prensa, Nuhad Ponce Kuri, presidenta del Consejo Consultivo de ese organismo aut\u00f3nomo, ha explicado que la obligaci\u00f3n que rige al organismo es la de custodiar, proteger y garantizar la protecci\u00f3n de datos personales de cualquier persona. Por lo que se espera una respuesta negativa a su petici\u00f3n, este mismo d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se puede reproducir la sesi\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/INAImx\/videos\/370058594932917\/\">https:\/\/www.facebook.com\/INAImx\/videos\/370058594932917\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero \u00e9l una y otra vez, se\u00f1alando que quienes lo critican son pagados por lo que llama \u201cla mafia del poder\u201d, volvi\u00f3 a la cargada: sobre Jorge Ramos, \u201ca lo mejor lo de sus bienes pues no, aunque tambi\u00e9n ayudar\u00eda mucho saber de Jorge Ramos. Porque est\u00e1n representando a intereses, no representan al pueblo, representan a intereses creados\u201d. Y agreg\u00f3 que el INAI debe difundir la informaci\u00f3n sobre sus ingresos, ya que es un tema que tiene relaci\u00f3n con el presupuesto p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEntonces, no hay ning\u00fan problema que ellos ejerzan su periodismo, incluso que calumnien, porque estamos en una \u00e9poca de mentiras en el manejo de medios, de guerra sucia, no importa, pero que la gente tenga informaci\u00f3n. \u00bfPor qu\u00e9 nada m\u00e1s van a informar los servidores p\u00fablicos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y en tono de burla, pero de rostro preocupado, a punto de salir a ver las obras del Aeropuerto Felipe \u00c1ngeles, afirm\u00f3 \u201ces que ellos (los periodistas) son privados\u2019, nooo\u2026 Sus ingresos tienen que ver con el presupuesto y con bienes p\u00fablicos, y con la pol\u00edtica, que es un oficio p\u00fablico. Ayudar\u00eda mucho para entender bien qu\u00e9 est\u00e1 sucediendo\u201d,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00f3pez Obrador \u2013lo dijeron m\u00e1s de 65 mil por twitter el fin de semana pasado- no toma en cuenta la desproporci\u00f3n de sus dichos y catilinaria, en contra de periodistas, todos, dir\u00edan ayer en Guerrero y en Oaxaca, los integrantes del gremio, que tienen la lista de m\u00e1s de 49 asesinados en el presente sexenio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Volvi\u00f3 a hablar de lo que llama\u201d campa\u00f1a negra\u201d de los medios a su gobierno\u201d, pero agradeci\u00f3 a medios y periodistas e intelectuales que est\u00e1n con la 4T esta ma\u00f1ana:&nbsp;\u201cA Fabricio, a Paco Ignacio, a Armando Bartra, Pedro Miguel, tambi\u00e9n a algunos caricaturistas, Epigmenio y muchos\u2026\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta ma\u00f1ana, no se reprimi\u00f3, a pesar de que dijo har\u00eda una ma\u00f1anera corta, sigui\u00f3 hablando y dijo que el INE \u201ctrata muy bien\u201d a los periodistas, tras advertir, imbuido de poder, &nbsp;que la reforma electoral que presentar\u00e1 es para que no se tenga tanto presupuesto \u2013en el INE- y que se gaste menos en las campa\u00f1as, \u201cque se garantice una verdadera democracia y se termine con los fraudes electorales.\u201d, recordando 1988 cuando se le cay\u00f3 el sistema a su flamante director de la Comisi\u00f3n Federal de Electricidad, Manuel Bartlett, a qui\u00e9n tambi\u00e9n Loret de Mola, le encontr\u00f3 bienes y capital acumulado de millones de d\u00f3lares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ma\u00f1ana del presidente estar\u00e1 en Tijuana, Baja California, que seg\u00fan se comprometi\u00f3 a realizar un balance de la investigaci\u00f3n sobre el asesinato de Lourdes Maldonado L\u00f3pez, en Tijuana, pero explic\u00f3 la reportera de Radio F\u00f3rmula, no se ha informado sobre las investigaciones del asesinato a tiros Alfonso Margarito Mart\u00ednez Esquivel, fotoperiodista de nota policial, la ma\u00f1ana del lunes 17 de enero cuando sal\u00eda de su domicilio. Mart\u00ednez Esquivel se desempe\u00f1aba como fot\u00f3grafo para las notas relacionadas al tema de seguridad para Semanario Zeta y otros medios de alcance internacional como la BBC.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"los-agravios-en-baja-california\"><strong>Los agravios en Baja California<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En la entidad tambi\u00e9n fue asesinado<strong>&nbsp;H\u00e9ctor F\u00e9lix Miranda,&nbsp;<\/strong>en 1988, seguido del atentado armado a<strong>&nbsp;Jes\u00fas Blancornelas<\/strong>, en 1997, ambos del&nbsp;<strong>Semanario Zeta.<\/strong>&nbsp;Posteriormente en 2004 Francisco Ortiz Franco, fue privado de la vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante la pregunta de los dem\u00e1s casos de homicidio a periodistas el presidente<strong>&nbsp;Andr\u00e9s Manuel&nbsp;<\/strong>asegur\u00f3 que se \u201cest\u00e1 actuando en todos los casos\u201d y que el gobierno tiene dos ventajas para poder esclarecer los actos violentos: \u201cNo tenemos situaciones de complicidad con nadie (&#8230;) y tenemos la convicci\u00f3n y estamos trabajando todos los d\u00edas\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rodolfo Montes, periodista de UNONoticias le anunci\u00f3 \u201cno le vamos a preguntar nada\u201d, en solidaridad con las y los ca\u00eddos<\/p>\n","protected":false},"author":3,"featured_media":45814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[693,55],"tags":[],"class_list":["post-45813","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-periodistas"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/45813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=45813"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/45813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/45814"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=45813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=45813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=45813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}