{"id":45798,"date":"2022-02-16T10:04:40","date_gmt":"2022-02-16T16:04:40","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=45798"},"modified":"2023-07-21T18:59:17","modified_gmt":"2023-07-21T23:59:17","slug":"ople-veracruz-conmemora-el-dia-de-la-mujer-mexicana-por-el-real-acceso-de-las-mujeres-a-los-puestos-de-decision","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/ople-veracruz-conmemora-el-dia-de-la-mujer-mexicana-por-el-real-acceso-de-las-mujeres-a-los-puestos-de-decision\/","title":{"rendered":"OPLE Veracruz conmemora el D\u00eda de la Mujer Mexicana por el real acceso de las mujeres a los puestos de decisi\u00f3n"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Con el Foro: \u201cLos aportes en el avance hacia la igualdad de las Mujeres Mexicanas\u201d, se examinaron los obst\u00e1culos persistentes<\/strong><strong><\/strong><\/li><li><strong>Atribuyen panelistas que esta celebraci\u00f3n naci\u00f3 de la demanda por derechos pol\u00edticos de las mujeres <a href=\"https:\/\/twitter.com\/intent\/tweet?text=OPLE+Veracruz+conmemora+el+D%C3%ADa+de+la+Mujer+Mexicana&amp;url=https%3A%2F%2Fbillieparkernoticias.com%2Fople-veracruz-conmemora-el-dia-de-la-mujer-mexicana%2F&amp;via=Billie+Parker+Noticias\"><\/a><\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/BillieParkerNoticias, Xalapa, Ver., 16 de febrero, 2022.- En el marco del \u201cD\u00eda de la Mujer Mexicana\u201d, la Comisi\u00f3n Permanente de Igualdad de G\u00e9nero y No Discriminaci\u00f3n del Organismo P\u00fablico Local Electoral del Estado de Veracruz (OPLE), realiz\u00f3 el Foro: \u201cLos Aportes en el Avance hacia la Igualdad de las Mujeres Mexicanas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el 15 de febrero de 1961 se conmemora esta fecha, que tiene como antecedente, el reconocimiento de los derechos pol\u00edticos de las mexicanas, y, se dijo, que este Organismo Electoral ha tomado como propios, para abonar a la materializaci\u00f3n de m\u00e1s y mejores acciones que les permitan a las mujeres gozar de condiciones igualitarias para el pleno ejercicio de sus derechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Consejera Presidenta de la Comisi\u00f3n, Maty Lezama Mart\u00ednez, se\u00f1al\u00f3 que este foro se organiz\u00f3 con el objetivo de reflexionar sobre la igualdad sustantiva, lo cual significa que todas las mujeres desde los diversos contingentes puedan gozar por igual de los mismos derechos, recursos y oportunidades en la vida cotidiana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, sostuvo, que la realidad sigue evidenciando que a\u00fan quedan retos por superar y que los impactos intergeneracionales han puesto en la agenda p\u00fablica la necesaria toma de decisiones desde una perspectiva incluyente y no discriminatoria, lucha que se debe de continuar impulsando de manera conjunta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00f1adi\u00f3 que este \u201cForo permitir\u00e1 crear conciencia y sensibilizarnos en torno a la importante actividad que tenemos como parte de una sociedad en la que todas y todos estamos inmersos y que requiere del inter\u00e9s para contribuir en la solidificaci\u00f3n de un M\u00e9xico en el que las brechas de desigualdad no contin\u00faen siendo obst\u00e1culo para el pleno desarrollo.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su intervenci\u00f3n, la Consejera Electoral Mar\u00eda de Lourdes Fern\u00e1ndez Mart\u00ednez, dijo que \u201cser mujer en este M\u00e9xico plural resulta distinto en cada \u00e1mbito, pues no es lo mismo ser mujer en la ciudad que en una zona ind\u00edgena; no se vive de igual manera siendo ni\u00f1a que siendo adulta o bien desde los m\u00faltiples \u00e1mbitos laborales donde se desempe\u00f1an.\u201d A\u00f1adi\u00f3 que las mujeres en M\u00e9xico son tan diversas que se puede decir que no se conmemora a la Mujer Mexicana sino a las Mujeres Mexicanas, ya que no existe una sola forma de ser mujer, sino muchas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el Consejero Electoral Roberto L\u00f3pez P\u00e9rez, puntualiz\u00f3 que \u201cen este d\u00eda destaca el trabajo de las Mujeres Mexicanas que han tenido en la vida pol\u00edtica, econ\u00f3mica y social de este pa\u00eds a lo largo de su historia. Sus aportes, adem\u00e1s de ser diversos, muchos de ellos se dieron en circunstancias a\u00fan m\u00e1s dif\u00edciles en tiempos en los que la participaci\u00f3n de la mujer en los diferentes \u00e1mbitos era no solo mal vista y restringida sino hasta penada, de ah\u00ed que dichos aportes hayan adquirido mayor validez, pues tras de ellos hab\u00eda una fuerte dosis de valent\u00eda, sacrificio y esfuerzos incontables como los que seguimos viendo hasta ahora.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Foro estuvo integrado por la doctora Georgina C\u00e1rdenas Acosta, Jefa de Carrera de Sociolog\u00eda en la Facultad de Estudios Superiores Arag\u00f3n de la UNAM; Adriana Leonel de Cervantes Ascencio, integrante de la Red de Defensoras de los Derechos Pol\u00edtico-Electorales y del Colectivo 50+1 de la Ciudad de M\u00e9xico, as\u00ed como Muriel Salinas D\u00edaz, presidenta de la Red para el Avance Pol\u00edtico de las Mujeres Guerrerenses e integrante de la Red Nacional Mujeres en Plural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las ponentes coincidieron que las mujeres han obtenido sus derechos gracias a las distintitas luchas que se han hecho desde diversos \u00e1mbitos, pero lamentablemente la pandemia ha generado un retroceso y adem\u00e1s se ha aumentado la violencia, por lo que la lucha debe continuar, adem\u00e1s que la sociedad se debe involucrar en estas acciones que beneficiar\u00e1n a todas y todos de manera directa o indirecta. Insistieron en que es importante sumar esfuerzos desde los distintos \u00e1mbitos de la vida p\u00fablica para poder concretar acciones que favorezcan la vida de las Mujeres Mexicanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un aspecto que hay que superar, es todav\u00eda, el reducido acceso de las mujeres en el poder local, en los municipios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el Foro: \u201cLos aportes en el avance hacia la igualdad de las Mujeres Mexicanas\u201d, se examinaron los obst\u00e1culos persistentes<\/p>\n","protected":false},"author":3,"featured_media":45799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[693,51],"tags":[],"class_list":["post-45798","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/45798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=45798"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/45798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/45799"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=45798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=45798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=45798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}