{"id":45086,"date":"2022-02-01T13:35:25","date_gmt":"2022-02-01T19:35:25","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=45086"},"modified":"2023-07-21T18:58:06","modified_gmt":"2023-07-21T23:58:06","slug":"ocnf-da-seguimiento-violencia-contra-las-mujeres-en-guerrero","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/ocnf-da-seguimiento-violencia-contra-las-mujeres-en-guerrero\/","title":{"rendered":"OCNF da seguimiento violencia contra las mujeres en Guerrero"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li>Se re\u00fanen con la fiscal de esa entidad, Sandra Luz Valdovinos<\/li><li>Asiste tambi\u00e9n dirigentes del Centro de Derechos Humanos de la Monta\u00f1a Tla.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n<br>SemM\u00e9xico\/Ceprovysa, Acapulco, Gro., 1 de febrero, 2022.- Como parte de las acciones para dar atenci\u00f3n y acceso a la justicia a las mujeres, la Fiscal General del Estado, Sandra Luz Valdovinos Salmer\u00f3n, se reuni\u00f3 con el representante del Centro de Derechos Humanos de la Monta\u00f1a Tlachinollan e integrantes del Observatorio Ciudadano Nacional del Feminicidio (OCNF).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante el representante del Centro de Derechos Humanos de Tlachinollan, Aar\u00f3n D\u00edaz Salazar, en tanto que del OCNF asistieron Mar\u00eda de la Luz Estrada Mendoza, Carlos Humberto Olvera Gonz\u00e1lez y Mercedes Adriana Rubio Mendoza se inform\u00f3 sobre el seguimiento que la dependencia estatal da a los casos de delitos en contra de mujeres ocurridos en la regi\u00f3n Monta\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estuvieron presentes la Comisionada Nacional para Prevenir y Erradicar la Violencia contra las Mujeres, Fabiola Alan\u00eds S\u00e1mano; la coordinadora de Representaciones Temporales para Erradicar la Violencia de G\u00e9nero, Tania Galicia Carmona, entre otras personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM-Ceprovysa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se re\u00fanen con la fiscal de esa entidad, Sandra Luz Valdovinos<\/p>\n","protected":false},"author":3,"featured_media":45087,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,54],"tags":[],"class_list":["post-45086","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/45086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=45086"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/45086\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/45087"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=45086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=45086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=45086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}