{"id":44789,"date":"2022-01-27T11:33:42","date_gmt":"2022-01-27T17:33:42","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=44789"},"modified":"2023-07-21T18:57:38","modified_gmt":"2023-07-21T23:57:38","slug":"dura-critica-a-la-comision-ejecutiva-de-atencion-a-victimas-que-no-cumple-su-cometido-sin-embargo-acaba-de-renovar-su-asamblea","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/dura-critica-a-la-comision-ejecutiva-de-atencion-a-victimas-que-no-cumple-su-cometido-sin-embargo-acaba-de-renovar-su-asamblea\/","title":{"rendered":"Dura cr\u00edtica a la Comisi\u00f3n Ejecutiva de Atenci\u00f3n a V\u00edctimas que no cumple su cometido, sin embargo, acaba de renovar su asamblea"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Se designa a dos feministas para la Asamblea Consultiva, entre ellas una integrante del consejo consultivo de INMUJERES<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Cambios a un mes de ser nombrada la nueva titular y luego del abandono institucional de m\u00e1s de dos a\u00f1os<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sara Lovera&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 27 de enero, 2022.-Luego de un largo periodo de abandono institucional y falta de transparencia sobre sus acciones, la de la Comisi\u00f3n Ejecutiva de Atenci\u00f3n a V\u00edctimas CEAV celebr\u00f3 una reuni\u00f3n extraordinaria y aprob\u00f3 de manera un\u00e1nime la nueva conformaci\u00f3n de la Asamblea Consultiva para el periodo 2022-2026.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se hace a un mes de que se nombr\u00f3 nueva titular, tras a\u00f1o y medio ac\u00e9fala, seg\u00fan un an\u00e1lisis de varias organizaciones, la CEAV, arrastra deficiencias, burocracia e incapacidad para atender los derechos de las v\u00edctimas. Encima no tiene suficiente presupuesto, no cumple con la reparaci\u00f3n del da\u00f1o, no tiene apoyo institucional desde Gobernaci\u00f3n y sufre de burocracia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Las nuevas cabezas no garantizan nada, si no hay presupuesto, concluyen organizaciones civiles, entre otras el Grupo de Informaci\u00f3n en Reproducci\u00f3n Elegida GIRE que presentaron un informe hace una semana, elaborado ante la preocupaci\u00f3n de que el CEAV estuvo ac\u00e9fala desde junio de 2020, con una nueva titular apenas hace 5 semanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reuni\u00f3n extraordinaria se hizo en un momento cr\u00edtico para esta comisi\u00f3n, despojada de recursos desde 2019, sin personal capacitado, materiales de trabajo&nbsp;&nbsp;&nbsp;insuficientes, y una labor calificada como burocr\u00e1tica, por exceso de tr\u00e1mites y ausencia de voluntad pol\u00edtica para funcionar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que esta instancia qued\u00f3 sin direcci\u00f3n desde 2020, debido a la falta de apoyo institucional y luego de meses de inactividad, la CEAV entra en acci\u00f3n con estas designaciones y con un paquete de casi 40 mil v\u00edctimas de violaciones a sus derechos humanos, seg\u00fan cifras oficiales y muy abultadas recomendaciones de la comisi\u00f3n de derechos humanos, expedientes judiciales y v\u00edctimas en todo el pa\u00eds.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los nuevos nombramientos incluyen al menos a dos feministas, una m\u00e9dica, ya integrante del consejo de Inmujeres, M\u00f3nica Jasis Silberg y la abogada, integrante de Cladem y colaboradora de SemM\u00e9xico, Mar\u00eda Guadalupe Ramos Ponce, y otras son:&nbsp;&nbsp;Liliana A Lomel\u00ed, Iliana Galilea Cari\u00f1o Cepeda, Alejandra Maritza Cartagena L\u00f3pez; Luc\u00eda de los \u00c1ngeles D\u00edaz Genaro, Sim\u00f3n Hern\u00e1ndez Le\u00f3n, Adriana Muro Polo, y Gerardo Fernando R\u00edos Mart\u00ednez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">G\u00f3mez Ponce es colaboradora permanente de este portal informativo. Los nombramientos los dio a conocer el subsecretario de Poblaci\u00f3n, Migraci\u00f3n y Asuntos Religiosos de la Secretar\u00eda de Gobernaci\u00f3n, Alejandro Encinas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La CEAV qued\u00f3 sin representaciones en los estados, por el recorte presupuestal, y luego de la renuncia de la Comisionada, un largo proceso para sustituirla y seg\u00fan organizaciones no gubernamentales, su deficiencia institucional, hace inoperante la atenci\u00f3n a las v\u00edctimas, aparentemente casi el 50 por ciento de las personas registradas con esa categor\u00eda. Y hace notar que esta comisi\u00f3n no tiene claro su nivel ejecutivo dentro de la Secretar\u00eda de Gobernaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la directora del Grupo de Informaci\u00f3n en Reproducci\u00f3n Elegida&nbsp;&nbsp;GIRE, Rebeca Ramos,&nbsp;&nbsp;dos tercios de mujeres y ni\u00f1as mayores de 15 a\u00f1os han sido v\u00edctimas de al menos un episodio de violencia, adem\u00e1s de que de 2007 al 2017 pr\u00e1cticamente se triplic\u00f3 la tasa de feminicidios; y hasta el 31 de diciembre de 2020, se tienen contabilizados 24 casos o expedientes abiertos en la CEAV, relacionados con derechos reproductivos, mientras que en el Registro Nacional de V\u00edctimas Rnavi se tienen 88 registros asociados con violaciones a derechos sexuales y reproductivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, seg\u00fan un informe de esta organizaci\u00f3n la CEAV, que sufri\u00f3 severos recortes presupuestales, no est\u00e1 funcionando debidamente; tiene rezagos, incapacidad institucional y burocracia. Los ajustes pretendidos, anunciados por Gobernaci\u00f3n, no han sido posibles por \u201cfalta de voluntad pol\u00edtica \u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una de sus responsabilidades es hacer cumplir integralmente las medidas de reparaci\u00f3n dictadas por el Poder Judicial federal y local o las comisiones de Derechos Humanos,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan informes oficiales debe atender a 37 mil personas, m\u00e1s del 50 por ciento mujeres, v\u00edctimas de violaciones a sus derechos humanos, como las negativas a realizarles un aborto humanizado o atender denuncias sobre violencia obst\u00e9trica, como ha documentado Gire y Justicia para las mujeres. Estas v\u00edctimas tienen m\u00e1s de 3 a\u00f1os con dificultades en su registro y frecuentemente no reciben los apoyos institucionales necesarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">GIRE, la Fundaci\u00f3n para la Justicia y el Estado Democr\u00e1tico de Derecho (FJEDD) y la Comisi\u00f3n Mexicana de Defensa y Promoci\u00f3n de los Derechos Humanos A.C (CMDPDH), elaboraron informe, presentado hace una semana, denominado&nbsp;<a href=\"https:\/\/gire.org.mx\/wp-content\/uploads\/2022\/01\/Informe-CEAV.pdf?fbclid=IwAR3YMIHKb4VpCGVDESUJLd35fo29Fl4_x65DSF8LdaaWhGczYVwn0BCN3MA\">\u201cSin reparaci\u00f3n no hay justicia. Obst\u00e1culos para la reparaci\u00f3n integral de violaciones a Derechos Humanos en M\u00e9xico\u201d<\/a>, presentado hace una semana, el funcionamiento de esta comisi\u00f3n es muy deficiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta el 30 de junio 2019 el Renavi ten\u00eda un total de 27 mil 609 v\u00edctimas, de las cuales m\u00e1s de la mitad 13 mil 852 son mujeres. Al menos 20 por ciento de las v\u00edctimas registradas hab\u00edan solicitado integrarse del Fondo de Ayuda, Asistencia y Reparaci\u00f3n Integral, y de enero de 2015 al 30 de junio de 2019 se destinaron 976 millones de pesos para la indemnizaci\u00f3n de s\u00f3lo mil 406 v\u00edctimas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las organizaciones, que dicen que obtuvieron informaci\u00f3n en solicitudes al Instituto Nacional de Transparencia, recogieron testimonios y analizaron, espec\u00edficamente, el funcionamiento del Sistema Nacional de Atenci\u00f3n a V\u00edctimas (surgido en 2013 con la publicaci\u00f3n de la Ley General de V\u00edctimas). Adem\u00e1s, el documento habla de la experiencia de integrantes de esas organizaciones que han realizado labores de representantes legales de v\u00edctimas de violaciones a Derechos Humanos, especialmente los relacionados con la justicia reproductiva, tortura y desaparici\u00f3n forzada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cifras oficiales de montos para la reparaci\u00f3n de da\u00f1o o ayudas, contrastan con el hecho de que tan s\u00f3lo en 2019 en M\u00e9xico hubo un total de 346 mil 241 v\u00edctimas de delitos del fuero com\u00fan, de acuerdo con cifras del Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica (SESNSP). Las organizaciones civiles indicaron que el n\u00famero de v\u00edctimas contabilizadas en el Registro Nacional no refleja el aumento de casos de tortura, desaparici\u00f3n y desplazamiento forzado, y violencia contra las mujeres que se ha observado los a\u00f1os recientes en el pa\u00eds.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reto atender a v<strong>\u00edctimas de violencia sexual<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">GIRE que atiende litigios sobre violencia obst\u00e9trica y otros, encontr\u00f3 que las mujeres con sentencias o recomendaciones por esta violencia, elaboradas por las instancias de Derechos Humanos, no consiguen cumplirse por la falta de voluntad pol\u00edtica de las autoridades responsables; incapacidad para acordar&nbsp;&nbsp;&nbsp;el reconocimiento de los hechos violados de las v\u00edctimas, particularmente despu\u00e9s de negativa de aborto en casos de una violaci\u00f3n sexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn la pr\u00e1ctica, para que una v\u00edctima pueda obtener un dictamen de reparaci\u00f3n integral y asegurar su cumplimiento, debe transitar un proceso largo que a menudo es obstruido por la respuesta tard\u00eda de las autoridades para realizar acciones concretas como la provisi\u00f3n de servicios de rehabilitaci\u00f3n f\u00edsica o emocional hasta su pleno restablecimiento, recibir una justa compensaci\u00f3n o iniciar el procedimiento de investigaci\u00f3n y sanci\u00f3n a los funcionarios involucrados. Al estar involucradas diversas autoridades, el avance de la implementaci\u00f3n de las medidas depende en buena medida del tiempo, la voluntad pol\u00edtica y la capacidad de respuesta de cada una\u201d, dice el informe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ac\u00e9fala dos a\u00f1os<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el informe, en general el exceso de tr\u00e1mites, personal no capacitado o insuficiente, escasez de material y ausencia de voluntad pol\u00edtica han rezagado la atenci\u00f3n de las v\u00edctimas; a esto se suma que el&nbsp;<strong>SNAV<\/strong>&nbsp;se ha centrado en una sola dependencia (la CEAV) y a un aumento generalizado de la violencia en el pa\u00eds.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CEAV, dos a\u00f1os sin titular<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ello por su crisis institucional. En junio de 2019, renunci\u00f3 el titular de la CEAV, Jaime Roch\u00edn del Rinc\u00f3n, argumentando la imposibilidad de atender las necesidades de reparaci\u00f3n integral. En diciembre de ese a\u00f1o, Mara G\u00f3mez P\u00e9rez fue nombrada titular del organismo, pero renunci\u00f3 6 meses despu\u00e9s tras denunciar un recorte presupuestas, as\u00ed la comisi\u00f3n qued\u00f3 ac\u00e9fala un a\u00f1o y medio. El 21 de diciembre, hace poco m\u00e1s de un mes, el Senado ratific\u00f3 a Martha Yuriria Rodr\u00edguez Estrada como nueva titular.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A los otros obst\u00e1culos se sum\u00f3 que el Programa Institucional de la CEAV que se aprob\u00f3 para la administraci\u00f3n federal actual, y en particular, el Nuevo Modelo de Atenci\u00f3n Integral a V\u00edctimas, establece la intenci\u00f3n de reducir los apoyos econ\u00f3micos a las v\u00edctimas, lo que aument\u00f3 la crisis al sistema de atenci\u00f3n a v\u00edctimas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta 2019, la Comisi\u00f3n Ejecutiva de Atenci\u00f3n a V\u00edctimas destinaba 500 millones de pesos al pago de indemnizaciones. Para dimensionar: si a cada una de las 200 mil v\u00edctimas de homicidio doloso que hubo en M\u00e9xico tan s\u00f3lo en 2006 y 2007 se le entregara 470 mil pesos, tomar\u00eda m\u00e1s de 100 a\u00f1os pagar a todas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con las organizaciones civiles, el recorte imposibilita el pago las rentas y servicios b\u00e1sicos de las oficinas centrales y los 32 Centros de Atenci\u00f3n Integral en las entidades federativas, pone en peligro de perder el alojamiento y resguardo del Renavi, y reduce 30 por ciento a asesores jur\u00eddicos, entre otros da\u00f1os.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ana Lorena Delgadillo P\u00e9rez, directora del FJEDD, en la presentaci\u00f3n del informe dijo que las mayores dificultades son el cumplimiento de las medidas de reparaci\u00f3n las enfrentan las familias, algunas desde otros pa\u00edses como v\u00edctimas de delito en M\u00e9xico, as\u00ed como migrantes centroamericanas. Como ejemplo, dijo, su organizaci\u00f3n representa legalmente 250 casos de personas migrantes, de los cuales no se ha conseguido que se cumpla una sola medida de reparaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Delgadillo P\u00e9rez habl\u00f3 de las fallas de la CEAV:&nbsp;&nbsp;burocracia, falta de personal especializado en atenci\u00f3n a v\u00edctimas, ausencia de un sistema sencillo de recepci\u00f3n de informaci\u00f3n, exceso de formalismo y discrecionalidad de la instituci\u00f3n para decidir qu\u00e9 casos s\u00ed repara y qu\u00e9 casos no.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ella record\u00f3 que en la masacre de los 72 migrantes, ocurrida en Tamaulipas hace 11 a\u00f1os, a\u00fan hay familias que no reciben ni los 800 d\u00f3lares que la CEAV prometi\u00f3 que les dar\u00eda a cada una para medicamentos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La directora de la CMDPDH, Graciela Mart\u00ednez Manzo, asegur\u00f3 que, en casos de tortura y detenci\u00f3n arbitraria, como los que su organizaci\u00f3n acompa\u00f1a, es posible que en todo el pa\u00eds no exista un solo caso en el que se hayan cumplido totalmente las medidas de reparaci\u00f3n integral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, cuando las v\u00edctimas consiguen un fallo favorable en primera instancia para su reparaci\u00f3n, la CEAV y sus hom\u00f3logas enfrentan litigios agresivos en contra de las v\u00edctimas y es contra ellas donde despliegan los recursos y la maquinaria de la instituci\u00f3n.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se designa a dos feministas para la Asamblea Consultiva, entre ellas una integrante del consejo consultivo de INMUJERES Cambios a un mes de ser nombrada la nueva titular y luego del abandono institucional de m\u00e1s de dos a\u00f1os Sara Lovera&nbsp; SemM\u00e9xico, Cd. de M\u00e9xico, 27 de enero, 2022.-Luego de un largo periodo de abandono institucional [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":44790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,51],"tags":[],"class_list":["post-44789","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/44789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=44789"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/44789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/44790"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=44789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=44789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=44789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}