{"id":44399,"date":"2022-01-19T13:39:53","date_gmt":"2022-01-19T19:39:53","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=44399"},"modified":"2023-07-21T18:56:49","modified_gmt":"2023-07-21T23:56:49","slug":"opinion-gobernadores-de-mal-en-peor-cuitlahuac-cuauhtemoc-sheinbaum-y-los-ex-cooptados-por-la-4t","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/opinion-gobernadores-de-mal-en-peor-cuitlahuac-cuauhtemoc-sheinbaum-y-los-ex-cooptados-por-la-4t\/","title":{"rendered":"Opini\u00f3n| Gobernadores, de mal en peor\/ Cuitl\u00e1huac, Cuauht\u00e9moc, Sheinbaum\/ Y los ex, cooptados por la 4T"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Francisco Rodr\u00edguez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/\u00cdndice Pol\u00edtico, Cd. de M\u00e9xico, 19 de enero, 2022.- Por simple l\u00f3gica. Se apoya s\u00f3lo aquello que se observa d\u00e9bil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que est\u00e1 firme y fuerte no requiere ning\u00fan apuntalamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso la estrategia de apoyar al mandatario veracruzano Cuitl\u00e1huac Garc\u00eda por parte de la se\u00f1ora Claudia Sheinbaum, el fin de semana, y ayer por el mism\u00edsimo presidente L\u00f3pez Obrador s\u00f3lo revela lo pol\u00edticamente enclenque \u2013el colega Aurelio Contreras dixit\u2013&nbsp; oriundo de Xalapa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ah\u00ed en el Palacio de Gobierno de la capital veracruzana el hombre fuerte es el secretario de Gobierno Eric Cisneros, quien s\u00f3lo usa al gobernador como parapeto y en muchas ocasiones hasta como clown, para diversi\u00f3n de chicos y grandes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cisneros est\u00e1 tan firme en su puesto que incluso la petici\u00f3n del chihuahuense Bryan LeBar\u00f3n a Joe Biden para que lo investigue junto con el mandatario morelense Cuauht\u00e9moc Blanco por sus presumibles y muy probables ligas con la delincuencia organizada les est\u00e1n haciendo lo que, dicen, le hace el viento al Benem\u00e9rito de las Am\u00e9ricas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tienen ambos el apoyo de AMLO.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y, en consecuencia, el de la se\u00f1ora Sheinbaum que como lorito bien amaestrado s\u00f3lo atina a repetir la voz de su amo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El de Blanco, como el de Garc\u00eda y el de Cisneros, ya es un caso policiaco m\u00e1s que pol\u00edtico. Los cad\u00e1veres, las matanzas y los eficaces medios de comunicaci\u00f3n que son las llamadas&nbsp;<em>narcomantas<\/em>&nbsp;han hecho mella en la efectividad de sus administraciones y en la credibilidad de la 4T en la que dicen militar, as\u00ed y el morelense haya sido postulado a la alcald\u00eda de Cuernavaca y al gobierno de la entidad por un partido pelele de Morena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1ndo recibe la se\u00f1ora Sheinbaum a Cuauht\u00e9moc Blanco en sus oficinas del viejo Palacio del Ayuntamiento? \u00bfCu\u00e1ndo a Eric Cisneros?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiz\u00e1 cuando deje la actitud de cuentachiles y ya no reclame a los consejeros del INE la adquisici\u00f3n de croquetas que no son para sus mascotas, sino para los perros que prestan servicios de seguridad en las instalaciones del Instituto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dispendio en la Jefatura de Gobierno de CDMX<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toda la mala publicidad que le acarrea a la jefa de Gobierno las reuniones como la sostenida con Cuitl\u00e1huac Garc\u00eda, pretende ser neutralizada con recursos p\u00fablicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y es que apenas el PAN advirti\u00f3 que Claudia Sheinbaum es quien verdaderamente \u201cgoza\u201d de gastos \u201csuperfluos\u201d con m\u00e1s de 850 millones de pesos para promover su nombre e imagen en v\u00edspera de construir una candidatura presidencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras los ataques de la mandataria al INE, el GPPAN calific\u00f3 de \u201csospechosa\u201d esta actitud en el conflicto pol\u00edtico de AMLO, cuando la CDMX vive la peor coyuntura sanitaria por el pico de la peor semana de contagio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTal pareciera que se presta al juego sucio de L\u00f3pez Obrador para desviar la atenci\u00f3n de la galopante ola de contagios Covid19\u201d, refirieron los panistas al solicitarle el s\u00e1bado pasado a la mandataria no inmiscuirse en los asuntos de agenda pol\u00edtica y fuera de su competencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recordaron que quien s\u00ed verdaderamente tiene gastos superfluos para 2022, es ella: 400 millones de pesos para su imagen personal con cargo al erario. 346 millones de pesos para su promoci\u00f3n personal en radio y televisi\u00f3n. 104 millones de pesos m\u00e1s para mover su nombre por internet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPor qu\u00e9 tenemos que pagar por ello los pagaimpuestos de la capital nacional?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Indicios<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro gobernador, ahora el neoleon\u00e9s Samuel Garc\u00eda, vuelve a estar en la picota de la opini\u00f3n p\u00fablica por sus desplantes y los de su se\u00f1ora esposa. La \u201cadopci\u00f3n,&nbsp;<em>just for the weekend<\/em>\u201d de un beb\u00e9 alojado en la Casa Cuna del DIF de la entidad norte\u00f1a para subir fotos a las redes sociales los muestra tal y como son: ignaros, fr\u00edvolos, c\u00ednicos. Los empresarios de la entidad insisten en poner de gobernador a cada ejemplar que\u2026 * * * Pregunta un lector, cuya entidad me reservo para no provocarle problemas. \u201c\u00bfPor qu\u00e9 nadie comenta lo peligroso que es un personaje con Ad\u00e1n Augusto L\u00f3pez? No debemos perder de vista que con su Ley Garrote intent\u00f3 criminalizar las protestas. Tampoco dejar de lado que, al igual que AMLO, es enemigo de la transparencia, ya que descabez\u00f3 el Instituto de Transparencia de Tabasco haciendo renunciar a sus integrantes y poniendo a sus incondicionales, tal y como hicieron en Veracruz y Chiapas. * * * Desde el d\u00eda de las elecciones federales, y estatales en el caso de Sonora, se sab\u00eda que Claudia Pavlovich tendr\u00eda un premio de la 4T. Primero, por hacerse a un lado a\u00fan y cuando el candidato de la alianza en la que participaba el PRI, Ernesto El Borrego G\u00e1ndara aventajaba la contienda all\u00e1 por el mediod\u00eda. En ese momento, cuentan por all\u00e1, personeros del crimen organizado comenzaron a operar, intimidando y hasta secuestrando a quienes apoyaban al contrincante de Alfonso Durazo. La se\u00f1ora, por eso, ha sido designada consulesa en Barcelona, la capital de Catalunya. * * * No es muy distinto el caso de Carlos Miguel Aysa Gonz\u00e1lez, en el caso de Campeche. Tambi\u00e9n abon\u00f3, por omisi\u00f3n y hasta por comisi\u00f3n, en el triunfo\u201d de Layda Sansores. Pero aqu\u00ed el golpe a los pri\u00edstas es m\u00e1s severo, toda vez que el personaje fue \u00bfo a\u00fan es? el hombre de todas las confianzas de Alejandro&nbsp;<em>Alito<\/em>&nbsp;Moreno, a tal grado que fue a Aysa a quien hered\u00f3 el cargo de gobernador cuando vino a Ciudad de M\u00e9xico a acabar de matar al PRI. * * * Atendible el tweet de Enrique de la Madrid Cordero (@edelamadrid):<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A m\u00ed me dan penita los exgobernadores y exgobernadoras (sic) que aceptan chambas en el servicio exterior mexicano acabando de perder las elecciones en sus estados. Se ve mal, se presta a malas interpretaciones. \u00bfO no?\u201d * * * Y esas amenazas de Alito Moreno de expulsar a Pavlovich y a Aysa mueven a risa. \u00a1Si ya no existe el partido! * * * Sinteticemos: los gobernadores del sexenio pe\u00f1ista fueron pillos redomados. Tambi\u00e9n los de la 4T, s\u00f3lo que estos \u00faltimos, adem\u00e1s, son c\u00ednicos. * * * Por hoy es todo. Agradezco la lectura de estas l\u00edneas y, como siempre, deseo que usted tenga \u00a1buenas gracias y muchos, muchos d\u00edas!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.indicepolitico.comindicepolitico@gmail.com@IndicePolitico@pacorodriguez\">https:\/\/www.indicepolitico.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.indicepolitico.comindicepolitico@gmail.com@IndicePolitico@pacorodriguez\">indicepolitico@gmail.com <\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.indicepolitico.comindicepolitico@gmail.com@IndicePolitico@pacorodriguez\">@IndicePolitico<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.indicepolitico.comindicepolitico@gmail.com@IndicePolitico@pacorodriguez\">@pacorodriguez<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por simple l\u00f3gica. Se apoya s\u00f3lo aquello que se observa d\u00e9bil.<\/p>\n","protected":false},"author":3,"featured_media":44400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,110,35],"tags":[459],"class_list":["post-44399","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-la-opinion-columnas","category-opinion","tag-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/44399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=44399"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/44399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/44400"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=44399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=44399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=44399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}