{"id":44266,"date":"2022-01-17T10:44:15","date_gmt":"2022-01-17T16:44:15","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=44266"},"modified":"2023-07-21T18:56:53","modified_gmt":"2023-07-21T23:56:53","slug":"miradas-de-reportero-es-tiempo-de-una-ley-para-el-sistema-nacional-de-proteccion-a-periodistas","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/miradas-de-reportero-es-tiempo-de-una-ley-para-el-sistema-nacional-de-proteccion-a-periodistas\/","title":{"rendered":"Miradas de reportero| Es tiempo de una ley para el sistema nacional de protecci\u00f3n a periodistas"},"content":{"rendered":"\n<p class=\"has-text-align-right wp-block-paragraph\"><em>Nota. &#8211; Texto para el primer dialogo regional para la nueva ley general de prevenci\u00f3n y protecci\u00f3n ante agravios a personas defensoras de los derechos humanos y periodistas en la ciudad de M\u00e9xico los d\u00edas 17 y 18 de enero de 2022<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Rogelio Hern\u00e1ndez L\u00f3pez<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 17 de enero, 2022.- Buena repercusi\u00f3n e inter\u00e9s despert\u00f3 la convocatoria que present\u00f3 el 12 de enero Alejandro Encinas Rodr\u00edguez, Subsecretario de Derechos Humanos, Poblaci\u00f3n y Migraci\u00f3n para iniciar los di\u00e1logos p\u00fablicos por una nueva ley de protecci\u00f3n a personas defensoras de derechos humanos y periodistas que sustituya a la de 2012.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre algunos periodistas obstinados en la protecci\u00f3n para sus colegas (como este reportero) esa convocatoria caus\u00f3 tres sorpresas a\u00f1adidas:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Qu\u00e9 se decidiera realizar foros regionales y uno nacional para una nueva ley que requiere el m\u00e1s <strong><em>amplio respaldo social\u2026<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que desde ahora se anuncie que se pondr\u00e1 por delante la <strong><em>prevenci\u00f3n\u2026 y<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que deber\u00e1 ser una ley <strong><em>general<\/em><\/strong> para establecer obligaciones a los gobiernos municipales y estatales y ya no \u00fanicamente para el federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas pretensiones anunciadas en la convocatoria atienden, en principio, demandas expresadas por la coalici\u00f3n amplia de organismos sociales del <em>Espacio OSC para la Protecci\u00f3n de Personas Defensoras y Periodistas<\/em>, del Consejo Consultivo del Mecanismo, de la oficina en M\u00e9xico para los Derechos Humanos de las Naciones Unidas y de un n\u00famero no muy amplio de periodistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo principal de todas estas exigencias Encinas lo sintetiz\u00f3 el 5 de octubre de 2021 como la necesidad de modificar el marco legal para impulsar un <strong>Sistema Nacional de Prevenci\u00f3n y Protecci\u00f3n<\/strong> para personas defensoras de derechos humanos y periodistas en todo M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las y los periodistas sensibles al tema debi\u00e9ramos participar en todos esos foros e impulsar que la nueva ley signifique precisamente eso: una ley nacional que facilite <strong>una pol\u00edtica de Estado. <\/strong>Y nada menos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Subsanar dos oquedades del Estado<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En el nuevo gobierno federal se han abierto condiciones para vislumbrar una pol\u00edtica de Estado. Por ejemplo, d\u00edas despu\u00e9s del nombramiento como Subsecretario de Alejandro (11 octubre de 2018), este reportero le dedic\u00f3 una columna a su antiguo camarada de partido con un mensaje en ese sentido\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cEncinas, te toca otro tigre: proteger periodistas<\/em> \u2026<em>porque ser\u00e1s el responsable directo de enfrentar el problema nacional en que se convirtieron los agravios y asesinatos que aumentan cada a\u00f1o y que en tres sexenios nadie ha podido frenarlos<\/em>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como causa de fondo, anot\u00e9que <em>\u201cla subvaloraci\u00f3n y desatenci\u00f3n del problema que tuvieron los presidentes Fox, Calder\u00f3n y Pe\u00f1a foment\u00f3 una enorme oquedad del Estado ante la sociedad y los periodistas. (<\/em>nunca entendieron<em>) que los reporteros son los primeros sujetos de la mediaci\u00f3n democr\u00e1tica y que deben contar con la protecci\u00f3n del Estado\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cCasi sin excepci\u00f3n, la otra falla del Estado la produjeron los gobernadores y procuradores estatales <\/em>(que)<em> ni siquiera tomaron en serio las tres cartas de coordinaci\u00f3n que firmaron. En las entidades se comete la mayor\u00eda de agresiones y de asesinatos; all\u00ed deber\u00eda procurarse justicia, pero no lo hacen. La fiscal\u00eda federal se desentiende, no atrae los casos porque dice que pertenecen al fuero com\u00fan y no al federal. Y entonces el \u00edndice de impunidad sigue en 97 por ciento. La CNDH ha emitido cuatro recomendaciones generales para que todas las instancias atiendan el problema, pero no le hacen caso porque le faltan dientes para sancionar\u201d.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La Segob, rectora<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Seis meses despu\u00e9s de aquel escrito p\u00fablico, por su formaci\u00f3n de izquierda Encinas comenz\u00f3 a exponer una visi\u00f3n distinta a la que ten\u00edan los gobiernos anteriores. Empez\u00f3 a formular las riberas de lo que deber\u00eda ser un <strong><em>Sistema Nacional de Prevenci\u00f3n y Protecci\u00f3n.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 29 de abril de 2019, recog\u00ed esa categor\u00eda de Alejandro en otra columna titulada:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cAhora s\u00ed, la Segob puede ser rectora en protecci\u00f3n integral a defensores y periodistas\u201d <\/em>y a\u00f1ad\u00ed elementos de una autocr\u00edtica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces reconoc\u00ed que \u201c<em>quienes impulsamos la ley federal de Protecci\u00f3n y el Mecanismo en 2012 hicimos mal varias cosas. Una fue encausar a funciones policiales a la Secretaria de Gobernaci\u00f3n cuando deber\u00eda ser normativa y rectora de pol\u00edticas p\u00fablicas; otro error fue suponer que una ley federal ser\u00eda suficiente para atender un problema nacional que crec\u00eda en todos los estados y, un error m\u00e1s fue impulsar hasta 20 leyes estatales de protecci\u00f3n con la mismas caracter\u00edsticas cautelar-policiaca y meramente reactivas, cuando lo indispensable es la prevenci\u00f3n en todas las instancias del Estado. Se necesitaba un giro radical\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La experiencia nos ense\u00f1\u00f3 que una ley de alcance nacional y de aplicaci\u00f3n efectiva requiere de al menos tres cosas: voluntad pol\u00edtica verdadera, pertinencia y viabilidad para su institucionalizaci\u00f3n y, sobre todo, el respaldo activo de la o las poblaciones a las que se reconozcan derechos y se les protejan. Poco de eso lo obtuvimos con la ley actual y la mayor\u00eda de leyes locales relacionadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por esas y otras razones creo que en los di\u00e1logos p\u00fablicos puede darse ese giro y cristalizar una ley diferente que enmiende los errores originales que varios cometimos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si este reportero tuviera oportunidad de exponer lo anterior en el primer di\u00e1logo regional a\u00f1adir\u00eda los siguientes elementos que parecen fundamentales:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>No desconcentrar al Mecanismo, pero s\u00ed lo policiaco<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para la nueva ley habr\u00e1 que considerar varias de las normas enunciadas en las reformas que aprob\u00f3 la C\u00e1mara de Diputados en diciembre de 2020 para la ley actual de protecci\u00f3n y que el Senado no ratific\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunas de esas normas parecen positivas porque derivaron de amplias consultas y deliberaciones que sostuvieron, en la modalidad de parlamento abierto, las y los legisladores con m\u00e1s de cien organizaciones y personalidades de defensa de los derechos humanos, del periodismo y de instancias internacionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esas reformas intentan darle garant\u00edas al Mecanismo federal para contar con recursos anuales suficientes para las demandas de protecci\u00f3n y pol\u00edticas p\u00fablicas, pero etiquetados por el Congreso de la Uni\u00f3n; ampliarle facultades y una estructura adecuada su funci\u00f3n rectora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo ello parece positivo, pero lo negativo en esa propuesta de reforma es querer desconcentrar al Mecanismo de la Segob y convertirlo en \u00f3rgano aut\u00f3nomo. Ese ser\u00eda un error craso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando los riesgos son claros e inminentes es indispensable la protecci\u00f3n cautelar que proporcionan las instancias de seguridad p\u00fablica. Estas son las que tienen la responsabilidad de proporcionar garant\u00edas a la integridad f\u00edsica de los defensores y periodistas en riesgo, pero no deben hacerlo las instancias civiles que, en lo general tienen fuerza y capacitaci\u00f3n insuficientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta funci\u00f3n y car\u00e1cter para-policiaco actual es la que debiera desconcentrarse del mecanismo con la nueva ley para darle la rector\u00eda y supervisi\u00f3n de las medidas cautelares y adem\u00e1s tener m\u00e1s apoyo en los organismos civiles y profesionales que lo acompa\u00f1en.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Prever y prevenir agravios<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Este reportero hace \u00e9nfasis en la protecci\u00f3n integral para quienes hacen periodismo profesional porque las y los defensores de los derechos humanos si cuentan con una red robusta de organizaciones muy activas, con estudios y propuestas a diferencia de los periodistas que no hemos podido construir organismos serios mexicanos para la autoprotecci\u00f3n y menos para convertirnos en interlocutores reales ante los poderes y los patrones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Propongo a mis colegas que reivindiquemos en los foros los seis m\u00ednimos que la nueva ley debe contener para beneficio de la funci\u00f3n de periodista en M\u00e9xico:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Que la ley sea general y dar prioridad a la prevenci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Qu\u00e9 all\u00ed se perfile claramente el Sistema Nacional de Prevenci\u00f3n y Protecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. Que la Secretar\u00eda de Gobernaci\u00f3n sea la autoridad rectora, tanto para la protecci\u00f3n ante riesgos y en la supervisi\u00f3n de medidas protectoras, como para el dise\u00f1o de pol\u00edticas p\u00fablicas preventivas de aplicaci\u00f3n obligatoria para las autoridades de los tres niveles\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. Que se ajuste la definici\u00f3n de las personas periodistas conforme a lo que ya contienen algunas leyes locales &#8211;como la de la Ciudad de M\u00e9xico&#8211; autorizadas por la Suprema Corte de Justicia de la Naci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La definici\u00f3n debe precisar que las y los periodistas profesionales tienen la funci\u00f3n esencial de informar y con ello adquieren una responsabilidad y relaci\u00f3n distinta con toda la sociedad, diferente a las que tienen las personas colaboradoras period\u00edsticas. La redacci\u00f3n que refiero es:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Las personas periodistas realizan una actividad permanente del m\u00e1s alto inter\u00e9s p\u00fablico por su servicio social a las relaciones democr\u00e1ticas; esta actividad consiste en buscar, recibir, recabar, almacenar, generar, procesar, editar, comentar, opinar, difundir, publicar o proveer informaci\u00f3n a trav\u00e9s de cualquier medio de difusi\u00f3n y comunicaci\u00f3n que puede ser impreso, radioel\u00e9ctrico, digital o imagen; funciones acreditadas en su actividad cotidiana, experiencia, estudios o en su caso t\u00edtulo para ejercer el periodismo profesionalmente. Se reconocen tambi\u00e9n a las personas colaboradoras period\u00edsticas, quienes ejercen las libertades de expresi\u00f3n y\/o informaci\u00f3n con actividades espor\u00e1dicas o regulares, sin que se les requiera registro gremial o acreditaci\u00f3n alguna.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. Que para la operaci\u00f3n del nuevo Mecanismo deber\u00e1n perfilarse una visi\u00f3n m\u00e1s amplia y funciones de mayor alcance a la Unidad de Prevenci\u00f3n para que se convierta en la instancia de inteligencia capaz de prever y prevenir, coordinando la construcci\u00f3n de estrategias espec\u00edficas y pol\u00edticas p\u00fablicas con respaldo social, impulsar la coordinaci\u00f3n intersecretarial del Ejecutivo federal y las sinergias de actuaci\u00f3n de los tres niveles de gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6. Que en las pol\u00edticas p\u00fablicas de prevenci\u00f3n el Mecanismo perfile un plan nacional de protecci\u00f3n integral para reporteros y otros periodistas y que sea aplicado intersecretarialmente, con una serie de programas para reducirles vulnerabilidades profesionales, para reconocerles al menos diez derechos profesionales que garantizan la fluidez de la informaci\u00f3n de inter\u00e9s social y para facilitarles la obtenci\u00f3n de fortalezas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Nosotros<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s all\u00e1 de la nueva ley, hay que insistir en que las y los periodistas tambi\u00e9n tenemos que asumir responsabilidades que completen y faciliten el trabajo a ese eventual sistema nacional de prevenci\u00f3n y protecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Requerimos un programa com\u00fan entre el mayor n\u00famero posible de colegas para contar una red de redes de autoprotecci\u00f3n, tanto para reacci\u00f3n r\u00e1pida ante amenazas como para impulsar mayores fortalezas profesionales, una red con mayor vinculaci\u00f3n con periodistas de otros pa\u00edses, con empresas de periodismo, con m\u00e1s coaliciones de defensores y con la cooperaci\u00f3n sincera de universidades, empresas y organismos internacionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">rogeliohl@yahoo.com.mx<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre algunos periodistas obstinados en la protecci\u00f3n para sus colegas (como este reportero) esa convocatoria caus\u00f3 tres sorpresas a\u00f1adidas<\/p>\n","protected":false},"author":3,"featured_media":8473,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[693,106,35,85],"tags":[459],"class_list":["post-44266","post","type-post","status-publish","format-standard","has-post-thumbnail","category-693","category-mirada-de-reportero","category-opinion","category-rogelio-hernandez-lopez","tag-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/44266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=44266"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/44266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/8473"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=44266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=44266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=44266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}