{"id":43361,"date":"2021-12-12T14:02:59","date_gmt":"2021-12-12T20:02:59","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=43361"},"modified":"2023-07-21T18:54:43","modified_gmt":"2023-07-21T23:54:43","slug":"dia-mundial-de-la-informatica-lleva-nombre-de-mujer","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/dia-mundial-de-la-informatica-lleva-nombre-de-mujer\/","title":{"rendered":"D\u00eda mundial de la Inform\u00e1tica lleva nombre de mujer"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/Prensa Latina, La Habana, 12 de diciembre, 2021.-) Casi ning\u00fan proceso pasa hoy en el mundo sin la intervenci\u00f3n de la Inform\u00e1tica, una rama de la ciencia que celebra en esta jornada su d\u00eda mundial, en homenaje a una mujer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Considerada la madre de la programaci\u00f3n, Grace Hopper fue la primera persona en utilizar el Harvard Mark I, el ordenador electromec\u00e1nico pionero del orbe, desarrollado por la reconocida empresa multinacional estadounidense IBM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Naci\u00f3 un 9 de diciembre de 1906 y en 1983, durante el Primer Encuentro de Profesionales Inform\u00e1ticos, surgi\u00f3 la idea de recordarle estableciendo la fecha para celebrar el d\u00eda internacional del sector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero la impronta de Hopper lleg\u00f3 a otras labores: fue ella la responsable del desarrollo del primer compilador, adem\u00e1s de participar en la aparici\u00f3n de los m\u00e9todos de validaci\u00f3n, los procesos que garantizan que los procedimientos funcionen de forma adecuada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Varias referencias internacionales coinciden en que si no fuera por Hooper hubiera sido imposible desarrollar la WWW o diferentes lenguajes de programaci\u00f3n \u00fatiles en la actualidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1959, esta mujer de los ordenadores -no precisamente de ropa en el hogar- cre\u00f3 el primer lenguaje complejo de ordenador universal, el COBOL (Common Business-Oriented Language), orientado a la inform\u00e1tica de gesti\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue la misma Hooper quien populariz\u00f3 t\u00e9rminos como bug (bicho en ingl\u00e9s), el cual se refiere a un error en un programa, mientras que el t\u00e9rmino debug significa depurar un programa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recibi\u00f3 numerosos reconocimientos como el de \u201cHombre del a\u00f1o\u201d en ciencias de la computaci\u00f3n en 1969.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n era llamada varias veces por la armada norteamericana para que ayudara a estandarizar sus lenguajes de alto nivel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hooper muri\u00f3 el 1 de enero de 1992, a los 85 a\u00f1os, y en su honor, en julio de 2020 Google Cloud anunci\u00f3 la construcci\u00f3n de un cable submarino de fibra \u00f3ptica que unir\u00e1 Estados Unidos, el Reino Unido y Espa\u00f1a, el cual llevar\u00e1 su nombre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La inform\u00e1tica contribuy\u00f3 exponencialmente a la revoluci\u00f3n tecnol\u00f3gica del siglo XX, y la modernizaci\u00f3n del mundo como lo conocemos hoy d\u00eda, es, en parte, gracias a los avances de esta ciencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con bases en las Matem\u00e1ticas y la F\u00edsica, cada proceso de desarrollo est\u00e1 influenciando por ella, desde la ingenier\u00eda, industria, medicina, arquitectura, administraci\u00f3n p\u00fablica hasta la organizaci\u00f3n de empresas, educaci\u00f3n, transporte, comercio, o las comunicaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los innumerables avances y el impacto de la Inform\u00e1tica en el mundo moderno se destaca la inteligencia artificial, la cual hace posible que las m\u00e1quinas realicen actividades y tareas como seres humanos.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><em>#<\/em><a href=\"https:\/\/www.prensa-latina.cu\/tags\/dia\"><em>d\u00eda<\/em><\/a><em>&nbsp;#<\/em><a href=\"https:\/\/www.prensa-latina.cu\/tags\/hopper\"><em>Hopper<\/em><\/a><em>&nbsp;#<\/em><a href=\"https:\/\/www.prensa-latina.cu\/tags\/informatica\"><em>inform\u00e1tica<\/em><\/a><em>&nbsp;#<\/em><a href=\"https:\/\/www.prensa-latina.cu\/tags\/mundial\"><em>Mundial<\/em><\/a><em><\/em><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Considerada la madre de la programaci\u00f3n, Grace Hopper fue la primera f\u00e9mina en utilizar el Harvard Mark I, el ordenador electromec\u00e1nico pionero del orbe, desarrollado por la reconocida empresa multinacional estadounidense IBM.<\/p>\n","protected":false},"author":3,"featured_media":43362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[692,65,64],"tags":[],"class_list":["post-43361","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-efemerides","category-para-saber"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/43361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=43361"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/43361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/43362"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=43361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=43361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=43361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}