{"id":43354,"date":"2021-12-12T11:15:30","date_gmt":"2021-12-12T17:15:30","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=43354"},"modified":"2023-07-21T18:54:43","modified_gmt":"2023-07-21T23:54:43","slug":"presidenta-del-comite-de-cedaw-violencia-contra-las-mujeres-no-es-una-rueda-suelta","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/presidenta-del-comite-de-cedaw-violencia-contra-las-mujeres-no-es-una-rueda-suelta\/","title":{"rendered":"Presidenta del Comit\u00e9 de CEDAW: Violencia contra las mujeres no es una rueda suelta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gladys Acosta, abogada y soci\u00f3loga peruana, est\u00e1 en un tramo del malec\u00f3n de Costa Verde, en Lima, Foto: Mariela Jara \/ IPS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La movilizaci\u00f3n a favor de los derechos de las mujeres es much\u00edsimo m\u00e1s potente, amplia y m\u00e1s pol\u00edtica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Es imperativo analizar la violencia de g\u00e9nero como parte de las discriminaciones sist\u00e9micas contra las mujeres<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>40 a\u00f1os cumpli\u00f3 la Convenci\u00f3n, carta fundamental de los Derechos Humanos de las mujeres<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mariela Jara<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/IPS, Lima, Per\u00fa, 12 de diciembre, 2021.- \u201cEl nivel de injustica que hay en el mundo no se puede quedar as\u00ed, no soy pesimista del futuro\u201d expresa la presidenta del Comit\u00e9 de la CEDAW, Gladys Acosta, &nbsp;en una entrevista con IPS en la capital peruana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<a href=\"https:\/\/www.ohchr.org\/sp\/professionalinterest\/pages\/cedaw.aspx\">Convenci\u00f3n sobre la Eliminaci\u00f3n de Todas las Formas de Discriminaci\u00f3n contra la Mujer<\/a>&nbsp;(CEDAW, en ingl\u00e9s) cumpli\u00f3 cuatro d\u00e9cadas en septiembre de este a\u00f1o como la herramienta jur\u00eddica de los derechos de las mujeres que los 189 Estados parte est\u00e1n obligados a cumplir. &nbsp;Muchos la califican como la \u201cconstituci\u00f3n universal de los derechos de las humanas\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acosta, abogada y soci\u00f3loga peruana, feminista, preside el Comit\u00e9 de 23 expertos independientes, con mandatos de cuatro a\u00f1os y encargados de supervisar la aplicaci\u00f3n de la Convenci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras un intenso periodo de sesiones, Acosta se encuentra en Lima para retornar el 2022 a sus obligaciones en Ginebra, donde opera&nbsp;<a href=\"https:\/\/www.ohchr.org\/en\/hrbodies\/cedaw\/pages\/cedawindex.aspx\">el Comit\u00e9,<\/a>&nbsp;y culminar su periodo. Mientras, estas semanas le ofrecer\u00e1n el panorama del mar del Pac\u00edfico y el relajante rumor de su oleaje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando insiste en que no es pesimista del futuro, subraya que, por el contrario,&nbsp; s\u00ed \u201csoy muy cr\u00edtica y pesimista de lo que existe hoy\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos llegando al l\u00edmite de una era que da sus alaridos de muerte porque el nivel de injusticia en el mundo no se puede quedar as\u00ed\u201d, plantea la especialista que ha ocupado antes altos cargos regionales en agencias de las Naciones Unidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los temas abordados con IPS, Acosta plantea la importancia de analizar la violencia de g\u00e9nero como parte de las discriminaciones sist\u00e9micas contra las mujeres y se\u00f1ala que la pandemia est\u00e1 marcando un antes y un despu\u00e9s no solo en relaci\u00f3n a este problema, sino un quiebre de \u00e9poca que urge a colocar como una prioridad el tema del cuidado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;IPS: \u00bfConsidera &nbsp;que la pandemia de covid-19 marca un antes y un despu\u00e9s en relaci\u00f3n a las discriminaciones a las mujeres, un paso atr\u00e1s en conquistas? \u00bfSe puede hacer esa lectura?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">GLADYS ACOSTA: Creo que eso va a ser para todo, no solo para las mujeres, la discriminaci\u00f3n o los derechos humanos, me atrevo a pensar que va a ser juzgado como el quiebre de una \u00e9poca. Venimos de una \u00e9poca donde se ha producido la mayor cantidad de concentraci\u00f3n de riqueza en la historia del mundo, con una poblaci\u00f3n en pobreza&nbsp;<em>in crescendo<\/em>,&nbsp; que est\u00e1 llegando a puntos insostenibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es muy importante que se desarrolle esta consciencia, porque nos han vendido la idea de que tener dinero o comprar bienes es como el n<em>on plus ultra&nbsp;<\/em>de todo. Estamos en un posneoliberalismo y nadie sabe a ciencia cierta cu\u00e1n lejos se ha llegado, pero estamos en un punto de quiebre porque esta econom\u00eda basada en la explotaci\u00f3n de territorios, de personas, del conocimiento, es una apropiaci\u00f3n il\u00edcita constante de todo y hoy con la pandemia se ha puesto a la luz que los seres humanos necesitan cuidado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto se ha convertido en el centro y puesto en la agenda, la pandemia ha desgarrado justamente que en el no cuidado se ha exacerbado la presencia de este virus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(Con energ\u00eda, &nbsp;Acosta recuerda que hace ya bastantes a\u00f1os la econom\u00eda feminista plante\u00f3 que el sistema econ\u00f3mico no puede vivir sin&nbsp; el trabajo de las mujeres, sobre todo el trabajo no pagado. Y convoca a analizar la actual situaci\u00f3n con ojos m\u00e1s frescos y relacionando mejor para, por ejemplo, \u2018dejar de mirar el creciente problema de la violencia contra las mujeres como algo dislocado, como una rueda suelta\u2019).<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando en el Comit\u00e9 hemos tomado posici\u00f3n por el 25 de noviembre (<a href=\"https:\/\/www.un.org\/es\/observances\/ending-violence-against-women-day\">D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra la Mujer<\/a>), hemos visto que se han exacerbado tres formas de violencia: los feminicidios, la violencia dom\u00e9stica y una violencia que se expresa a trav\u00e9s de los medios virtuales que ha cobrado una vitalidad enorme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces s\u00ed, hay unas cosas nuevas, pero queda clar\u00edsimo que no hemos resuelto las formas de discriminaci\u00f3n b\u00e1sicas que est\u00e1n en la base de la sociedad, que es una violencia de tipo social, es pol\u00edtica, es econ\u00f3mica, es racial, es cultural, y en los sitios donde hay castas, de castas. Hay una base discriminatoria que est\u00e1 en su apogeo y creo que es un momento grave de relaciones de poder muy desiguales y muy injustas que veo con mucha preocupaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>IPS: En este momento que describe, hay resistencia de grupos de poblaci\u00f3n, j\u00f3venes, feminista, ind\u00edgenas, pero es dif\u00edcil articular una respuesta como se ve en Per\u00fa y otros pa\u00edses latinoamericanos. \u00bfEs este un gran desaf\u00edo?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">GA: Vivimos una \u00e9poca altamente conflictiva, no es que estemos siendo arrasados por una derecha sin resistencia. No. Estamos en una \u00e9poca abiertamente conflictiva entre sectores pol\u00edticos, sectores econ\u00f3micos, sectores sociales y hay una resistencia muy interesante. Y estoy pensando planetariamente, m\u00e1s globalmente desde el Comit\u00e9, no solo desde lo que pasa en Per\u00fa. Las crisis ambientales est\u00e1n grav\u00edsimas y la covid tiene que ver con eso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No es una epidemia que se puede desconectar de lo que ha sido la agresividad humana contra la naturaleza. Las crisis ambientales se han acelerado en el siglo veinte por el modelo de industrializaci\u00f3n, de producci\u00f3n y de desarrollo econ\u00f3mico. Ahora est\u00e1n tratando de poner la reversa (marcha de retroceso), pero los acuerdos mundiales no son f\u00e1ciles y no dan r\u00e1pido los frutos que se quisiera porque hay unos intereses econ\u00f3micos atr\u00e1s, enormes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Que est\u00e1n dispuestos a matar al planeta! Dicen: \u2018Total qu\u00e9 importa, dentro de treinta a\u00f1os nosotros no vamos a estar ac\u00e1\u2019. As\u00ed, de un pragmatismo atroz. Y dentro de esos conflictos ambientales a las mujeres nos toca la peor parte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En segundo lugar est\u00e1 la conflictividad social que se produce dentro y fuera de estas circunstancias. Y hay un ambiente de conflictividad, yo digo violenta, armada, en diferentes partes del mundo y tiene que ver con esta locura de producci\u00f3n de armas, porque este es un modelo b\u00e9lico-econ\u00f3mico que produce y vende armas a diestra y siniestra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y los grandes pa\u00edses, incluso aquellos que parecen muy dem\u00f3cratas y progresistas \u2013y lo digo porque lo veo en el Comit\u00e9- son grandes productores de armas y las venden a pa\u00edses que justamente tienen conflictos y eso repercute en la vida de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(Acosta explica que el Comit\u00e9 abordar\u00e1 este problema con los pa\u00edses productores de armas y espera un crecimiento del movimiento de resistencia. \u2018El problema que encuentro es que esta perversidad en la econom\u00eda lamentablemente est\u00e1 vinculada a un dominio en medios masivos y con una tecnolog\u00eda de primer nivel. Y creo que esos elementos que son m\u00e1s macro, tienen que entrar en los an\u00e1lisis sobre los temas de las mujeres\u2019).<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2021\/12\/presidenta-cedaw-02.jpg\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2021\/12\/presidenta-cedaw-02-1024x768.jpg\" alt=\"\" class=\"wp-image-43356\"\/><\/a><figcaption>Gladys Acosta sentada en el malec\u00f3n de Lima, tras un a\u00f1o intenso como presidenta del Comit\u00e9 de la CEDAW, conformado por 23 expertas\/os independientes que vigilan el cumplimiento de la Convenci\u00f3n contra toda discriminaci\u00f3n de las mujeres. Foto: Mariela Jara \/ IPS<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>IPS: Las ecofeministas alertan del riesgo de la sostenibilidad de la vida, los pueblos ind\u00edgenas advierten de la amenaza a la naturaleza mientras se tenga Estados d\u00e9biles o c\u00f3mplices. \u00bfDesde el Comit\u00e9 c\u00f3mo aportan en esta reflexi\u00f3n?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">GA: En primer lugar, todav\u00eda existen los Estados. Si bien el poder econ\u00f3mico de las transnacionales es enorme, ese es el \u00e1mbito donde nosotros nos movemos, discutimos con los Estados parte que en esta Convenci\u00f3n son 189 en una din\u00e1mica interesante de presi\u00f3n para respetar los est\u00e1ndares internacionales de los derechos humanos, dentro de los cuales son muy importantes los est\u00e1ndares internacionales de protecci\u00f3n de los derechos de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los derechos de las mujeres tienen una conexi\u00f3n enorme con lo de la sostenibilidad de la vida, pero no desde una mirada esencialista. Trajiste a colaci\u00f3n lo de los pueblos ind\u00edgenas y me parece que en muchos sentidos nosotros estamos discutiendo una recomendaci\u00f3n general sobre los derechos de las mujeres y las ni\u00f1as ind\u00edgenas. Hay una sabidur\u00eda ancestral ind\u00edgena y sobre todo la de las mujeres, que deben ser protegidos en un sentido m\u00e1s efectivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay un conocimiento enorme sobre la naturaleza, la alimentaci\u00f3n, la semilla y la reproducci\u00f3n de las semillas; un conocimiento sobre c\u00f3mo est\u00e1 sufriendo la naturaleza, le conocen los s\u00edntomas a este sufrimiento y c\u00f3mo podr\u00edamos hacer de otra forma. Es un saber que ha sido transmitido ancestralmente y que por suerte todav\u00eda existe y hay que protegerlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>IPS: En otra entrevista con IPS, en 2009, cuando era representante regional de la organizaci\u00f3n predecesora de ONU Mujeres, dijo que las pol\u00edticas no deb\u00edan ver a las mujeres como sector vulnerable, \u00bfcree que ha habido avances en esa visi\u00f3n calificada de paternalista?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">GA: Dir\u00eda que hay las dos cosas. Me parece que la calidad de la movilizaci\u00f3n de hoy en el mundo a favor de los derechos de las mujeres es much\u00edsimo m\u00e1s potente, amplia y m\u00e1s pol\u00edtica. Creo que en los Estados uno encuentra de todo, pol\u00edticas de igualdad que han sido muy positivas y que han abierto camino para que las mujeres tengan m\u00e1s respetados sus derechos y accedan a la educaci\u00f3n, la universidad, al trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inclusive dir\u00eda que el tema de la paridad ha avanzado pese a que tambi\u00e9n est\u00e1 apareciendo algo que a m\u00ed me preocupa, que es como un aprovechamiento de sectores muy retr\u00f3grados que se montan sobre el asunto y lo quieren hacer suyo cuando en realidad lo \u00fanico que buscan es m\u00e1s poder para s\u00ed mismos. Las mujeres terminan siendo nada m\u00e1s que unos elementos decorativos dentro de su postura pol\u00edtica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(Acosta destaca en este contexto &nbsp;el surgimiento de movimientos m\u00e1s j\u00f3venes, de ni\u00f1os y ni\u00f1as que reclaman m\u00e1s poder, y que tienen m\u00e1s visi\u00f3n sobre hacia d\u00f3nde hay que caminar que la gente adulta y mayor, a los que tiene confianza, aunque aclara que se refiere a los que tienen \u2018una posici\u00f3n cr\u00edtica\u2019).<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No soy por eso pesimista del futuro. Soy muy cr\u00edtica y pesimista de lo que existe hoy, pero no pienso que esto siga igual. Por eso digo que estamos llegando al l\u00edmite de una era que da sus alaridos de muerte porque el nivel de injusticia en el mundo no se puede quedar as\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto va a explotar y ojal\u00e1 que sea lo menos da\u00f1ino para las personas. Pero s\u00e9 que la conflictividad no se queda como est\u00e1 ahora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>ED: EG<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este art\u00edculo es parte de la cobertura de IPS sobre los 16 d\u00edas de activismo contra la violencia hacia las mujeres, iniciados el 25 de noviembre, D\u00eda Internacional de la Eliminaci\u00f3n de la Violencia contra la Mujer, y que concluyen el 10 de diciembre, D\u00eda de los Derechos Humanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEl nivel de injustica que hay en el mundo no se puede quedar as\u00ed, no soy pesimista del futuro\u201d expresa la presidenta del Comit\u00e9 de la CEDAW, Gladys Acosta,  en una entrevista con IPS en la capital peruana.<\/p>\n","protected":false},"author":3,"featured_media":43355,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[692,54],"tags":[],"class_list":["post-43354","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/43354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=43354"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/43354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/43355"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=43354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=43354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=43354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}