{"id":41745,"date":"2021-11-08T11:07:21","date_gmt":"2021-11-08T17:07:21","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=41745"},"modified":"2023-07-21T18:51:45","modified_gmt":"2023-07-21T23:51:45","slug":"desobedienciapor-zorrasigues-tu","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/desobedienciapor-zorrasigues-tu\/","title":{"rendered":"Desobediencia|Por zorra\u2026sigues t\u00fa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Olimpia Flores Ortiz<br>SemM\u00e9xico, 8 de noviembre, 2021.- La banalizaci\u00f3n del feminicidio que la banalidad social produce ante la banalizaci\u00f3n del espect\u00e1culo total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En estos d\u00edas recientes de muertos y halloween, tuvimos las im\u00e1genes de la ambientaci\u00f3n en un boliche con bolsas de pl\u00e1stico negras y grandes, simulando envolver un cad\u00e1ver de mujer al que le colocaron el letrero: \u201cPOR ZORRA\u201d; en un espejo del sal\u00f3n se pod\u00eda leer tambi\u00e9n \u201c\u00a1Sigues t\u00fa!!\u201d. Esa era la ambientaci\u00f3n del sitio para un evento festivo, el \u201cWizzard Fest\u201d en Culiac\u00e1n, Sinaloa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante las reacciones airadas y en algunos casos violentas y amenazantes que corrieron por las redes, la empresa responsable \u201cMC Dise\u00f1a Eventos\u201d emiti\u00f3 disculpa p\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La an\u00e9cdota no parece sostenerse en la maliciosa intenci\u00f3n que se oculta tras la provocaci\u00f3n de una acci\u00f3n pol\u00edticamente incorrecta. En este caso es pura banalidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entendamos \u201cbanalidad\u201d como la resolvi\u00f3 Hanna Arendt a prop\u00f3sito del juicio a Eichman, el nazi jud\u00edo apresado en Argentina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La monstruosidad humana no es excepcional, todo \u201cbuen ciudadano\u201d que viva en paz con sus vecinos y pague sus impuestos puntualmente, puede cometer actos monstruosos tan despreocupadamente restando el horror a lo horrible.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2021\/11\/Screenshot_20211110-105233_Office.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"918\" height=\"514\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2021\/11\/Screenshot_20211110-105233_Office.jpg\" alt=\"\" class=\"wp-image-41841\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La infinita sucesi\u00f3n de las im\u00e1genes del horror, en la era del espect\u00e1culo digital, tambi\u00e9n banalizan al mal. Es cotidiano, es frecuente, es normalizado; cruza sucesivamente delante de nuestros ojos diluy\u00e9ndose el horror de su contenido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya no hay registro \u00e9tico ante la proliferaci\u00f3n de im\u00e1genes.<br>El infinito torrente de im\u00e1genes que circula por las redes sociales, su repetici\u00f3n parece que las despoja de sentido. Nadie puede consumir tanto contenido. Las im\u00e1genes dejan de representar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para Guy Debord, fil\u00f3sofo, escritor y cineasta franc\u00e9s de la posguerra, en su libro La Sociedad del Espect\u00e1culo , sostiene que \u00e9ste en s\u00ed, es una negaci\u00f3n de la revoluci\u00f3n. Es un distractor que no deja ver lo importante obturando la posibilidad de cambio. El espect\u00e1culo al cabo nos reconcilia con el sistema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sociedad espectadora es irremediablemente pasiva ante la inconsistencia de los relatos de las redes, que inconexos entre s\u00ed, no configuran un relato y no producen una comunidad de reacci\u00f3n, porque no hay tal comunidad y por tanto tampoco manera de reconfigurar en t\u00e9rminos del argelino Ranci\u00e8re \u201cla experiencia com\u00fan de lo sensible\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta situaci\u00f3n en la que no se trata de un relato ni de una falta absoluta del mismo, \u201cEl espectador permanece ante una apariencia, ignorando el proceso de producci\u00f3n de esa apariencia o la realidad que ella recubre\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSer espectador es estar separado al mismo tiempo de la capacidad de conocer y de poder actuar.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La percepci\u00f3n pol\u00edtica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bordieu dice respecto de una fotograf\u00eda, que \u201cno es solamente recuperar las significaciones que proclama, es tambi\u00e9n descifrar el excedente de significaci\u00f3n que revela, en la medida que participa de la simb\u00f3lica de una \u00e9poca, de una clase o de un grupo art\u00edstico.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese excedente de significaci\u00f3n proviene m\u00e1s bien de la apreciaci\u00f3n est\u00e9tica. Para Ranci\u00e8re, \u201cla est\u00e9tica es un r\u00e9gimen de pensamiento liberador dentro del cual son cuestionadas las jerarqu\u00edas establecidas: comprensi\u00f3n y sensibilidad, imagen y palabra, abstracci\u00f3n y representaci\u00f3n, arte y vida\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de una imagen intolerable, Ranci\u00e8re, encuentra que su efecto pol\u00edtico no existe sin unos supuestos previos que lleven al espectador a conmoverse porque detenta un juicio producto de un pensamiento cr\u00edtico y no puede desprenderse de la responsabilidad que le implica formar parte el sistema que genera los horrores. Pero porque sabe, es sensible a lo irrepresentable en la imagen que es el horror en s\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Efectos de las im\u00e1genes en las redes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la perspectiva de las, los, les usuaries extraviades en el laberinto de su presentismo que les impide tomar distancia, comprender causalidades y conectarlas, \u00bfse puede ubicar el relato-mensaje en la incesante observaci\u00f3n de infinidad de im\u00e1genes que proliferan sin una l\u00f3gica com\u00fan de sentido, porque surgen de sensaciones y expresiones dial\u00f3gicas individuales, cuyo efecto pol\u00edtico consiste precisamente en la ausencia de interpretaci\u00f3n y posici\u00f3n pol\u00edtica? La repetici\u00f3n de la imagen no transforma el pensamiento. Satura la percepci\u00f3n hasta neutralizarla. No hay nada m\u00e1s all\u00e1 de la imagen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La narraci\u00f3n es del orden de la permanencia, con horizonte hacia la eternidad; las redes lo son de lo ef\u00edmero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el pre\u00e1mbulo al libro de Ranci\u00e8re, Ane Bugnone rescata que la idea \u201ces trastornar la l\u00f3gica dominante que hace de lo visual la parte de las multitudes y de lo verbal el privilegio de unos pocos\u201d. \u00bfNo ser\u00e1 que la imagen y la palabra pueden ambas \u201coperar formas de redistribuci\u00f3n de los elementos de la representaci\u00f3n\u2026?\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A guisa de colof\u00f3n a prop\u00f3sito de la an\u00e9cdota<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me encuentro en mis indagaciones para este art\u00edculo a Deleuze diciendo que \u201ctenemos necesidad de una \u00e9tica y de una fe, lo cual hace re\u00edr a los idiotas. No es una necesidad de creer en otra cosa, sino una necesidad de creer en este mundo, del que los idiotas forman parte.\u201d Las idiotas del caso, tambi\u00e9n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">https:\/\/www.facebook.com\/OlimpiaFloresMirabilia<br>Twitter: @euphrasina (amor por la elocuencia)<br>TikTok Gentopia_mx (La t\u00eda de les muchaches)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olimpia Flores OrtizSemM\u00e9xico, 8 de noviembre, 2021.- La banalizaci\u00f3n del feminicidio que la banalidad social produce ante la banalizaci\u00f3n del espect\u00e1culo total. En estos d\u00edas recientes de muertos y halloween, tuvimos las im\u00e1genes de la ambientaci\u00f3n en un boliche con bolsas de pl\u00e1stico negras y grandes, simulando envolver un cad\u00e1ver de mujer al que le [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":41746,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[692,133,134,35],"tags":[],"class_list":["post-41745","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-desobediencia","category-olimpia-flores-ortiz","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/41745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=41745"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/41745\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/41746"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=41745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=41745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=41745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}