{"id":40683,"date":"2021-10-06T18:25:31","date_gmt":"2021-10-07T00:25:31","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=40683"},"modified":"2023-07-21T17:07:19","modified_gmt":"2023-07-21T22:07:19","slug":"tras-la-puerta-del-poder-el-pri-va-por-deslopezobradorizar-la-reforma-electrica","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/tras-la-puerta-del-poder-el-pri-va-por-deslopezobradorizar-la-reforma-electrica\/","title":{"rendered":"Tras la puerta del Poder| El PRI va por deslopezobradorizar la reforma el\u00e9ctrica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&nbsp;<strong>Roberto Vizca\u00edno<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 6 de octubre, 2021.- El l\u00edder nacional del PRI&nbsp;<strong>Alejandro Moreno<\/strong>&nbsp;y el coordinador de los diputados tricolores&nbsp;<strong>Rub\u00e9n Moreira<\/strong>&nbsp;saben que, con 71 legisladores<strong>, su bancada&nbsp;<\/strong>en<strong>&nbsp;San L\u00e1zaro<\/strong>&nbsp;es la \u00fanica que puede aprobar o rechazar la controvertida reforma el\u00e9ctrica de<strong>&nbsp;Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ellos saben que hoy tienen a sus pies a su excompa\u00f1ero pri\u00edsta poblano&nbsp;<strong>Ignacio Mier<\/strong>, hoy coordinador de Morena en esa c\u00e1mara, y al mism\u00edsimo&nbsp;<strong>Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En lo esencial, es cuesti\u00f3n de n\u00fameros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y es que, para aprobar esa reforma tan deseada y buscada por el tabasque\u00f1o, se requieren 334 votos a favor (2 terceras partes de 500). Pero Morena s\u00f3lo tiene 198 diputados, que m\u00e1s los 42 del Verde Ecologista y los 37 del PT, apenas llegan a 277.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les faltan 57.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El PAN, la segunda fuerza en San L\u00e1zaro tiene 114 pero este partido se opone radical y contundentemente a esa reforma por considerarla estatista, monop\u00f3lica, inconstitucional y contraria al libre mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El PRD tiene15 y MC 23 para sumar apenas 38 y que igual que el PAN han dicho que no dar\u00e1n ning\u00fan voto a favor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es as\u00ed que los \u00fanicos que pueden lograr la aprobaci\u00f3n de la El\u00e9ctrica de&nbsp;<strong>AMLO<\/strong>&nbsp;son los del PRI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con ese as en la mano,&nbsp;<strong>Moreira<\/strong>&nbsp;y&nbsp;<strong>Alito<\/strong>&nbsp;comenzaron a jugar ayer a las vencidas, a doblar y someter a&nbsp;<strong>AMLO<\/strong>&nbsp;y&nbsp;<strong>Mier<\/strong>. Y de entrada han dicho que ellos y su bancada no tienen prisa, que antes de llevar esa reforma a una votaci\u00f3n en el Pleno, van por realizar todos los foros abiertos que sean necesarios para escuchar a los enviados y representantes de&nbsp;<strong>L\u00f3pez Obrador,<\/strong>&nbsp;as\u00ed como a t\u00e9cnicos, cient\u00edficos, acad\u00e9micos, empresarios, inversionistas, sindicalistas de la CFE y otras empresas del sector, a pol\u00edticos, a la poblaci\u00f3n abierta y -en fin- a todos quienes quieran ser escuchados respecto de este tema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se declararon abiertos a un di\u00e1logo y an\u00e1lisis a fondo y adelantaron que creen que todo proyecto de reforma constitucional puede ser reorientado, modificado y perfeccionado en aras de hacerlo viable constitucional y socialmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso en estos foros y encuentros, negociaciones y deliberaciones, intentar\u00e1n&nbsp;<em>deslopezobradorizar<\/em>&nbsp;esta reforma para que realmente sea una garant\u00eda de impulso a energ\u00edas limpias, comercialmente accesibles para la poblaci\u00f3n y que no afecte la participaci\u00f3n de empresarios y capitales privados nacionales y extranjeros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poco despu\u00e9s&nbsp;<strong>Mier<\/strong>&nbsp;dir\u00eda que piensa que esta reforma ser\u00eda aprobada en San L\u00e1zaro entre el 15 de noviembre y 15 de diciembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NO POLARIZAR, PIDE MONREAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Senado ayer el debate se centr\u00f3 en la decisi\u00f3n de&nbsp;<strong>Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong>&nbsp;de no asistir a la entrega de la Medalla&nbsp;<strong>Belisario Dom\u00ednguez<\/strong>&nbsp;que en este a\u00f1o recay\u00f3 en la maestra&nbsp;<strong>Ifigenia Mart\u00ednez<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo porque la senadora&nbsp;<strong>Lilly T\u00e9llez<\/strong>, quien pas\u00f3 de aliada a abierta opositora, emiti\u00f3 un twitt en que adelantaba que enfrentar\u00eda al mandatario en ese evento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto,&nbsp;<strong>Ricardo Monreal<\/strong>, excoordinador de la senadora&nbsp;<strong>T\u00e9llez quien pertenec\u00eda a la bancada de Morena<\/strong>, pidi\u00f3 no extrapolar las cosas, no caer en especulaciones y respetar la decisi\u00f3n presidencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y, respecto a la reforma el\u00e9ctrica, adelant\u00f3 que apenas iniciar\u00eda conversaciones con los otros coordinadores a fin de comenzar una negociaci\u00f3n en caso de que los diputados la aprueben y entonces llegue al Senado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entretanto no hay nada que hacer, se\u00f1al\u00f3. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;.<a href=\"mailto:rvizcainoa@gmail.com\" target=\"_blank\" rel=\"noreferrer noopener\">rvizcainoa@gmail.com<\/a>&nbsp;\/ Twitter: @_Vizcaino \/ Facebook \/&nbsp;<a href=\"https:\/\/www.facebook.com\/rvizcainoa\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/rvizcainoa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El l\u00edder nacional del PRI\u00a0Alejandro Moreno\u00a0y el coordinador de los diputados tricolores\u00a0Rub\u00e9n Moreira\u00a0saben que, con 71 legisladores, su bancada\u00a0en\u00a0San L\u00e1zaro\u00a0<\/p>\n","protected":false},"author":3,"featured_media":39589,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[692,35,623,622],"tags":[459],"class_list":["post-40683","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-opinion","category-roberto-vizcaino","category-tras-la-puerta-del-poder","tag-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/40683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=40683"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/40683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/39589"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=40683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=40683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=40683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}