{"id":40130,"date":"2021-09-20T16:10:00","date_gmt":"2021-09-20T22:10:00","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=40130"},"modified":"2023-07-21T17:06:56","modified_gmt":"2023-07-21T22:06:56","slug":"denuncias-por-pornografia-infantil-acoso-y-pederastia-rompen-records-en-la-pandemia","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/denuncias-por-pornografia-infantil-acoso-y-pederastia-rompen-records-en-la-pandemia\/","title":{"rendered":"Denuncias por pornograf\u00eda infantil, acoso y pederastia rompen r\u00e9cords en la pandemia"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>En 2020, los reportes de pederastia crecieron casi 2 mil % y los de pornograf\u00eda infantil 272 % respecto a 2019, seg\u00fan la Guardia Nacional<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/la-lista.com\/autor\/alexis-ortiz\">Alexis Ortiz<\/a><\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/LaLista, Cd. de M\u00e9xico, 20 de septiembre, 2021.- Rezago educativo, afectaciones en su salud mental, violencia familiar, malnutrici\u00f3n, matrimonios forzados.&nbsp;La-Lista&nbsp;de posibles afectaciones que la pandemia del&nbsp;Covid-19&nbsp;ha dejado en los ni\u00f1os, ni\u00f1as y adolescentes es muy larga y no se limita a lo que este sector de la poblaci\u00f3n ha vivido en su entorno f\u00edsico, sino tambi\u00e9n en el digital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un informe de la Guardia Nacional obtenido por este medio a trav\u00e9s de una&nbsp;<a href=\"https:\/\/buscador.plataformadetransparencia.org.mx\/en\/buscadornacional?buscador=2800100084621&amp;coleccion=5\" target=\"_blank\" rel=\"noreferrer noopener\">solicitud de informaci\u00f3n<\/a>&nbsp;muestra que las denuncias ciudadanas por el delito en internet de&nbsp;pederastia&nbsp;crecieron 1,933 % en el 2020 respecto al 2019. En el mismo periodo de tiempo los reportes de&nbsp;pornograf\u00eda infantil&nbsp;aumentaron 272 % y los de&nbsp;acoso contra menores de edad&nbsp;en internet, 7 %.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El documento elaborado por la Direcci\u00f3n General Cient\u00edfica de la Guardia Nacional destaca que el a\u00f1o pasado, el primero de la pandemia, los&nbsp;delitos cibern\u00e9ticos contra menores de edad&nbsp;alcanzaron m\u00e1ximos hist\u00f3ricos que no se hab\u00edan visto desde el 2013, cuando la extinta Polic\u00eda Federal comenz\u00f3 a registrar denuncias ciudadanas por cr\u00edmenes cometidos en la web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de la pederastia, las&nbsp;denuncias ciudadanas&nbsp;pasaron de 15 en 2019 a 305 en 2020. En cuanto a la pornograf\u00eda infantil, hace dos a\u00f1os se registraron 121 casos y en 2020 fueron 451. El acoso contra menores de edad en internet es el crimen que menos creci\u00f3 en la pandemia, al pasar de 215 casos en 2019 a 232 el a\u00f1o pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No te pierdas:&nbsp;<a href=\"https:\/\/la-lista.com\/familia\/2021\/07\/05\/por-que-compartir-fotos-de-tus-hijos-sin-precauciones-los-pone-en-riesgo\">\u00bfPor qu\u00e9 compartir fotos de tus hijos sin precauciones los pone en riesgo?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eileen Matus Caballeros, doctora en Derecho y especialista en derechos humanos, atribuye el incremento de estos delitos a un&nbsp;mayor uso de la tecnolog\u00eda durante el confinamiento&nbsp;por la emergencia sanitaria. Las actividades educativas, laborales y recreativas pasaron al \u00e1mbito digital y los cr\u00edmenes no fueron la excepci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodos los delitos cibern\u00e9ticos aumentaron, aunque estos son de los m\u00e1s preocupantes porque tienen que ver con menores de edad\u201d, se\u00f1ala en entrevista la experta. \u201cSi todos est\u00e1n en casa y todos est\u00e1n conectados, todos&nbsp;empezamos a hacer en l\u00ednea lo que ya no pod\u00edamos hacer en persona, incluido la comisi\u00f3n de delitos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;Red por los Derechos de la Infancia (Redim)&nbsp;ya hab\u00eda alertado sobre este problema en su Balance Anual 2020, donde se\u00f1al\u00f3 que hasta mediados del 2020 ya se registraba un aumento preocupante en las denuncias ciudadanas por pornograf\u00eda infantil que la Guardia Nacional hab\u00eda recibido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa infancia y adolescencia se volvieron un blanco vulnerable ante la desprotecci\u00f3n del Estado que les abandon\u00f3 durante la pandemia\u201d, critic\u00f3 la Redim en su informe anual no solo por el crecimiento de la pornograf\u00eda infantil, sino porque tambi\u00e9n hubo un&nbsp;aumento en las carpetas de investigaci\u00f3n por homicidios, desapariciones y maltrato de ni\u00f1os, ni\u00f1as y adolescentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Matus Caballeros, tambi\u00e9n directora de la Maestr\u00eda en Derecho de la Escuela de Gobierno y Transformaci\u00f3n P\u00fablica del Tecnol\u00f3gico de Monterrey, a\u00f1ade que para el caso de la pornograf\u00eda infantil hay dos maneras en que esta se produce: \u201cPuede haber una&nbsp;c\u00e9lula dedicada a la pornograf\u00eda&nbsp;que tenga acceso a los menores y los pueda filmar directamente o puede haber casos en que, por medio del enga\u00f1o, los agresores le piden a los menores grabarse haci\u00e9ndose algo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;C\u00f3digo Penal Federal&nbsp;establece una&nbsp;pena de siete a 12 a\u00f1os de prisi\u00f3n por la pornograf\u00eda infantil. Este crimen es realizado por quien induzca a un menor de edad a realizar actos sexuales o de exhibicionismo corporal y que esto sea captado por una c\u00e1mara para despu\u00e9s distribuir los materiales. Las personas que almacenan y consumen este tipo de materiales tambi\u00e9n cometen este delito y la pena es la misma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No te pierdas:&nbsp;<a href=\"https:\/\/la-lista.com\/entretenimiento\/2021\/07\/27\/caeli-soy-la-mas-bulleada-por-yosstop-exhibe-acoso-a-otras-mujeres\">Caeli: \u2018Soy la m\u00e1s bulleada por YosStop\u2019; exhibe acoso a otras mujeres<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pederastia tambi\u00e9n est\u00e1 tipificada en el C\u00f3digo Penal Federal. El castigo por este crimen es de&nbsp;nueve a 18 a\u00f1os de prisi\u00f3n&nbsp;y la pena se agrava si se comete con violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este delito es cometido por quien aproveche una posici\u00f3n de superioridad frente a un menor de edad para convencerlo o ejecutar actos sexuales, con y sin su consentimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto al acoso de menores, ese es un delito tipificado por cada estado de la Rep\u00fablica. El caso de la Ciudad de M\u00e9xico, el acoso sexual a ni\u00f1os, ni\u00f1as y adolescentes se condena con&nbsp;dos a siete a\u00f1os de prisi\u00f3n&nbsp;y este il\u00edcito lo comete quien trate de abusar de un menor amenaz\u00e1ndolo con afectar la actividad que los vincula.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Acciones para combatirlos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las denuncias ciudadanas recibidas por la Guardia Nacional respecto a pornograf\u00eda infantil, pederastia y acoso contra menores se registraron pr\u00e1cticamente en todo el pa\u00eds. La&nbsp;Ciudad de M\u00e9xico&nbsp;y el&nbsp;Estado de M\u00e9xico&nbsp;encabezaron esa lista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los reportes ciudadanos que recaba la Guardia Nacional no son lo mismo que una denuncia interpuesta ante el ministerio p\u00fablico. El&nbsp;Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica (SESNSP)&nbsp;es la instituci\u00f3n que cada mes informa sobre el n\u00famero de carpetas de investigaci\u00f3n en el pa\u00eds, aunque no incluye los tres cr\u00edmenes que se abordan en este trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Matus Caballeros, la especialista del Tec de Monterrey, delinea varias acciones que las autoridades deben llevar a cabo para atender estos cr\u00edmenes, empezando por la coordinaci\u00f3n entre autoridades estatales y federales. El caso de la pornograf\u00eda infantil es el m\u00e1s claro, ya que este es un&nbsp;delito del fuero federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA m\u00ed siempre me ha quedado la duda, no solo en este tema, de la&nbsp;coordinaci\u00f3n entre autoridades federales y estatales, sobre todo porque se pierde en qu\u00e9 momento acaba el trabajo de una autoridad para que entre la otra\u201d, cuestiona la experta. \u201cComo algo que les da p\u00e1nico a las instituciones p\u00fablicas es la invasi\u00f3n de competencias, muchas veces levantan las manos y prefieren no hacer nada para no exceder sus facultades\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No te pierdas:&nbsp;<a href=\"https:\/\/la-lista.com\/mexico\/2021\/05\/31\/informe-revela-abuso-sexual-a-ninos-en-escuelas-de-siete-estados\">Informe revela abuso sexual a ni\u00f1os en escuelas de siete estados<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s all\u00e1 de la coordinaci\u00f3n entre autoridades, en opini\u00f3n de la experta no todo debe quedar en manos de las instituciones de gobierno, sino tambi\u00e9n de las&nbsp;empresas privadas que son propietarias de los equipos que las personas utilizan para cometer los delitos cibern\u00e9ticos&nbsp;y de las mismas familias de los menores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn la cuesti\u00f3n de&nbsp;educaci\u00f3n&nbsp;es bien importante que se le explique a los menores que existe ese riesgo (de que sean v\u00edctimas), aunque muchas veces existe el tab\u00fa de hablar de eso\u201d, concluye la especialista. \u201cLa coordinaci\u00f3n que debe haber entre el sector p\u00fablico, privado y social es alt\u00edsima\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM-LaLista\/ao<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 2020, los reportes de pederastia crecieron casi 2 mil % y los de pornograf\u00eda infantil 272 % respecto a 2019, seg\u00fan la Guardia Nacional<\/p>\n","protected":false},"author":3,"featured_media":40131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[692,51],"tags":[],"class_list":["post-40130","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/40130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=40130"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/40130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/40131"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=40130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=40130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=40130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}