{"id":38723,"date":"2021-07-06T11:25:00","date_gmt":"2021-07-06T17:25:00","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=38723"},"modified":"2023-07-21T17:03:33","modified_gmt":"2023-07-21T22:03:33","slug":"suman-2-mil-147-diabeticos-fallecidos-por-complicaciones-de-covid-19-en-michoacan","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/suman-2-mil-147-diabeticos-fallecidos-por-complicaciones-de-covid-19-en-michoacan\/","title":{"rendered":"Suman 2 mil 147 diab\u00e9ticos fallecidos por complicaciones de COVID-19 en Michoac\u00e1n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Redacci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Morelia, Michoac\u00e1n, a 6 de julio de 2021.- Para los pacientes con enfermedades cr\u00f3nico degenerativas como diabetes, obesidad e hipertensi\u00f3n, el COVID-19 puede ser mortal, debido a las complicaciones que se desarrollan al padecerlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De las 5 mil 875 defunciones registradas hasta el d\u00eda de hoy por este virus en la entidad, 2 mil 147 de los pacientes eran diab\u00e9ticos, mismos que perdieron la batalla contra la enfermedad pese a los esfuerzos del personal m\u00e9dico, y derivado de su comorbilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este tipo de padecimientos debilita el sistema inmune, m\u00e1s a\u00fan si no tienen sus niveles controlados, por lo que se complica la enfermedad al momento de contagiarse, existiendo un riesgo alto de perder la vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En relaci\u00f3n a las comorbilidades en casos confirmados por COVID-19, la diabetes ocupa la segunda posici\u00f3n con un registro de 10 mil 859 casos, lo que puede representar complicaciones graves a su salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En caso de tener diabetes u otra enfermedad como presi\u00f3n arterial alta y obesidad, la SSM recomienda llevar un estricto control de sus padecimientos, y seguir las medidas de cuidado que se han establecido para toda la poblaci\u00f3n, como son el distanciamiento social, el lavado frecuente de manos, uso de cubre bocas y gel antibacterial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n SemM\u00e9xico. Morelia, Michoac\u00e1n, a 6 de julio de 2021.- Para los pacientes con enfermedades cr\u00f3nico degenerativas como diabetes, obesidad e hipertensi\u00f3n, el COVID-19 puede ser mortal, debido a las complicaciones que se desarrollan al padecerlo. De las 5 mil 875 defunciones registradas hasta el d\u00eda de hoy por este virus en la entidad, 2 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":38724,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[692,51],"tags":[],"class_list":["post-38723","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/38723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=38723"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/38723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/38724"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=38723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=38723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=38723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}