{"id":38367,"date":"2021-07-19T14:16:04","date_gmt":"2021-07-19T20:16:04","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=38367"},"modified":"2023-07-21T17:04:39","modified_gmt":"2023-07-21T22:04:39","slug":"violeta-del-anahuac-mujeres-que-buscan-a-sus-hijs-por-isabel-ortega-morales","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/violeta-del-anahuac-mujeres-que-buscan-a-sus-hijs-por-isabel-ortega-morales\/","title":{"rendered":"\u00abMujeres que buscan a sus hij@s\u00bb"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">VIOLETA DEL AN\u00c1HUAC <\/span><\/p>\n<p><!--more--><\/p>\n<p><span style=\"font-weight: 400;\">Isabel Ortega Morales<\/span><\/p>\n<p><span style=\"font-weight: 400;\">SemM\u00e9xico, Tlapa, Guerrero, 19 de julio, 2021.- En M\u00e9xico, la pandemia por COVID-19 no ha parado el dolor que la desaparici\u00f3n de hijos e hijas causa. Y as\u00ed, las mujeres vuelven a colocarse en la l\u00ednea de resistencia para ir, contra su propio dolor, a enfrentar el camino que las conduzca a saber de sus hijas e hijos desaparecidos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En Guerrero un ejemplo de esa b\u00fasqueda la representan las Madres de los Normalistas desaparecidos la noche y madrugada del viernes y s\u00e1bado 26 y 27 de septiembre de 2014 en Iguala,&nbsp; Guerrero, que refiere una violencia sostenida a\u00fan en estos d\u00edas.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las mujeres-madres de los desaparecidos han tenido que enfrentar en estos largos meses y a\u00f1os, la dura carrera que han asumido para no permitir que baje el tema, se borre y desaparezca de la agenda del gobierno federal que pueda conducir a la no aparici\u00f3n de sus hijos, y al conocimiento de la verdad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En septiembre de 2020 acompa\u00f1e la marcha de los normalistas en Ciudad de M\u00e9xico, de grupos de la sociedad que se sumaron a la exigencia de la presentaci\u00f3n con vida de los estudiantes y ciudadanas y ciudadanos, pero sobre todo, de padres y madres que est\u00e1n de pie sorteando el tiempo en espera de encontrar con vida a sus hijos y para conocer en voz de ellos la verdad de lo sucedido.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero el silencio, que tambi\u00e9n habla, es la \u00fanica respuesta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La marcha, una enorme columna humana unida en un solo clamor, asum\u00eda con una empat\u00eda conmovedora la lucha. Los rostros de los padres, pero sobre todo de las madres parec\u00edan moldeadas en una sola expresi\u00f3n dolorosa, donde parece se ha instaurado la incertidumbre sobre el paradero de sus hijos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La periodista Libertad L\u00f3pez presenta en SemM\u00e9xico la historia de las mujeres buscadoras de sus hijos e hijas y el caso reciente del asesinato de Aranza Ramos, una de las mujeres que salieron a abrir fosas para buscar a sus hijos en escenas que son m\u00e1s duras por que representan la realidad.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En menos de tres meses se cumplir\u00e1n 7 a\u00f1os de la desaparici\u00f3n de los 43 estudiantes de la Normal Rural \u201cRa\u00fal Isidro Burgos\u201d de Ayotzinapa. Eso indica que ha pasado 82 meses buscando a sus hijos, resistiendo el dolor, buscando sobreponerlo para dar pasos m\u00e1s dif\u00edciles cada d\u00eda provocado por el mismo peso de la incertidumbre.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En la misma nota de SemM\u00e9xico cita Libertad L\u00f3pez una cifra por dem\u00e1s impactante \u00a180 mil desaparecidos!&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Algo tenemos que hacer como sociedad para restaurar el tejido social que ha marcado con dolor, luto, incertidumbre los d\u00edas y la geograf\u00eda del pa\u00eds. Omitir el compromiso es omitir la responsabilidad que tenemos como habitantes de \u00e9ste planeta cuidadoras de nuestros hijos e hijas como tambi\u00e9n de quienes no son por l\u00ednea consangu\u00ednea.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El Presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador ha se\u00f1alado que dentro de los 100 compromisos que asumi\u00f3 el d\u00eda de su mandato quedan dos pendientes: la descentralizaci\u00f3n del gobierno federal a las entidades del pa\u00eds, y la aparici\u00f3n de los 43 normalistas. En septiembre conoceremos sin duda los avances en los tres primeros a\u00f1os de su gobierno, aunque los padres y madres, a pesar de ser recibidos por el Mandatario, han se\u00f1alado pocos avances. Ojala logre impedir dentro de su pol\u00edtica de seguridad que estos temas sean parte de la historia del pa\u00eds y las mujeres dejen de ser buscadoras de sus hijos e hijas&nbsp; porque ellas y ellos, todos y todas nuestras hijas, est\u00e1n bien.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIOLETA DEL AN\u00c1HUAC<\/p>\n","protected":false},"author":3,"featured_media":38368,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[692,198,35,197],"tags":[476,530,531],"class_list":["post-38367","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-isabel-ortega-morales","category-opinion","category-violeta-del-anahuac","tag-isabel-ortega-morales","tag-oipinion","tag-violeta-del-anahuac"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/38367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=38367"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/38367\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/38368"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=38367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=38367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=38367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}