{"id":3706,"date":"2019-02-06T21:42:43","date_gmt":"2019-02-06T21:42:43","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=3706"},"modified":"2023-07-21T14:46:09","modified_gmt":"2023-07-21T19:46:09","slug":"cifras-optimistas-discurso-gastado-y-aplausos-del-personal-acarreado-dieron-la-nota","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/cifras-optimistas-discurso-gastado-y-aplausos-del-personal-acarreado-dieron-la-nota\/","title":{"rendered":"Cifras optimistas, discurso gastado y aplausos del personal \u201cacarreado\u201d dieron la nota."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.semmexico.com\/gallery-post.php?id=7105#\">Redacci\u00f3n<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Rodrigo Islas Brito<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Oaxaca. 6 febrero 2018.- La comparecencia del Fiscal General de Oaxaca, Rub\u00e9n Vasconcelos M\u00e9ndez ante la 64 legislatura termin\u00f3 en la falta de quorum parlamentario y la suspensi\u00f3n de toda la sesi\u00f3n. Descripci\u00f3n puntual de lo que fueron cerca de dos horas y media de aut\u00e9ntica tersidad entre diputadas, diputados y un Fiscal que en todo momento agradeci\u00f3 las preguntas y observaciones hechas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201dEl fiscal est\u00e1 agotado en su discurso. Habl\u00f3 lo que le dio la gana y no respondi\u00f3 a las preguntas. Todo pareci\u00f3 m\u00e1s bien un ejercicio de lavado y planchado de las dos partes. Parecen haber acuerdos o miedo de ir m\u00e1s all\u00e1. Eso es preocupante porque la ciudadan\u00eda, las v\u00edctimas secundarias, hoy estamos al garete\u201d, resumi\u00f3 al t\u00e9rmino de la suspendida comparecencia la periodista Soledad Jarqu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su hija Mar\u00eda del Sol Cruz Jarqu\u00edn fue asesinada por hombres armados hace casi nueve meses en Juchit\u00e1n, Oaxaca y hoy en la comparecencia el diputado y presidente de la mesa directiva del Congreso C\u00e9sar Morales Ni\u00f1o y la diputada Magaly L\u00f3pez Dom\u00ednguez le preguntaron a Vasconcelos sobre el avance de las investigaciones para encontrar a los responsables del crimen. Y el Fiscal emanado de un r\u00e9gimen estatal priista simplemente no respondi\u00f3 nada, ante una legislatura de enorme mayor\u00eda morenista, que le respondi\u00f3 que pod\u00eda mandar sus respuestas por escrito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algo contraria actitud parlamentaria a la manifestada la sesi\u00f3n ordinaria de la semana pasada cuando un grupo de diputadas y diputados morenistas se posesionaron en tribuna con pancartas condenando un clima feminicida en Oaxaca al que colectivos de mujeres vienen se\u00f1alando que va en auge con una alerta de g\u00e9nero que en el estado de Oaxaca ya se emiti\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl Fiscal nos va a tener que explicar muchas cosas\u201d dijeron entonces diputadas y diputados. Hoy el Fiscal en el Congreso Oaxaque\u00f1o no explic\u00f3 absolutamente nada. Con un sal\u00f3n de plenos poblado de madres de mujeres v\u00edctimas de feminicidio y ministerios p\u00fablicos, agentes investigadores, vicefiscales y secretar\u00edas adscritas a la propia Fiscal\u00eda, a la que la 64 legislatura pronunci\u00f3 recibir con gusto y apertura, Vasconcelos inici\u00f3 derecho y dijo que el suyo era un trabajo t\u00e9cnico y no pol\u00edtico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fij\u00f3 tres premisas: 1.- Las Fiscal\u00edas no previenen delitos, sino le dan respuesta, ni tienen como funci\u00f3n la seguridad ciudadana, sino el combate a la impunidad. 2.- A las Fiscal\u00edas no se les puede achacar el incremento de delitos, pero si se le puede reclamar el no dar respuestas (aunque m\u00e1s adelante en eso se lleg\u00f3 a contradecir. 3.- Para evaluar el trabajo de la Fiscal\u00eda se debe partir de indicadores objetivos, conocimiento de comportamiento criminal y an\u00e1lisis de los contextos, para conocer de fondo los problemas sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inspirado, el Fiscal sigui\u00f3 vehemente en la descripci\u00f3n de su versi\u00f3n del estado de las cosas. Describiendo a una Fiscal\u00eda que ha registrado un cambio total en sus t\u00e9cnicas de gesti\u00f3n, abatiendo el enorme rezago de averiguaciones prexistentes y d\u00e1ndole pelea al baj\u00edsimo nivel de casos determinados y resueltos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn la Fiscal\u00eda ninguna denuncia puede dejar de tener respuesta\u201d, dijo, anunciando la creaci\u00f3n de un Centro de Orientaci\u00f3n y Denuncia inmediata con funciones para discriminar los casos que se denuncian y canalizarlos a los \u00f3rganos de investigaci\u00f3n adecuados y 20 unidades existentes en todo el estado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de la creaci\u00f3n de la figura de 43 nuevos fiscales orientadores que en menos de 15 d\u00edas han dado respuesta hacia casi todas las denuncias presentadas, con una Centro de Justicia Alternativa donde los delitos que la ley permite resolver facilitando el dialogo entre los involucrados, se resuelven con la participaci\u00f3n de 356 facilitadores en todo el estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cContribuimos a la paz social y al acceso a la justicia\u201d, dijo el Fiscal con una porra de prestadores de justicia que en bola acudieron a las tribunas del edificio legislativo de San Raymundo Jalp\u00e1n a vitorear a su jefazo, que orgulloso afirmaba lo mucho que se ha avanzado en el n\u00famero de casos resueltos y en el combate a la impunidad de los delitos graves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lleg\u00f3 el tema que b\u00e1sicamente lo llev\u00f3 a comparecer ante la legislatura este cinco de febrero (a diferencia del resto del gabinete del gobernador Alejandro Murat Hinojosa que fue llamado a comparecer en pleno desde diciembre del 2018), los feminicidios en Oaxaca que hoy han llevado a que seg\u00fan informe presentado por el colectivo de derechos humanos Huaxyacac ante el Observatorio Nacional del Feminicidio, la entidad ocupe el segundo lugar en feminicidios, estimaci\u00f3n para la que se usaron criterios como la violencia obstetricia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como lo ha hecho desde el inicio de su gesti\u00f3n Vasconcelos diferenci\u00f3 entre feminicidios y lo que llam\u00f3: \u201chomicidios dolosos de mujeres\u201d. Dijo que en los \u00faltimos 18 meses se han registrado 45 sentencias condenatorias por feminicidios y homicidios dolosos de mujeres. Con 116 carpetas abiertas investigaci\u00f3n sobre casos de muertes violentas de mujeres. Asever\u00f3 que en 2018 fueron asesinadas en Oaxaca 127 mujeres, donde la existencia de los \u00fanicos 29 casos que la Fiscal\u00eda considera como feminicidios, significa que hoy Oaxaca est\u00e1 por debajo de la media nacional, que es de 49 feminicidios en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asegur\u00f3 que la Fiscal\u00eda tiene procesadas a 42 personas por feminicdios y homicidios de mujeres. A la pregunta que todo el mundo se hace sobre cuantos feminicidios se han resuelto encontrando a sus asesinos en Oaxaca, Vasconcelos celebr\u00f3 que la instituci\u00f3n a su cargo ha resuelto el 75 por ciento de los mismos. Obteniendo 104 \u00f3rdenes de aprehensi\u00f3n para feminicidas en la que el cumplimiento de su trabajo como Fiscal no ha obedecido ni a intereses pol\u00edticos, ni a presiones medi\u00e1ticas conducen el trabajo de la instituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de este resumen halag\u00fce\u00f1o de la impartici\u00f3n de justicia en Oaxaca, donde Vasconcelos dijo que Oaxaca es entidad campeona en resoluci\u00f3n de secuestros donde lo \u00fanico que le hace falta a la Fiscal\u00eda es la autorizaci\u00f3n de un mucho mayor presupuesto que permita la adquisici\u00f3n de veh\u00edculos, c\u00e1maras, drones, binomios y dem\u00e1s equipos t\u00e9cnicos, lleg\u00f3 el primer turno para los diputados y diputadas de hacer preguntas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elisa Zepeda de Morena pregunt\u00f3 sobre qu\u00e9 resultados ha tenido la fiscal\u00eda en delitos electorales, sobre cu\u00e1nto de su presupuesto total ha ido al combate de la violencia contra las mujeres, sobre cuantos agentes trabajan en eso y cuantos m\u00e1s se concentran en la investigaci\u00f3n de feminicidios, sobre lo cual la ciudadan\u00eda experimenta un profundo dolor en dilaci\u00f3n de casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Fiscal habl\u00f3 de 6651 horas de capacitaci\u00f3n sobre el tema para 1287 funcionarios p\u00fablicos y 26 carpetas por violencia pol\u00edtica de g\u00e9nero, donde siete est\u00e1n en tr\u00e1mite. Las dem\u00e1s respuestas a las preguntas las dej\u00f3 fuera porque eran demasiadas para tan poco tiempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diputada tambi\u00e9n morenista Magaly L\u00f3pez le pregunt\u00f3 entonces sobre el n\u00famero de expedientes por agravios a defensores de derechos humanos y periodistas y el citado caso del asesinato de Mar\u00eda del Sol Cruz Jarqu\u00edn, y el cuestionamiento sobre donde est\u00e1n el abogado defensor derechos humanos, Ernesto Serna, desaparecido desde mayo del 2018, y la activista de Morena Mar\u00eda Concha Rebollar, y su hija, Martha Rosa S\u00e1nchez Concha, desaparecidas desde enero de este a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante un Fiscal con ojo flam\u00edgero, el presidente de la mesa directiva, el petista Cesar Morales Ni\u00f1o le hace ver a los diputados que el acuerdo de la Junta de Coordinaci\u00f3n Pol\u00edtica para la comparecencia se limita a tres preguntas nada m\u00e1s, una pregunta por diputado o diputada, donde otra voz legislativa le dice al funcionario que si no puede responderlas todas, les puede mandar las respuestas por escrito. Vasconcelos M\u00e9ndez casi sonr\u00ede.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s no hablar\u00e1 de nada de lo que le preguntaron, ni de expedientes, ni de los casos de desaparici\u00f3n especificados. Dir\u00e1 que hoy a los imputados de delitos en Oaxaca se les ha hecho tomar cursos de derechos humanos, que 212 personas desaparecieron en Oaxaca en 2108 y que 205 fueron localizadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El morenista vicepresidente de la mesa directiva, Pavel Mel\u00e9ndez, le dice que nada m\u00e1s con las cifras presentadas ya es motivo para alarmarse, generalmente m\u00e1s frontal en sus intervenciones, el legislador se limita a decirle que en Oaxaca los feminicidios se han incrementado, sin tocar siquiera alguna posible contradicci\u00f3n en todo lo planteado por el funcionario. \u201cFalta algo que hacer en la Fiscal\u00eda\u201d, dice Pavel. El Fiscal le da las gracias por la observaci\u00f3n y vuelve a ignorar la pregunta sobre el caso del desaparecido Ernesto Serna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del avance sobre la resoluci\u00f3n de los 13 asesinados hace seis meses en Santa Mar\u00eda Ecatepec por conflictos de tierra, Vasconcelos aclara primero que los \u00edndices delictivos no son tarea de la dependencia a su cargo, sino en el n\u00famero de los casos resueltos, y que ya hay diversas \u00f3rdenes de aprehensi\u00f3n en proceso por la masacre. Precisa que \u00e9l no se re\u00fane con los abogados de las v\u00edctimas, sino con las mismas v\u00edctimas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los minutos se convierten en horas. La parsimonia envuelve a una comparecencia que hace por lo menos cinco d\u00edas amenazaba con ser vibrante. \u201c\u00bfPor qu\u00e9 est\u00e1 libre el asesino de Ivanna Mingo, lo protege el gobernador?, le pregunta el diputado petista Sa\u00fal Cruz sobre el caso de una mujer muerta cuyos familiares han poblado la grader\u00eda con pancartas con su nombre. \u201cLa ciudadan\u00eda no los baja de corruptos e incompetentes\u201d, le recuerda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHay casos que nos hemos atrevido a poner ante los jueces. Yo no hago las leyes. Ni soy juez\u201d, responde Vasconcelos. Su audiencia le aplaude. En los pasillos el t\u00edo de Ivanna Mingo habla con la prensa y comenta que en el caso del responsable la muerte de su sobrina, la familia considera que la Fiscal\u00eda lo hizo a lo menos deficiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asegura que hay pruebas de que en el accidente automovil\u00edstico en el que muri\u00f3, y de cuya responsabilidad el conductor sali\u00f3 literalmente caminando, a su sobrina la trataron de colocar al volante para que dijeran que ella manejaba, pero no pudieron porque muri\u00f3 prensada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El diputado de Encuentro Social, Fabricio D\u00edaz Alc\u00e1zar no tiene una pregunta para el Fiscal, pero si un comentario. \u201c\u00bfTodos los casos son graves, pero que pasa con los que no tienen acceso a la protesta?\u201d, dice D\u00edaz con cara a ver qui\u00e9n le responde. Habla de que todo los casos, aun el de Ivanna Mingo, se deben conducir por la sana vinculaci\u00f3n de procesos. Al final pide informaci\u00f3n sobre el caso de Heriberto Pazos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fiscal le da las gracias por la observaci\u00f3n e informa que con respecto al asesinato del fundador del MULT ya hay varios detenidos y se trabajan diferentes l\u00edneas de investigaci\u00f3n a sugerencia de la familia. La diputada del Verde Ecologista, Aurora L\u00f3pez Acevedo pasa a tribuna, y dice que ella m\u00e1s que una pregunta le quiere decir al Fiscal que es su amigo personal. Vasconcelos sonr\u00ede, se conmueve.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDelitos cometidos contra mujeres son prioridad para la Fiscal\u00eda\u201d, \u201cjudalizaci\u00f3n de todos los casos\u201d, \u201cnosotros si tenemos un plan y un proyecto para seguir avanzando en profesionalizaci\u00f3n de casos\u201d, \u201cninguna de las cifras que di es falsa\u201d, \u201ccon un poco m\u00e1s de recursos estar\u00edamos en la soluci\u00f3n de todos los casos y no s\u00f3lo del 75 por ciento\u201d, son algunas de las cosas que el Fiscal dir\u00e1 en una sesi\u00f3n que se hace eterna y en la que diputadas y diputados empiezan a desaparecer progresivamente de sus curules.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diputada panista Mar\u00eda de Jes\u00fas Mendoza S\u00e1nchez parece sacar fuerzas de su rebeld\u00eda que pidi\u00f3 la renuncia de por lo menos cinco integrantes del gabinete de Alejandro Murat en las comparecencias de diciembre pasado a las que Vasconcelos no fue convocado, y le dice al fiscal que si sabe que el feminicidio significa una \u201cforma de extrema violencia contra las mujeres por el solo hecho de ser mujer, con inherentes conductas de odio y rechazo hacia las mujeres\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le pregunta el c\u00f3mo considera el reciente asesinato de una profesora en Tuxtepec, violentada previamente por su asesino. \u201cFeminicidio\u201d, le responde el Fiscal, el golpe y la sorpresa terminan antes de empezar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El legislador Fabrizio D\u00edaz Alc\u00e1zar regresa a tribuna y comenta que la violencia contra la mujer en Oaxaca es un problema cultural y de educaci\u00f3n, que no est\u00e1 en las manos de la Fiscal\u00eda resolver. Dice que hay que ser sinceros con la gente en eso. Como no planeado corolario del momento el Fiscal Rub\u00e9n Vasconcelos M\u00e9ndez asegura estar de acuerdo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la mesa directiva, Morales Ni\u00f1o se da cuenta de que ya s\u00f3lo hay 20 diputadas y diputados presentes. \u201cYa no ha quorum, se suspende la sesi\u00f3n\u201d. Las porras del Fiscal, familiares de v\u00edctimas (que ya se han salido del sal\u00f3n de sesiones con pancartas dobladas en mano desde veinte minutos antes) y reporteros dan gracias por eso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alguien dice que tomando en cuenta lo duros y cuestionadores que fueron las y los 42 diputados con el resto del gabinete de Alejandro Murat en las comparecencias de diciembre, hoy pareciera que acabamos de asistir a una simulaci\u00f3n a la que debieron afinarle el guion en sus dosis de emoci\u00f3n. Al final la realidad es que hace ya mucho calor, en la comparecencia del Fiscal nadie ha dicho nada para que algo pase y el \u00e1nimo para el debate se ha ido con la esperanza de algo mejor.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n Rodrigo Islas Brito SemM\u00e9xico. Oaxaca. 6 febrero 2018.- La comparecencia del Fiscal General de Oaxaca, Rub\u00e9n Vasconcelos M\u00e9ndez ante la 64 legislatura termin\u00f3 en la falta de quorum parlamentario y la suspensi\u00f3n de toda la sesi\u00f3n. Descripci\u00f3n puntual de lo que fueron cerca de dos horas y media de aut\u00e9ntica tersidad entre diputadas, diputados [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3708,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,50],"tags":[],"class_list":["post-3706","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-congreso"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/3706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=3706"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/3706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/3708"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=3706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=3706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=3706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}