{"id":3609,"date":"2019-02-02T20:35:12","date_gmt":"2019-02-02T20:35:12","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=3609"},"modified":"2023-07-21T14:46:11","modified_gmt":"2023-07-21T19:46:11","slug":"5-75-de-los-municipios-417-municipios-que-se-rigen-por-ese-sistema","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/5-75-de-los-municipios-417-municipios-que-se-rigen-por-ese-sistema\/","title":{"rendered":"5.75 % de los municipios 417 municipios que se rigen por ese sistema."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.semmexico.com\/gallery-post.php?id=7299#\">Redacci\u00f3n<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 20 febrero 2019.-&nbsp;Una reforma a la Ley de Procedimientos Electorales del Estado de Oaxaca que busca la paridad entre mujeres y hombres en las elecciones locales que se rigen por sistemas normativos ind\u00edgenas, propuso hoy la diputada de Morena, Magaly L\u00f3pez Dom\u00ednguez, en la sesi\u00f3n del Congreso local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa con proyecto de decreto que reforma la Fracci\u00f3n XIX del Art\u00edculo 32 de la Ley de Instituciones y Procedimientos Electorales del Estado de Oaxaca, tiene como fin garantizar la paridad entre los hombres y las mujeres en las elecciones municipales por sistemas normativos ind\u00edgenas, se\u00f1ala la iniciativa que se basa en la normatividad internacional y nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Oaxaca es notable la poca presencia de mujeres como gobernantes en los 417 municipios que se rigen bajo sistemas normativos ind\u00edgenas, esto de acuerdo al informe que present\u00f3, en enero pasado, la Comisi\u00f3n de Sistemas Normativos Ind\u00edgenas del Instituto Estatal Electoral y de Participaci\u00f3n Ciudadana de Oaxaca basado en los resultados obtenidos en las elecciones ordinarias realizadas durante 2018 en municipios que se rigen por esos sistemas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese a\u00f1o fueron electas 145 mujeres para ocupar un cargo en los cabildos de su comunidad: 107 regidoras propietarias, 37 regidoras suplentes y una s\u00edndica suplente, de un total de 370 cargos propietarios y 165 suplentes sometidos a elecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto es, solamente 28 por ciento de los cargos propietarios son encabezados por mujeres. El fen\u00f3meno es m\u00e1s evidente en las presidencias municipales, donde es pr\u00e1cticamente nula la participaci\u00f3n femenina. De los 417 municipios regidos bajo sistemas normativos ind\u00edgenas, solamente 24 son encabezados por mujeres; esto es, 5.75 por ciento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La legisladora explic\u00f3 que varias disposiciones de esa ley establecen que los sistemas normativos ind\u00edgenas deben garantizar la participaci\u00f3n de las mujeres en condiciones de igualdad frente a los hombres, pero en las facultades del instituto electoral para validar ese tipo de elecciones, el criterio de igualdad aparece s\u00f3lo como una b\u00fasqueda que debe ser progresiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe trata de \u2018ponerle dientes\u2019 al IEEPCO para que pueda invalidar elecciones en las que no se garantiz\u00f3 la paridad\u201d, explic\u00f3 posteriormente la tambi\u00e9n presidenta de la Comisi\u00f3n Permanente de Derechos Humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Legisladora, quien tambi\u00e9n preside la Comisi\u00f3n Permanente de Derechos Humanos en la actual Legislatura, expuso que adem\u00e1s de reconocer y respetar la autodeterminaci\u00f3n de los pueblos ind\u00edgenas, los procesos electorales se deben desarrollar con apego a los derechos humanos, garantizando en todo momento la paridad entre hombres y mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas mujeres ind\u00edgenas necesitan tener el respaldo jur\u00eddico para poder participar en los procesos electorales de sus municipios, por ello la respuesta del Congreso del Estado para garantizar este derecho\u201d, recalc\u00f3 L\u00f3pez Dom\u00ednguez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00f3pez Dom\u00ednguez reconoci\u00f3 que gradualmente se ha avanzado en materia de participaci\u00f3n pol\u00edtica de las mujeres en los procesos electorales de las comunidades que se rigen por sistemas normativos ind\u00edgenas, pero advirti\u00f3 que es necesario acelerar el paso para lograr la garant\u00eda en el ejercicio de los derechos de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la sesi\u00f3n de este mi\u00e9rcoles, la iniciativa con proyecto de decreto que reforma la fracci\u00f3n XIX del art\u00edculo 32 de la Ley de Instituciones y Procedimientos Electorales del Estado de Oaxaca, con el fin de garantizar la paridad entre mujeres y hombres en las elecciones municipales por sistemas normativos ind\u00edgenas, fue turnada a comisiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n SemM\u00e9xico, Oaxaca, 20 febrero 2019.-&nbsp;Una reforma a la Ley de Procedimientos Electorales del Estado de Oaxaca que busca la paridad entre mujeres y hombres en las elecciones locales que se rigen por sistemas normativos ind\u00edgenas, propuso hoy la diputada de Morena, Magaly L\u00f3pez Dom\u00ednguez, en la sesi\u00f3n del Congreso local. La iniciativa con proyecto [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,50],"tags":[],"class_list":["post-3609","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-congreso"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/3609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=3609"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/3609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/3610"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=3609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=3609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=3609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}