{"id":3547,"date":"2017-09-18T19:47:07","date_gmt":"2017-09-18T19:47:07","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=3547"},"modified":"2023-07-21T14:25:14","modified_gmt":"2023-07-21T19:25:14","slug":"denuncian-organizaciones-oportunismo-politico-por-sismo","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/denuncian-organizaciones-oportunismo-politico-por-sismo\/","title":{"rendered":"Denuncian organizaciones oportunismo pol\u00edtico por sismo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Una respuesta inadecuada de los tres niveles de gobierno<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"> Falta coordinaci\u00f3n gubernamental en la distribuci\u00f3n de ayuda humanitaria<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/semmexico.com\/gallery-post.php?id=2975#\">Redacci\u00f3n<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Ciudad de M\u00e9xico, 18 septiembre 2017.- Tras el sismo del pasado 7 de septiembre, siete organizaciones expertas de la sociedad civil conformamos una Misi\u00f3n de Observaci\u00f3n de Ayuda Humanitaria (MOAH) que recorri\u00f3 la zona del Istmo de Tehuantepec en Oaxaca, atestiguando la falta de coordinaci\u00f3n gubernamental en la distribuci\u00f3n de la ayuda humanitaria y el uso discrecional de los escasos recursos que han llegado a la zona. En un comunicado de prensa, se\u00f1ala que MOAH llev\u00f3 a cabo labores de reconocimiento del 11 al 14 de septiembre en las comunidades de Ixhuat\u00e1n, Juchit\u00e1n de Zaragoza, Mat\u00edas Romero, R\u00edo Pachi\u00f1e, San Dionisio del Mar, Pueblo Nuevo (Agencia Municipal de San Francisco del Mar), San Mateo del Mar, Santa Mar\u00eda Xadani y Uni\u00f3n Hidalgo, afectadas por el sismo de magnitud 8.2. El objetivo fue vigilar que la ayuda humanitaria se entregue bajo los principios de imparcialidad, neutralidad, humanidad e independencia operacional que dictan los m\u00e1s altos est\u00e1ndares del derecho internacional humanitario. Los hallazgos m\u00e1s relevantes de la Misi\u00f3n de Observaci\u00f3n son: Existe una falta de coordinaci\u00f3n interinstitucional en todas las zonas de desastre y no se act\u00faa de manera pronta. En contraste, existe amplia presencia militar y de la polic\u00eda federal en las diferentes comunidades visitadas. La ayuda humanitaria que ha llegado es deficiente e insuficiente. Las necesidades b\u00e1sicas urgentes de las personas afectadas por el sismo como el derecho al agua, a la alimentaci\u00f3n y a la salud, entre otros, no han sido cubiertas. Adicionalmente, los esfuerzos de acopio y entrega de v\u00edveres desde la sociedad civil se han enfrentado a hostigamiento y, en algunos casos, el acopio ha sido decomisado. Los gobiernos federal y estatal han involucrado a diferentes instancias gubernamentales (como a las Secretar\u00edas de Energ\u00eda y de Turismo y a la Comisi\u00f3n Nacional Forestal) que no tienen ni la capacidad ni la experiencia en este tipo de desastres para realizar diagn\u00f3sticos de los inmuebles da\u00f1ados. Precandidatos y funcionarios p\u00fablicos, hombres y mujeres, han ca\u00eddo en el oportunismo al condicionar la ayuda humanitaria entreg\u00e1ndola \u00fanicamente a las personas cercanas al gobierno y los partidos pol\u00edticos, algunos incluso reetiquetan y recanalizan los v\u00edveres que llegan a la zona. Algunas empresas privadas est\u00e1n jugando un papel protag\u00f3nico en la respuesta, situaci\u00f3n que no deber\u00eda suplir las obligaciones del gobierno. Varias de estas empresas han tenido conflictos en algunas de estas comunidades por el desarrollo de megaproyectos y desconocemos si tienen las capacidades y el conocimiento para realizar las labores de respuesta bajo los m\u00e1s altos est\u00e1ndares del derecho internacional humanitario. Las organizaciones firmantes hacemos un llamado al gobierno federal para que atienda las siguientes recomendaciones: Todos los niveles de gobierno tienen la obligaci\u00f3n de proteger y garantizar los derechos humanos de todas las personas y colocarlos en el centro de los esfuerzos de atenci\u00f3n y respuesta, priorizando el derecho al agua y a un techo seguro para las personas afectadas por el sismo. La entrega de ayuda humanitaria debe reconocer las diferentes necesidades de la poblaci\u00f3n sin discriminaci\u00f3n alguna, incluyendo a mujeres, ni\u00f1as, ni\u00f1os, personas de la tercera edad y personas de origen ind\u00edgena. El gobierno federal debe iniciar las labores de reconstrucci\u00f3n en calidad de urgencia con un enfoque de prevenci\u00f3n de desastres. Proveer a las personas de un refugio digno debe ser una prioridad, de lo contrario, esto podr\u00eda provocar que la situaci\u00f3n se agrave a\u00fan m\u00e1s dado que la temporada de huracanes termina hasta noviembre. Los esfuerzos de reconstrucci\u00f3n deben contemplar la recuperaci\u00f3n de los medios de vida y la econom\u00eda local, ya que las personas afectadas no s\u00f3lo perdieron sus hogares sino tambi\u00e9n sus bienes materiales, sus negocios y sus fuentes de empleo. Esta situaci\u00f3n de crisis se suma a las condiciones preexistentes de exclusi\u00f3n, desigualdad y pobreza en las que se encontraban muchas personas y comunidades de la regi\u00f3n visitada. Por ello, la MOAH enfatiza que ante la grave situaci\u00f3n de desastre provocada por el sismo las personas afectadas son titulares de derechos, NO objetos de ayuda, y por ello su voz debe ser escuchada en primer lugar durante esta etapa de respuesta y la futura etapa de reconstrucci\u00f3n y recuperaci\u00f3n. Las organizaciones que conforman la Misi\u00f3n de Observaci\u00f3n de Ayuda Humanitaria son: El Centro de Derechos Humanos Tepeyac del Istmo de Tehuantepec, el Comit\u00e9 de Defensa Integral de Derechos Humanos Gobixha (Codigo DH), Oxfam M\u00e9xico, Proyecto sobre Organizaci\u00f3n, Desarrollo, Educaci\u00f3n e Investigaci\u00f3n (PODER), Proyecto de Derechos Econ\u00f3micos, Sociales y Culturales (ProDESC), Servicios para una Educaci\u00f3n Alternativa (Educa) y Tequio Jur\u00eddico. SEM\/sje\/lr<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una respuesta inadecuada de los tres niveles de gobierno Falta coordinaci\u00f3n gubernamental en la distribuci\u00f3n de ayuda humanitaria Redacci\u00f3n SemM\u00e9xico, Ciudad de M\u00e9xico, 18 septiembre 2017.- Tras el sismo del pasado 7 de septiembre, siete organizaciones expertas de la sociedad civil conformamos una Misi\u00f3n de Observaci\u00f3n de Ayuda Humanitaria (MOAH) que recorri\u00f3 la zona del [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[687,42],"tags":[],"class_list":["post-3547","post","type-post","status-publish","format-standard","has-post-thumbnail","category-687","category-sismos-y-reconstruccion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/3547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=3547"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/3547\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/3548"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=3547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=3547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=3547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}