{"id":34040,"date":"2021-04-06T14:41:10","date_gmt":"2021-04-06T20:41:10","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=34040"},"modified":"2023-07-21T16:57:10","modified_gmt":"2023-07-21T21:57:10","slug":"ine-seguira-aplicando-la-ley-aunque-algunos-las-confundan-con-sesgos-o-actitudes-parciales-lorenzo-cordova","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/ine-seguira-aplicando-la-ley-aunque-algunos-las-confundan-con-sesgos-o-actitudes-parciales-lorenzo-cordova\/","title":{"rendered":"INE seguir\u00e1 aplicando la ley, aunque algunos las confundan con sesgos o actitudes parciales: Lorenzo C\u00f3rdova"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Candelario Osorio Le\u00f3n\/xevt.com<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/Telereportaje- xevt.com. Cd. de M\u00e9xico. 06 de abril 2021.- El consejero presidente del Instituto Nacional Electoral (INE), Lorenzo C\u00f3rdova Vianello, advirti\u00f3 que seguir\u00e1n aplicando las leyes y garantizando la equidad y la imparcialidad en el proceso electoral, aunque algunos las confundan con sesgos o actitudes parciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la ceremonia del inicio de producci\u00f3n de las boletas para las elecciones de diputados federales, C\u00f3rdova, quien ha sido fuertemente criticado por Morena por cancelar el registro de cerca de 60 candidaturas, entre ellos la de F\u00e9lix Salgado Macedonio aspirante a la gubernatura de Guerrero por no presentar el informe de ingresos y gastos de precampa\u00f1a, insisti\u00f3 en que el INE es un organismo constitucional aut\u00f3nomo.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl INE no solo es organizador de los comicios sino el \u00e1rbitro de la contienda y aunque haya quienes confundan la aplicaci\u00f3n de ley con sesgos y actitudes parciales, lo cierto es que el \u00e1rbitro seguir\u00e1 aplicando las leyes y garantizamos la imparcialidad y la aplicaci\u00f3n de la ley. Haremos valer la Constituci\u00f3n, las leyes electorales y las normas y lineamientos aprobados en el seno del Consejo General\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, asent\u00f3 que la boleta electoral es una muestra fehaciente y palpable de que hoy en M\u00e9xico no tiene sentido hablar de fraude electoral y de pr\u00e1cticas que formaron parte de una \u00ablamentable picaresca pol\u00edtica afortunadamente superada\u00bb, como el rat\u00f3n loco, los padrones rasurados, los muertos que votan y las urnas embarazadas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLa boleta electoral en M\u00e9xico es uno de los documentos oficiales m\u00e1s seguros del pa\u00eds, cuentan con una serie de candados y dispositivos que la vuelven infalsificables, la boleta es una evidencia f\u00edsica de la evoluci\u00f3n de nuestra democracia y del perfeccionamiento de nuestro sistema electoral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El consejero presidente del Instituto Nacional Electoral (INE), Lorenzo C\u00f3rdova Vianello, advirti\u00f3 que seguir\u00e1n aplicando las leyes y garantizando la equidad y la imparcialidad en el proceso electoral<\/p>\n","protected":false},"author":3,"featured_media":34041,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[692,141],"tags":[],"class_list":["post-34040","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-elecciones-2020-2021"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/34040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=34040"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/34040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/34041"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=34040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=34040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=34040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}