{"id":33710,"date":"2021-03-26T16:41:33","date_gmt":"2021-03-26T22:41:33","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=33710"},"modified":"2023-07-21T16:54:41","modified_gmt":"2023-07-21T21:54:41","slug":"sin-respetar-el-informe-sobre-las-violencias-contra-las-mujeres-en-la-mananera","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/sin-respetar-el-informe-sobre-las-violencias-contra-las-mujeres-en-la-mananera\/","title":{"rendered":"Sin respetar el informe sobre las violencias contra las mujeres en la ma\u00f1anera"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por: Lizbeth \u00c1lvarez Mart\u00ednez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Cd. de M\u00e9xico. 26 de marzo de 2021.- El presidente Andr\u00e9s Manuel L\u00f3pez Obrador se comprometi\u00f3 desde el pasado 25 de noviembre del 2020 a dar un informe sobre las violencias, feminicidios y desapariciones de mujeres en las conferencias matutinas, mejor conocidas como las \u201cMa\u00f1aneras\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero el acuerdo no se ha respetado por parte del mandatario, siempre hay temas o giras m\u00e1s importantes que atender, que los temas de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la conferencia de este viernes en Palacio Nacional, volv\u00ed a cuestionar&nbsp;&nbsp;al mandatario sobre el informe del 25 de cada mes que no se ha dado, pero tambi\u00e9n sobre el discurso que dio el gobernador de Campeche, Carlos Miguel Aysa Gonz\u00e1lez, quien dijo con toda seguridad que en los \u00faltimos seis meses s\u00f3lo se ha registrado un feminicidio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La respuesta del Ejecutivo Federal fue r\u00e1pida para pasar a otros temas de mayor relevancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cS\u00ed, se va a seguir informando cada mes sobre este tema, es un compromiso que tenemos\u201d, as\u00ed lo dijo el mandatario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe destacar, que el 13 de enero de este a\u00f1o, el mandatario pas\u00f3 el informe del 25 al d\u00eda 27 porque la agenda estaba saturada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cS\u00ed, vamos a informar para el 25, como quedamos. Lo vamos a pasar para el mi\u00e9rcoles siguiente. Le vamos a pedir a la licenciada Olga S\u00e1nchez Cordero, Nadine (sic) y a Alejandro Encinas que vengan a informar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con informaci\u00f3n del Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica (SESNSP), en M\u00e9xico hubo 70 feminicidios en febrero. El Estado de M\u00e9xico encabez\u00f3 la lista con 26 casos, 14 m\u00e1s que el mes anterior; seguido por Veracruz con 14; Chiapas con 9, Jalisco 8 y Morelos, Nuevo Le\u00f3n y Sinaloa con 7 casos cada uno.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"416\" style=\"aspect-ratio: 848 \/ 416;\" width=\"848\" controls src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2021\/03\/WhatsApp-Video-2021-03-26-at-11.01.13-AM.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por: Lizbeth \u00c1lvarez Mart\u00ednez. SemM\u00e9xico. Cd. de M\u00e9xico. 26 de marzo de 2021.- El presidente Andr\u00e9s Manuel L\u00f3pez Obrador se comprometi\u00f3 desde el pasado 25 de noviembre del 2020 a dar un informe sobre las violencias, feminicidios y desapariciones de mujeres en las conferencias matutinas, mejor conocidas como las \u201cMa\u00f1aneras\u201d. Pero el acuerdo no se [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":33712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[692,51,1],"tags":[],"class_list":["post-33710","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-ejecutivo","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/33710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=33710"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/33710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/33712"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=33710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=33710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=33710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}