{"id":33031,"date":"2021-03-10T17:59:59","date_gmt":"2021-03-10T17:59:59","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=33031"},"modified":"2023-07-21T16:51:49","modified_gmt":"2023-07-21T21:51:49","slug":"el-mayor-castigo-la-condena-publica-dice-amlo-por-violencia-del-8m","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/el-mayor-castigo-la-condena-publica-dice-amlo-por-violencia-del-8m\/","title":{"rendered":"El mayor castigo, la condena p\u00fablica, dice AMLO por violencia del #8M"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u2022<strong> Se\u00f1ala que no \u201cperseguir\u00e1n\u201d a nadie, porque encima de todo van a sentirse v\u00edctimas\u201d<br>\u2022 Tras la intervenci\u00f3n feminista iba a dejar una semana la valla, pero decidi\u00f3 retirarla por violencia en la manifestaci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lizbeth \u00c1lvarez Mart\u00ednez<\/strong><br>SemM\u00e9xico, Cd. de M\u00e9xico, 10 de marzo, 2021.- El presidente Andr\u00e9s Manuel L\u00f3pez Obrador asegur\u00f3 que el mayor castigo para quienes realizaron actos de violencia debe ser la condena p\u00fablica y pidi\u00f3 no castigar ni perseguir a quienes realizaron actos de violencia durante las manifestaciones por el D\u00eda internacional de la Mujer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la conferencia matutina de este mi\u00e9rcoles, se\u00f1al\u00f3 que su opini\u00f3n es no perseguir a nadie, \u201cporque encima de todo van a sentirse v\u00edctimas. No debe de haber ning\u00fan castigo, yo creo que el castigo en este caso es la condena p\u00fablica por lo que hicieron, la gente no ve bien el uso de la violencia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00f3pez Obrador consider\u00f3 que \u201ces un contrasentido, la expresi\u00f3n m\u00e1s burda y terrible del machismo es la violencia, el machismo es violencia. \u00bfC\u00f3mo quienes est\u00e1n en contra del machismo ejercen la violencia?\u201d, cuestion\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComo que hace falta m\u00e1s an\u00e1lisis, m\u00e1s reflexi\u00f3n, porque s\u00ed hay millones de mujeres que defienden la causa de la igualdad y eso es v\u00e1lido, es legal, es leg\u00edtimo, es justo, pero hay mucha infiltraci\u00f3n, mucha manipulaci\u00f3n\u201d, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente mexicano se\u00f1al\u00f3 que es un humanista, expresi\u00f3n que lo engloba todo, y descart\u00f3 ser machista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSoy humanista, considero que eso lo engloba todo, el ser humanista es no permitir las injusticas, la discriminaci\u00f3n, no se puede ser humanista si se es machista\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ten\u00eda informaci\u00f3n, iban a quemar la puerta del palacio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, L\u00f3pez Obrador asegur\u00f3 que ten\u00eda informaci\u00f3n de que durante la manifestaci\u00f3n por el D\u00eda Internacional de la Mujer se ten\u00eda pensado quemar la puerta de Palacio Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTen\u00eda informaci\u00f3n, es mi trabajo. No tengo grupos de espionaje, pero s\u00ed hay inteligencia, lo que me dice la gente, ah\u00ed est\u00e1 inteligencia. Adem\u00e1s, lo que he aprendido a lo largo del tiempo, mi experiencia. Si no ponemos el muro pues ponemos frente a frente a los que protestan, infiltrados, con los de la polic\u00eda\u201d, expres\u00f3 durante la conferencia matutina de este mi\u00e9rcoles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ejecutivo Federal asegur\u00f3 que ten\u00eda pensado dejar una semana las vallas con los nombres de las v\u00edctimas de feminicidio, pero ante la violencia que se registr\u00f3 en la manifestaci\u00f3n por el #8M dio la indicaci\u00f3n de quitarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTen\u00eda pensado que se hace la manifestaci\u00f3n, est\u00e1 el muro con los nombres, las flores, entonces lo tenemos que dejar por respeto una semana. Es una causa muy justa de las mujeres y siempre las vamos a respetar. No les import\u00f3 nada, a destruir, ya para qu\u00e9 mantenemos el muro. Di la instrucci\u00f3n que lo quiten\u201d, dijo el mandatario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe recordar, que el lunes 8 de marzo en su tradicional conferencia, el presidente dijo que le hab\u00eda gustado la intervenci\u00f3n que realizaron las mujeres en las vallas: \u201cme gust\u00f3 mucho. Es una manera de expresar un sentimiento y al mismo tiempo una protesta. Es muy v\u00e1lido\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/lam\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se\u00f1ala que no \u201cperseguir\u00e1n\u201d a nadie, porque encima de todo van a sentirse v\u00edctimas<\/p>\n","protected":false},"author":3,"featured_media":33032,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[692,51],"tags":[],"class_list":["post-33031","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/33031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=33031"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/33031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/33032"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=33031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=33031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=33031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}