{"id":3299,"date":"2019-03-27T17:28:27","date_gmt":"2019-03-27T17:28:27","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=3299"},"modified":"2023-07-21T14:47:44","modified_gmt":"2023-07-21T19:47:44","slug":"debemos-de-ver-la-perspectiva-de-los-derechos-de-las-personas-adultas-mayores-desde-un-punto-de-vista-de-los-derechos-humanos-y-no-del-asistencialismo-social","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/debemos-de-ver-la-perspectiva-de-los-derechos-de-las-personas-adultas-mayores-desde-un-punto-de-vista-de-los-derechos-humanos-y-no-del-asistencialismo-social\/","title":{"rendered":"Debemos de ver la perspectiva de los derechos de las personas adultas mayores, desde un punto de vista de los derechos humanos y no del asistencialismo social."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.semmexico.com\/gallery-post.php?id=7717#\">Redacci\u00f3n<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/Billie Parker Noticias. Xalapa, Ver.- 27 de marzo de 2019.- En el marco de la conmemoraci\u00f3n del D\u00eda Internacional de la Mujer 2019 y de la Estrategia de Coordinaci\u00f3n Estatal Cero Tolerancia a la Violencia Contra las Mujeres y las Ni\u00f1as en Veracruz, se llev\u00f3 a cabo la Mesa de Trabajo para Impulsar las Reformas a la Ley Estatal de Derechos de las Personas Adultas Mayores, en las instalaciones del Palacio Legislativo, en la que participaron las diputadas M\u00f3nica Robles Barajas, Ana Miriam Ferr\u00e1ez Centeno y Monserrat Ortega Ruiz; adem\u00e1s de representantes de diversas organizaciones civiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Correspondi\u00f3, a la legisladora M\u00f3nica Robles Barajas, dar la bienvenida a todas y todos los participantes, quien se\u00f1al\u00f3 que el verdadero avance de una sociedad debe de estar fundada en el respeto a los derechos humanos de todas y de todos; agradeci\u00f3 la convocatoria para esta reuni\u00f3n de trabajo, y destac\u00f3 la importancia de permitirles ser facilitadores del trabajo que las organizaciones civiles han venido desempe\u00f1ando en este tema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tambi\u00e9n presidenta de la Comisi\u00f3n de Justicia y Puntos Constitucionales del Congreso del Estado, se comprometi\u00f3 a hacer viable las reformas necesarias, por la parte que les corresponde como integrantes de la LXV Legislatura estatal; para realizar la armonizaci\u00f3n de la Ley Estatal de Derechos de las Personas Adultas Mayores; as\u00ed como impulsar y apoyar la agenda que los organismos civiles tienen en este sentido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la diputada Ana Miriam Ferr\u00e1ez Centeno, dijo que se trata de que \u201cjuntos garanticemos los derechos de los adultos mayores. Porque en un estado de derecho es fundamental que lo previsto en la Constituci\u00f3n se cumpla a cabalidad, particularmente lo relacionado con los derechos humanos, previstos en su art\u00edculo 1\u00ba, que obliga a nuestro pa\u00eds y a las entidades federativas, a promoverlos, respetarlos, protegerlos y garantizarlos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ferr\u00e1ez Centeno, destac\u00f3 que es necesario que queden debidamente establecidas las obligaciones del estado de conformidad con la Constituci\u00f3n, y as\u00ed promover, proteger, garantizar y reconocer, bajo el principio de igualdad y no discriminaci\u00f3n, los derechos humanos y libertades fundamentales de los adultos mayores, adem\u00e1s dijo poder contribuir con ello a su plena inclusi\u00f3n, integraci\u00f3n y participaci\u00f3n en la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su participaci\u00f3n, la legisladora Monserrat Ortega Ruiz, apunt\u00f3 que est\u00e1 convencida de que debemos de ver la perspectiva de los derechos de las personas adultas mayores, desde un punto de vista de los derechos humanos y no del asistencialismo social. \u201cEstoy convencida que no es la d\u00e1diva lo que va a venir a solucionar, en todo, la problem\u00e1tica que estamos viviendo y los retos que tenemos enfrente, es decir, no estamos en contra de los apoyos econ\u00f3micos, sin embargo, en derechos humanos lo que se busca es la integraci\u00f3n\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior, porque todav\u00eda son personas social y laboralmente productivas, y a\u00f1adi\u00f3 que se tiene que garantizarles ser incorporadas en los campos productivos; que ellos deben participar en el dise\u00f1o de las pol\u00edticas p\u00fablicas que fomenten su inclusi\u00f3n, como en la planeaci\u00f3n de las mismas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n SemM\u00e9xico\/Billie Parker Noticias. Xalapa, Ver.- 27 de marzo de 2019.- En el marco de la conmemoraci\u00f3n del D\u00eda Internacional de la Mujer 2019 y de la Estrategia de Coordinaci\u00f3n Estatal Cero Tolerancia a la Violencia Contra las Mujeres y las Ni\u00f1as en Veracruz, se llev\u00f3 a cabo la Mesa de Trabajo para Impulsar las [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3301,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[690,50],"tags":[],"class_list":["post-3299","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-congreso"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/3299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=3299"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/3299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/3301"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=3299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=3299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=3299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}