{"id":32749,"date":"2021-03-06T22:56:47","date_gmt":"2021-03-06T22:56:47","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=32749"},"modified":"2023-07-21T16:51:55","modified_gmt":"2023-07-21T21:51:55","slug":"estamos-listas-con-o-sin-lopez-obrador","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/estamos-listas-con-o-sin-lopez-obrador\/","title":{"rendered":"Estamos listas con o sin L\u00f3pez Obrador"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li>Las mujeres no hemos dejado de dar una batalla pol\u00edtica sin precedente por la justicia social. Y tenemos que coordinarnos y organizarnos para poder lograr cambios necesarios sin el respaldo de Andr\u00e9s Manuel L\u00f3pez Obrador, quien no entiende la lucha feminista.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Por: <strong>Viri R\u00edos<\/strong>\/Columna Invitada<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/New York Times. CIUDAD DE M\u00c9XICO. 06 de marzo 2021.-  La historia de M\u00e9xico ha sido una de hombres. El poder pol\u00edtico y econ\u00f3mico ha estado dominado casi exclusivamente por ellos, al menos en los m\u00e1s altos puestos de influencia. Los saldos han sido terribles: sus decisiones nos han llevado a un pa\u00eds donde la desigualdad no cede y la pobreza tiene\u00a0<a href=\"https:\/\/www.coneval.org.mx\/Medicion\/Paginas\/Mujeres.aspx#:~:text=47.2%20millones%20de%20mexicanos%20viven,pero%20tiene%20un%20ingreso%20bajo.\" rel=\"noreferrer noopener\" target=\"_blank\">rostro de mujer<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este pa\u00eds, la pobreza por ingreso&nbsp;<a href=\"https:\/\/expansion.mx\/economia\/2019\/08\/06\/la-pobreza-por-ingresos-dana-mas-a-mujeres-e-indigenas\" rel=\"noreferrer noopener\" target=\"_blank\">aumenta entre las mujeres<\/a>&nbsp;a la par que disminuye entre los hombres. Y las personas&nbsp;<a href=\"https:\/\/www.forbes.com.mx\/listas-millonarios-2020-los-mas-ricos\/amp\/\" rel=\"noreferrer noopener\" target=\"_blank\">m\u00e1s ricas<\/a>&nbsp;son, casi todas, hombres o han heredado su fortuna de hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto no es coincidencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La econom\u00eda que los hombres moldearon est\u00e1 llena de privilegios para ellos. El m\u00e1s importante es el que se erige sobre el&nbsp;<a href=\"https:\/\/www.oxfammexico.org\/sites\/default\/files\/Trabajo%20de%20cuidados%20y%20desigualdad%20en%20Me%CC%81xico_OXFAM%20ME%CC%81XICO.pdf\" rel=\"noreferrer noopener\" target=\"_blank\">trabajo no pagado<\/a>&nbsp;de millones de mujeres que cuidamos ni\u00f1os y ancianos para que los hombres puedan trabajar por dinero o estudiar. Mi bisabuela no fue a la escuela para cuidar a su padre; mi abuela, para cuidar a sus hermanos, y mi madre fue a la escuela hasta que, un d\u00eda, tuvo que cuidarme a m\u00ed. Las mujeres somos v\u00edctimas de un gobierno y de una econom\u00eda hecha por los hombres para que los hombres tengan el dinero y las mujeres los ayuden a tenerlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Andr\u00e9s Manuel L\u00f3pez Obrador se convirti\u00f3 en presidente de M\u00e9xico en 2018 con la promesa de abanderar una lucha sin precedentes contra la injusticia social. Y muchas mujeres pensamos que esto significar\u00eda que luchar\u00eda por nosotras porque, si los pobres tienen que\u00a0<a href=\"https:\/\/www.bbc.com\/mundo\/noticias-america-latina-44680824\" rel=\"noreferrer noopener\" target=\"_blank\">ir primero<\/a>, como dec\u00eda en su campa\u00f1a, entonces las mujeres deber\u00edamos estar al frente de su agenda. No ha sido as\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una y otra vez el presidente de M\u00e9xico ha mostrado su insensibilidad (\u201c<a href=\"https:\/\/aristeguinoticias.com\/1802\/mexico\/ya-chole-dice-amlo-sobre-campana-contra-salgado-macedonio-enterate\/\" rel=\"noreferrer noopener\" target=\"_blank\">ya chole<\/a>\u201d) ante la lucha feminista y los reclamos m\u00e1s b\u00e1sicos de las mujeres. Pero el presidente ha fallado en escuchar nuestro mensaje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es momento de dar un vuelco. Las mujeres debemos dejar de gastar energ\u00eda tratando de convencer a L\u00f3pez Obrador de que nuestra causa es leg\u00edtima e importante. Sabemos que lo es. Tambi\u00e9n muchas mujeres de izquierda y pol\u00edticas de Morena, su partido, est\u00e1n perdiendo tiempo valioso en ello.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La terquedad de L\u00f3pez Obrador es insondable. As\u00ed que, para ser efectivas, la nuestra debe serlo a\u00fan m\u00e1s. Es momento de que las mujeres nos organicemos y abanderemos una lucha contra todas las injusticias. No solo contra las desigualdades que L\u00f3pez Obrador considera relevantes. Y si el presidente no lo entiende, es momento de tener nuevos l\u00edderes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si L\u00f3pez Obrador ha sido condescendiente con los reclamos de las mujeres, me permito lo mismo: la verdad es que \u00e9l no entiende qu\u00e9 es la lucha feminista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Considera que cancelar guarder\u00edas y usar el dinero para d\u00e1rselo a madres trabajadoras&nbsp;<a href=\"https:\/\/www.eluniversal.com.mx\/nacion\/politica\/no-somos-machistas-amlo-mi-gobierno-apoya-las-mujeres-dice\" rel=\"noreferrer noopener\" target=\"_blank\">es una pol\u00edtica feminista<\/a>&nbsp;porque as\u00ed las mujeres tienen m\u00e1s dinero. En vez de que se lo queden los administradores de guarder\u00edas, ahora queda directamente en manos de mujeres. Esa maniobra no es feminista porque no resuelve el problema que impide que las mujeres sean autosuficientes en un trabajo: la falta de estancias infantiles. Asume que el problema es falta de dinero cuando en realidad el problema es que no existen guarder\u00edas a precios accesibles. As\u00ed, los cuidados terminan siendo dejados en manos de otras mujeres o de las abuelas, perpetuando un sistema que depende de&nbsp;<a href=\"https:\/\/www.nytimes.com\/es\/2021\/02\/24\/espanol\/opinion\/argentina-trabajos-de-cuidado.html\">trabajo no pagado o pagado a medias<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se considera un l\u00edder a favor de las mujeres porque nombr\u00f3 a&nbsp;<a href=\"https:\/\/www.gob.mx\/segob\/prensa\/palabras-de-la-secretaria-olga-sanchez-cordero-en-el-informe-sobre-las-acciones-y-politicas-con-perspectiva-de-genero-del-gobierno-de-mexico\" rel=\"noreferrer noopener\" target=\"_blank\">m\u00e1s funcionarias<\/a>&nbsp;en su gabinete que otro gobierno de M\u00e9xico. Sin duda es un avance pero que no por ello esto se ha traducido en la creaci\u00f3n de mecanismos que impulsen la participaci\u00f3n pol\u00edtica de m\u00e1s mujeres o, incluso, de pol\u00edticas p\u00fablicas que nos beneficien. Por el contrario, algunas legisladoras de su partido se han dedicado a&nbsp;<a href=\"https:\/\/elpais.com\/mexico\/opinion\/2020-11-24\/legisladoras-machistas.html?outputType=amp\" rel=\"noreferrer noopener\" target=\"_blank\">mentir<\/a>&nbsp;sobre la cantidad de recursos que se asignan a programas de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y, peor a\u00fan, cree que los motivos de las mujeres para cuestionar la candidatura de alguien acusado de violaci\u00f3n, como en el caso de F\u00e9lix Salgado Macedonio a la gubernatura de Guerrero, son por oponerse a su ideolog\u00eda. Pero reclamar que un candidato se\u00f1alado por al menos cinco mujeres de abuso sexual no es una cuesti\u00f3n de derecha o izquierda, de conservadurismo o liberalismo; es una cuesti\u00f3n de m\u00ednima decencia humana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero L\u00f3pez Obrador no se inmuta. Cree que el movimiento feminista est\u00e1 equivocado porque se enfoca en buscar la paridad de g\u00e9nero cuando, como ha dejado ver, considera que la principal ra\u00edz de la pobreza y la desigualdad de M\u00e9xico no es la discriminaci\u00f3n hacia las mujeres, sino&nbsp;<a href=\"https:\/\/lopezobrador.org.mx\/2013\/06\/07\/mexico-vive-un-neoporfirismo-que-significa-el-predominio-del-prian-alerta-lopez-obrador\/\" rel=\"noreferrer noopener\" target=\"_blank\">la captura del Estado<\/a>&nbsp;por parte de las \u00e9lites econ\u00f3micas y sus secuaces. Y a\u00fan si L\u00f3pez Obrador tuviera raz\u00f3n, no se contrapone a la lucha de las mujeres para que la igualdad de g\u00e9nero sea una parte fundamental del resolver el problema de la pobreza en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con una&nbsp;<a href=\"https:\/\/www.nytimes.com\/es\/2021\/02\/01\/espanol\/opinion\/ricardo-anaya-amlo.html\">oposici\u00f3n tan debilitada<\/a>&nbsp;(pol\u00edtica y moralmente) y una sociedad civil a\u00fan en proceso de madurez, creo que las mujeres se est\u00e1n convirtiendo en su principal oposici\u00f3n, la m\u00e1s leg\u00edtima y la m\u00e1s visible. Y \u00e9l no tiene un plan para dar respuesta a sus demandas. Ha decidido&nbsp;<a href=\"https:\/\/elpais.com\/mexico\/2021-02-26\/el-74-de-los-mexicanos-cree-que-lopez-obrador-debe-oponerse-a-la-candidatura-de-salgado-macedonio.html\" rel=\"noreferrer noopener\" target=\"_blank\">ignorar a una mayor\u00eda de sus ciudadanos<\/a>&nbsp;a pesar de ser un presidente que se jacta de siempre escuchar al pueblo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El feminismo tiene una agenda transversal que las pol\u00edticas del presidente de M\u00e9xico no est\u00e1n abordando del todo y no quedar\u00e1n resueltas a menos de que se elimine la violencia f\u00edsica y econ\u00f3mica de la que son presa las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro enojo y frustraci\u00f3n debe convertirse en una organizaci\u00f3n pol\u00edtica que colonice todos los partidos pol\u00edticos para que incluyan una agenda de g\u00e9nero s\u00f3lida y sustentada en la realidad. El se\u00f1alamiento p\u00fablico de hombres que han cometido abusos sexuales es solo parte de una meta. El objetivo final debe ser modificar las fallas del sistema que hace que nuestra sociedad, y el Estado, dependa de que las mujeres tengamos cargas laborales injustas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como ha probado este gobierno, tampoco tener liderazgos femeninos basta para lograrlo. La batalla de las mujeres debe ser por la justicia social que nos han negado, para d\u00e1rsela a m\u00e1s personas y no para capturarla nosotras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Arriba debe haber mujeres que quieran crear una sociedad justa, con menos desigualdad y pobreza. Me emociona poder ver esto surgir.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><em>Viri R\u00edos (<a href=\"https:\/\/twitter.com\/Viri_Rios\" rel=\"noreferrer noopener\" target=\"_blank\">@Viri_Rios<\/a>) es analista pol\u00edtica y colaboradora regular en espa\u00f1ol de The New York Times.<\/em><\/strong><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Las mujeres no hemos dejado de dar una batalla pol\u00edtica sin precedente por la justicia social.<\/p>\n","protected":false},"author":3,"featured_media":32750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[692,205,110,35],"tags":[],"class_list":["post-32749","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-8-de-marzo","category-la-opinion-columnas","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/32749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=32749"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/32749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/32750"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=32749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=32749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=32749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}