{"id":31752,"date":"2021-02-12T00:25:00","date_gmt":"2021-02-12T00:25:00","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=31752"},"modified":"2023-07-21T16:48:12","modified_gmt":"2023-07-21T21:48:12","slug":"la-trampa-patriarcal-de-confrontar-a-las-mujeres","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/la-trampa-patriarcal-de-confrontar-a-las-mujeres\/","title":{"rendered":"La trampa patriarcal de confrontar a las mujeres"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\"><strong>Muriel Salinas D\u00edaz&nbsp;<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Guadalajara. 11 de febrero de 2021.- Tras las denuncias penales por presunta violaci\u00f3n sexual y otros delitos sexuales contra F\u00e9lix Salgado Macedonio, virtual candidato de MORENA a la gubernatura de Guerrero, y la subsecuente movilizaci\u00f3n del movimiento feminista local para exigir a este partido pol\u00edtico que retire dicha postulaci\u00f3n. MORENA opt\u00f3 por hacer o\u00eddos sordos y realizar una marcha de mujeres militantes de ese instituto pol\u00edtico en apoyo a F\u00e9lix Salgado Macedonio, con la intenci\u00f3n de deslegitimar las exigencias del movimiento feminista. Aunado a lo anterior, recientemente se public\u00f3 un pronunciamiento suscrito por mujeres militantes de este partido pol\u00edtico refrendando su apoyo a Salgado, arguyendo la presunci\u00f3n de inocencia. Ello a pesar de que mujeres feministas de MORENA publicasen un pronunciamiento exigiendo a su partido no postular a Salgado por estas denuncias de violencia sexual, y de que el movimiento feminista hiciera eco de ello a nivel nacional.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciertamente, un requisito para ser candidato o candidata a cualquier cargo de elecci\u00f3n popular es no haber sido sentenciado por cometer violencia sexual o familiar, por ser deudor alimentario o haber cometido violencia pol\u00edtica contra las mujeres en raz\u00f3n de g\u00e9nero. Y lo que nos devela una vez m\u00e1s el caso de F\u00e9lix Salgado, es el contexto de impunidad que prevalece en el pa\u00eds respecto de la violencia contra las mujeres. Pese a ello, el aspirante a la gubernatura de Guerrero va viento en popa rumbo a la candidatura, aunque est\u00e1 lejos de poder acreditar otro de los requisitos para ser candidato, que consiste en tener un modo honesto de vivir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quienes respaldan al Salgado Macedonio olvidan que, si una de las denuncias prescribi\u00f3, ha sido por la inacci\u00f3n del Estado, lo que configura una violaci\u00f3n a los derechos humanos de las mujeres digna de una denuncia ante la Corte Interamericana de los Derechos Humanos. El tema reside en el actuar de las autoridades judiciales para avanzar en la resoluci\u00f3n de las denuncias y procesos de investigaci\u00f3n que se encuentran abiertos contra Salgado, las cuales siguen sin avanzar pese a las presiones del movimiento feminista de todo el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La estrategia de confrontar a las mujeres para defender a un personaje pol\u00edtico impresentable no es nueva. En 2015, las y los opositores de la entonces Presidenta Municipal de M\u00e1rtir de Cuilapan, Felicitas Mu\u00f1iz G\u00f3mez, organizaron una conferencia de prensa encabezada por sus esposas y algunas regidoras del Ayuntamiento &#8211; quienes se hicieron acompa\u00f1ar por un grupo de mujeres ind\u00edgenas que nunca tomaron la palabra y se mantuvieron de pie detr\u00e1s de las voceras &#8211; para deslegitimar el anuncio que d\u00edas antes hab\u00eda hecho la Red para el Avance Pol\u00edtico de las Mujeres Guerrerenses de que apoyar\u00eda a la alcaldesa y encabezar\u00eda su defensa ante los tribunales, pues enfrentaba violencia pol\u00edtica en raz\u00f3n de g\u00e9nero. En esa conferencia de prensa, una de las regidoras acus\u00f3 una especie de incongruencia feminista de la Red por defender a la alcaldesa, victimizando a las mujeres ind\u00edgenas ah\u00ed presentes, y luego lanz\u00f3 una amenaza de muerte contra ella ante los medios de comunicaci\u00f3n. Finalmente, el TEPJF emiti\u00f3 entonces una sentencia que acredit\u00f3 violencia pol\u00edtica en raz\u00f3n de g\u00e9nero contra Mu\u00f1iz G\u00f3mez y vincul\u00f3 a las autoridades competentes a proceder penal y administrativamente contra las y los perpetradores por los m\u00faltiples delitos cometidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Divide y vencer\u00e1s es una frase de dudoso origen que le ha sido atribuida al dictador y emperador romano Julio C\u00e9sar. Es una pr\u00e1ctica recurrente en la vida pol\u00edtica, pero, sobre todo, ha sido una vieja estrategia de sello patriarcal y de uso recurrente para escindir a las mujeres e impedir su articulaci\u00f3n pol\u00edtica en defensa de sus propios derechos e intereses. Las manifestaciones de mujeres en defensa de F\u00e9lix Salgado Macedonio orquestadas desde MORENA, pretenden generar en la opini\u00f3n p\u00fablica la idea de que se ha generado una fractura en el movimiento feminista, que no existe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El feminismo es un pensamiento cient\u00edfico, filos\u00f3fico y pol\u00edtico con una tradici\u00f3n de m\u00e1s de tres siglos. El feminismo tiene un origen ilustrado y hoy es un movimiento global de gran alcance que encabeza una amplia agenda que podr\u00edamos resumir en lo siguiente: eliminar toda forma de discriminaci\u00f3n y violencia hacia las mujeres en todas las esferas de la vida, alcanzar la autonom\u00eda y el ejercicio pleno de nuestros derechos sexuales y reproductivos y lograr la democracia paritaria. Cualquier reivindicaci\u00f3n que contravenga estos prop\u00f3sitos no puede decirse feminista, aun cuando sean mujeres quienes la encabezan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pretensi\u00f3n de confrontar a las militantes de base y l\u00edderes locales de MORENA con el movimiento feminista ha sido una err\u00e1tica estrategia para enfrentar esta crisis pol\u00edtica de MORENA en Guerrero. No es el movimiento feminista el que est\u00e1 escindido. La fractura es dentro de MORENA y sus aspirantes a la gubernatura, que han usado a las mujeres para dirimir sus diferencias. As\u00ed, en medio de esta crisis al interior de este partido pol\u00edtico, lo que se intenta con la estrategia de divide y vencer\u00e1s no solo es imponer a como d\u00e9 lugar la candidatura de un personaje muy popular, pero impresentable, sino construir la idea de que cuenta con el respaldo de miles de mujeres y de que el movimiento feminista est\u00e1 dividido. Como si no supi\u00e9ramos que las bases de cualquier partido operan en funci\u00f3n de las directrices que determinan sus dirigencias, y en no pocas ocasiones de manera acr\u00edtica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero si en ese partido pol\u00edtico hay mujeres dispuestas a defender a un presunto violador para que sea su gobernador, es momento de preguntar a MORENA Guerrero qu\u00e9 ha hecho con las prerrogativas que tiene por obligaci\u00f3n destinar a la capacitaci\u00f3n, promoci\u00f3n y desarrollo del liderazgo pol\u00edtico de las mujeres y por qu\u00e9 es la hora que muchas de sus militantes en Guerrero siguen en la incertidumbre respecto de sus aspiraciones, pues prevalece el ocultamiento de informaci\u00f3n y una discrecional toma de decisiones sobre la selecci\u00f3n de sus candidaturas y sobre c\u00f3mo van a cumplir con la paridad de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y en medio de todo, no podemos perder de vista que las denuncias contra Salgado Macedonio no han sido resueltas por las autoridades competentes. Y en ello reside uno de los temas centrales de la agenda de los derechos humanos de las mujeres guerrerenses, que es el acceso a la justicia y la erradicaci\u00f3n de la violencia contra las mujeres. Frente a ello, la dirigencia nacional y estatal de este instituto pol\u00edtico ha guardado total silencio, junto con su impresentable aspirante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muriel Salinas D\u00edaz&nbsp; SemM\u00e9xico. Guadalajara. 11 de febrero de 2021.- Tras las denuncias penales por presunta violaci\u00f3n sexual y otros delitos sexuales contra F\u00e9lix Salgado Macedonio, virtual candidato de MORENA a la gubernatura de Guerrero, y la subsecuente movilizaci\u00f3n del movimiento feminista local para exigir a este partido pol\u00edtico que retire dicha postulaci\u00f3n. MORENA opt\u00f3 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":31753,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[692,203,35],"tags":[],"class_list":["post-31752","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-la-mitad-del-cielo","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/31752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=31752"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/31752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/31753"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=31752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=31752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=31752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}