{"id":31336,"date":"2021-02-02T18:22:08","date_gmt":"2021-02-02T18:22:08","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=31336"},"modified":"2023-07-21T16:47:33","modified_gmt":"2023-07-21T21:47:33","slug":"amiga","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/amiga\/","title":{"rendered":"Amiga"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Bellas y Airosas<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por: Elvira Hern\u00e1ndez Carballido<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. 02 de febrero 2021.- Ese intercambio de miradas justo cuando se coincide en algo, de la complicidad eterna, del coraz\u00f3n que sabe latir a ritmo de la sororidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La llamada en el momento preciso, el mensaje cari\u00f1oso cuando m\u00e1s lo necesitas, el correo oportuno, un simple \u201cme gusta\u201d en el Facebook.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La confidencia que no necesita advertir ese \u201cno se lo cuentes a nadie\u201d. El silencio oportuno al enfrentar una traici\u00f3n, un desamor, la historia que va y viene de ese amor rom\u00e1ntico contra el que luchamos incansablemente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Canciones para escuchar con un buen tequila, ritmos para bailar toda la noche, libros que nos delatan, poemas que nos definen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tiempos buenos para recordar. Tiempos dif\u00edciles -como hoy- para el apapacho necesario, las bendiciones pese al ate\u00edsmo natural, las maldiciones para no caer en la tentaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Imaginarnos en mil playas para danzar descalzas en la arena. Regalarnos la luna en esas noches de insomnio. Inundar el mar cuando nuestras l\u00e1grimas son necesarias. Que el sol nos ilumine en cualquier escenario y derrita absurdas envidias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Soportar encierros resignadas, vencer sanas distancias, sonre\u00edr pese al cubrebocas, so\u00f1ar con ese abrazo eterno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apretar los pu\u00f1os ante la impotencia cuando alguna se queja con justa raz\u00f3n. Blasfemar muy alto si alguien nos lastima o violenta. Llorar por las muertas que no conocimos, orar porque ninguna se vaya entre silencios ni olvidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comprender el apoyo y la solidaridad, la reciprocidad y la esplendidez. Atreverse a cantar como sirenas pese a ser desafinadas. A montar caballitos de mar cuando nos amenazan profundidades negativas. Curar nuestro tal\u00f3n de Aquiles en femenino. Ensordecer al mundo con nuestras risas de brujas y nuestros coros de nereidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que este escrito, mi amiga, hermana y compa\u00f1era, hija y novia, amante y colega, ter arrulle en mil certezas de que aqu\u00ed sigo, te levante si tropezaste, te sane si est\u00e1s enferma o herida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que estas palabras, amigas, nos den fuerza en estos tiempos tan dif\u00edciles. Convierten la palabra amiga en nuestra bendici\u00f3n, el buen augurio, el pu\u00f1o en alto, la diamantina violeta, los soplos de nuestra esperanza, el esc\u00e1ndalo de nuestros suspiros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una pandemia parece habernos paralizado, ganas de no escribir, pereza de sonre\u00edr, miedo de volver a querer. Descansemos un rato, espiemos en el espejo por un rato qui\u00e9nes somos y al descubrir nuestra propia mirada, regresaremos a todos los cielos, a todos los mares, a las manos solidarias, a la inspiraci\u00f3n constante, a todas las palabras, a los espacios compartidos y musitaremos esa palabra m\u00e1gica, ese jerogl\u00edfico que solamente nosotras comprendemos, ese hechizo que nos musitamos al o\u00eddo, esa certeza de que no hay nada imposible, esa palabra que motiv\u00f3 este escrito: AMIGA.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ese intercambio de miradas justo cuando se coincide en algo, de la complicidad eterna, del coraz\u00f3n que sabe latir a ritmo de la sororidad.<\/p>\n","protected":false},"author":3,"featured_media":31337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[692,201,202,35],"tags":[],"class_list":["post-31336","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-bellas-y-airosas","category-elvira-hernandez-carballido","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/31336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=31336"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/31336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/31337"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=31336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=31336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=31336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}