{"id":3107,"date":"2019-03-09T01:16:26","date_gmt":"2019-03-09T01:16:26","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=3107"},"modified":"2023-07-21T14:47:47","modified_gmt":"2023-07-21T19:47:47","slug":"han-dejado-evidencia-suficiente-para-senalar-al-estado-mexicano-responsable-de-la-masacre","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/han-dejado-evidencia-suficiente-para-senalar-al-estado-mexicano-responsable-de-la-masacre\/","title":{"rendered":"Han dejado evidencia suficiente para se\u00f1alar al Estado mexicano responsable de la masacre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.semmexico.com\/gallery-post.php?id=7484#\">Redacci\u00f3n<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/ChiapasParalelo, Chiapas, 9 marzo 2019.- V\u00edctimas y familiares de asesinados del ataque realizado el 22 de diciembre de 1997&nbsp;<a href=\"https:\/\/acteal.blogspot.com\/2019\/03\/una-solucion-amistosa-no-revive.html?fbclid=IwAR25GUfW3kRp0ZnK6_PzWPgZELH-Ih4gW_TJVKBr3jZXCJvLir5sEQWnMVY\">en la comunidad de Actea<\/a>l, municipio de Chenalh\u00f3, exigieron a la<a href=\"https:\/\/www.chiapasparalelo.com\/noticias\/chiapas\/2018\/12\/a-21-anos-de-la-masacre-de-acteal-los-autores-estan-libres-burlandose-de-la-justicia-las-abejas\/\">&nbsp;Comisi\u00f3n Interamericana de Derechos Humanos (CIDH)<\/a>,&nbsp;dicte lo m\u00e1s pronto posible el informe de fondo del Caso 12.790 Manuel S\u00e1ntiz Culebra y otros (Masacre de Acteal), para frenar la impunidad en la que fallecieran 45 personas, entre ellas cuatro beb\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el lugar de los hechos, las victimas pidieron a la Comisi\u00f3n Interamericana valore las pruebas que han presentado en el caso que dan cuenta tanto de la estrategia de contrainsurgencia implementada en Chiapas a trav\u00e9s del Plan Campa\u00f1a 1994 y de las violaciones a derechos humanos cometidas en el caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, las victimas indicaron que los sobrevivientes y la organizaci\u00f3n viven una constante tortura psicol\u00f3gica y desgaste de su tejido social, que ha provocado divisiones en la organizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl Estado mexicano en lugar de castigar a los autores materiales e intelectuales de la Masacre, los excarcelan y los premian, como lo hizo la mal llamada Suprema Corte de Justicia de la Naci\u00f3n con los paramilitares confesos, argumentando faltas al debido proceso, faltas cometidas desde el inicio de las investigaciones y que fueron encaminadas a ser de antemano infructuosas y como resultado de la impunidad\u201d manifestaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, denunciaron que el nuevo gobierno en M\u00e9xico, ha generado expectativas de que ser\u00e1 una administraci\u00f3n de los pobres, pero, en nuestro caso no queremos generar ilusiones, sabemos que de all\u00e1 arriba no vendr\u00e1 la justicia verdadera, raz\u00f3n por la que hicieron una aclaraci\u00f3n que en ning\u00fan momento los sobrevivientes de la Masacre de Acteal y nla Organizaci\u00f3n Sociedad Civil Las Abejas de Acteal est\u00e1n&nbsp;buscando al gobierno actual para pedirle una mesa de di\u00e1logo y soluci\u00f3n amistosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM-ChiapasParalelo<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redacci\u00f3n SemM\u00e9xico\/ChiapasParalelo, Chiapas, 9 marzo 2019.- V\u00edctimas y familiares de asesinados del ataque realizado el 22 de diciembre de 1997&nbsp;en la comunidad de Acteal, municipio de Chenalh\u00f3, exigieron a la&nbsp;Comisi\u00f3n Interamericana de Derechos Humanos (CIDH),&nbsp;dicte lo m\u00e1s pronto posible el informe de fondo del Caso 12.790 Manuel S\u00e1ntiz Culebra y otros (Masacre de Acteal), para [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3108,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[690,48],"tags":[],"class_list":["post-3107","post","type-post","status-publish","format-standard","has-post-thumbnail","category-690","category-no-mas-impunidad-no-mas-impunidad"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/3107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=3107"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/3107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/3108"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=3107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=3107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=3107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}