{"id":30648,"date":"2021-01-13T22:40:03","date_gmt":"2021-01-13T22:40:03","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=30648"},"modified":"2023-07-21T16:45:26","modified_gmt":"2023-07-21T21:45:26","slug":"condenan-apropiacion-de-huipil-mazateco-para-una-moda-frivola","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/condenan-apropiacion-de-huipil-mazateco-para-una-moda-frivola\/","title":{"rendered":"Condenan apropiaci\u00f3n de huipil mazateco para \u201cuna moda fr\u00edvola\u201d"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Elisa Zepeda: plagian la cultura y el trabajo mujeres de la Ca\u00f1ada en Oaxaca<\/strong><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Empresa australiana present\u00f3 el huipil como parte la moda en ropa de playa<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lorena Vaniezcot<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 13 de enero, 2021.- Como una pr\u00e1ctica grave de apropiaci\u00f3n de las culturas ind\u00edgenas calific\u00f3 la diputada Elisa Zepeda Lagunas el hecho de que una empresa australiana presentara un vestido en su colecci\u00f3n Resort 2021, en la que se muestran bordados, encajes y plisados iguales a los que confeccionan las mazatecas en Oaxaca, \u201creducidos a una moda fr\u00edvola y pasajera\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un comunicado, la diputada de Morena consider\u00f3 que se trata de un plagio a la cultura que por cientos de a\u00f1os han forjado las mujeres de Huautla de Jim\u00e9nez, municipio ubicado en la regi\u00f3n de la Ca\u00f1ada.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><a href=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2021\/01\/elisa-zepeda-2.jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2021\/01\/elisa-zepeda-2-683x1024.jpeg\" alt=\"\" class=\"wp-image-30649\" width=\"325\" height=\"487\"\/><\/a><figcaption><strong><em>Diputada Elisa Zepeda Lagunas.<\/em><\/strong><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La diputada local conden\u00f3 el hecho, asegurando que la empresa de Zimmermann -de origen australiano y fundada por los hermanos Nicky y Simone Zimmermann fundaron su marca hom\u00f3nima en 1991 con una colecci\u00f3n de ropa de playa- present\u00f3 un vestido de la colecci\u00f3n Resort 2021 en donde no hace ninguna referencia ni menci\u00f3n ni de Oaxaca, ni de los municipios mazatecos Huautla de Jim\u00e9nez y Jalapa de D\u00edaz donde se elaboran los huipiles cuyos bordados y figuras evidentemente fueron plagiados, dijo m\u00e1s tarde a SemM\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como elementos para sus dise\u00f1os retoma las aves y las flores inspiradas por la flora y fauna de la regi\u00f3n mazateca y que representa tambi\u00e9n elementos fundamentales de la cosmovisi\u00f3n de dicho pueblo, as\u00ed como el cuello redondo de colores, los encajes, las mangas anchas y detalles plisados, se\u00f1ala la diputada quien con frecuencia se presenta al recinto legislativo con huipiles elaborados por las mujeres del distrito 04, que ella representa en el Congreso local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque sostuvo que por ahora solo conden\u00f3 el hecho, Zepeda Lagunas sostuvo que lo realizado por la empresa Zimmermann es una clara violaci\u00f3n al derecho de la propiedad intelectual de una cultura de origen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Originaria de Eloxochitl\u00e1n de Flores Mag\u00f3n, en la sierra Mazateca, expres\u00f3 que la gravedad de estas pr\u00e1cticas es el contexto de apropiaci\u00f3n, en la que las culturas ind\u00edgenas han sido menospreciadas y dominadas, y adem\u00e1s que los elementos que les son despojados son irrespetuosos, reducidos a modas fr\u00edvolas pasajeras de las culturas dominantes, extra\u00eddas del contexto social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n dijo que \u201cel imitador\u201d no experimenta esa clase de opresi\u00f3n y es capaz de \u201cjugar\u201d temporalmente con algo \u201cex\u00f3tico\u201d para ellos sin vivir la discriminaci\u00f3n diaria a la que se enfrenta la otra cultura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La empresa australiana Zimmerman<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con una presentaci\u00f3n en la p\u00e1gina de Maytheresa.com la empresa Zimmermann \u201ces reconocida hoy por fusionar con maestr\u00eda la moda de dise\u00f1o con el <em>beachwear<\/em>. As\u00ed, no es de extra\u00f1ar la rapidez con la que se ha ganado el estatus de culto entre los entendidos de la industria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con una sastrer\u00eda impecable y cortes limpios, sus creaciones derrochan una est\u00e9tica rom\u00e1ntica y bohemia que anima a sacar el pasaporte. Confeccionados para proveer de libertad de movimiento y extremo confort, sus elegantes dise\u00f1os son una fuente incansable de volantes, encajes y vol\u00famenes que invitan a so\u00f1ar con el verano\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/lv\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empresa australiana present\u00f3 el huipil como parte la moda en ropa de playa<\/p>\n","protected":false},"author":3,"featured_media":30650,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[692,50],"tags":[],"class_list":["post-30648","post","type-post","status-publish","format-standard","has-post-thumbnail","category-692","category-congreso"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/30648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=30648"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/30648\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/30650"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=30648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=30648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=30648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}