{"id":30114,"date":"2020-12-21T17:48:13","date_gmt":"2020-12-21T17:48:13","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=30114"},"modified":"2023-07-21T16:40:56","modified_gmt":"2023-07-21T21:40:56","slug":"nueve-mujeres-en-el-gabinete-de-amlo","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/nueve-mujeres-en-el-gabinete-de-amlo\/","title":{"rendered":"Nueve mujeres en el gabinete de AMLO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">* El Presidente de M\u00e9xico hace un recuento<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">* \u201c\u2026ah\u00ed vamos avanzando\u201d, se\u00f1ala<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lizbeth \u00c1lvarez Mart\u00ednez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 21 de diciembre, 2020.- \u201cAumenta el n\u00famero de mujeres en el gabinete, son nueve mujeres\u201d, as\u00ed lo expres\u00f3 el presidente Andr\u00e9s Manuel L\u00f3pez Obrador al nombrar a la maestra Delfina G\u00f3mez \u00c1lvarez como la titular de Educaci\u00f3n P\u00fablica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la conferencia ma\u00f1anera, fue nombrando a cada una de las mujeres que forman parte de su gobierno.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secretar\u00eda de Gobernaci\u00f3n, Olga S\u00e1nchez Cordero.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secretaria de Medio Ambiente, Mar\u00eda Luisa Albores.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secretaria del Trabajo, Luisa Mar\u00eda Alcalde.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secretaria de Energ\u00eda, Roc\u00edo Nahle Garc\u00eda.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secretaria de cultura, Alejandra Frausto Guerrero.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secretaria de Seguridad P\u00fablica, Rosa Icela Rodr\u00edguez.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secretaria de la Funci\u00f3n P\u00fablica, Irma Er\u00e9ndira Sandoval.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secretar\u00eda de Econom\u00eda, Tatiana Clouthier Carrillo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secretaria de Educaci\u00f3n P\u00fablica, Delfina G\u00f3mez \u00c1lvarez.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al finalizar la lista de mujeres dijo que se va avanzando.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cBueno, ah\u00ed vamos avanzando\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/lam\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>* El Presidente de M\u00e9xico hace un recuento * \u201c\u2026ah\u00ed vamos avanzando\u201d, se\u00f1ala Lizbeth \u00c1lvarez Mart\u00ednez SemM\u00e9xico, Cd. de M\u00e9xico, 21 de diciembre, 2020.- \u201cAumenta el n\u00famero de mujeres en el gabinete, son nueve mujeres\u201d, as\u00ed lo expres\u00f3 el presidente Andr\u00e9s Manuel L\u00f3pez Obrador al nombrar a la maestra Delfina G\u00f3mez \u00c1lvarez como la titular [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":30115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[691,51],"tags":[],"class_list":["post-30114","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/30114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=30114"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/30114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/30115"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=30114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=30114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=30114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}