{"id":28355,"date":"2020-11-10T00:07:11","date_gmt":"2020-11-10T00:07:11","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=28355"},"modified":"2023-07-21T16:37:24","modified_gmt":"2023-07-21T21:37:24","slug":"2021-la-hora-del-affidamento-entre-mujeres","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/2021-la-hora-del-affidamento-entre-mujeres\/","title":{"rendered":"2021: la hora del affidamento entre mujeres"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sara Lovera*<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Cd. de M\u00e9xico. 09 de noviembre 2020.- La historia es muy clara: las mexicanas hemos avanzado en derechos, siempre que actuamos unidas, en colectivos variopintos y emp\u00e1ticos. Sucedi\u00f3 en numerosas ocasiones, de la Independencia a nuestra \u00e9poca; de la rebeli\u00f3n en los conventos a la Rep\u00fablica, a trav\u00e9s de escritos en cientos de revistas, exigiendo derecho a la educaci\u00f3n, la convivencia familiar y el divorcio civil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la Revoluci\u00f3n Mexicana, unidas por el voto ciudadano y derechos progresivos; en 1916, en Yucat\u00e1n, los dos congresos feministas formularon la primera Agenda de Derechos. Venidas de distintos or\u00edgenes ideol\u00f3gicos y socioecon\u00f3micos, exigieron a la revoluci\u00f3n la calidad de ciudadanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los a\u00f1os 30, con el Frente \u00danico Pro Derechos de la Mujer, 50 mil mujeres de los partidos Comunista Mexicano y del Nacional Revolucionario y de otras organizaciones lograron modificaciones en el C\u00f3digo Civil y dieron horizonte a las sufragistas, al derecho al trabajo y mejoras econ\u00f3micas. Codo a codo, mujeres de todas las ideolog\u00edas, entre 1935 y 1939 hicieron la segunda agenda de derechos. Profesionistas, maestras, campesinas y pol\u00edticas, sin ataduras ideol\u00f3gicas, consiguieron visibilidad y presencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En organizaciones plurales, democr\u00e1ticas y con propuestas para todas, hace 40 a\u00f1os experimentamos el ingreso al feminismo y asumimos su programa m\u00ednimo: no a la violencia contra las mujeres, aborto libre y gratuito, libre opci\u00f3n sexual y participaci\u00f3n social y pol\u00edtica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, con integrantes de la sociedad civil, pol\u00edticas, campesinas, ind\u00edgenas y acad\u00e9micas en los a\u00f1os 80 y 90 surgieron 14 propuestas colectivas plurales. En 1996, una Convenci\u00f3n Nacional construy\u00f3 el primer programa de igualdad y la primera bancada feminista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Florecieron programas de reivindicaci\u00f3n sobre derechos sexuales y reproductivos, no a la violencia y se profundiz\u00f3 la ciudadan\u00eda. En 2014 eliminamos diques partidarios, llegamos la paridad electoral y, luego, a la paridad total en 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La lecci\u00f3n est\u00e1 aprendida. 2021 es una oportunidad para marchar con affidamento, una&nbsp; pr\u00e1ctica de confianza y cuidado mutuo entre mujeres, m\u00e1s all\u00e1 de la solidaridad voluntarista \u2013sororidad\u2013. Es momento de conseguir democracia plural, erigir un dique a la polarizaci\u00f3n, divisi\u00f3n o enfrentamiento, para una jornada electoral donde naufrague la espiral de violencia contra las mujeres y se ponga un alto a la violencia patriarcal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Interesadas en los m\u00e1s de 10 mil puestos en disputa, es tiempo de hacer la diferencia. Desde los municipios \u2013m\u00e1s de mil 800\u2013 a las c\u00e1maras legislativas y a los gobiernos de los estados, tienen en sus manos la posibilidad de trascender pol\u00edticas asistencialistas, construir una pol\u00edtica p\u00fablica nacional de igualdad, profundizar la existente, donde cada una tenga asegurada su vida, su integridad personal y su desarrollo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cada rinc\u00f3n del pa\u00eds, a contrapelo del poder, hay conocimientos, herramientas y experiencias. En cada rinc\u00f3n est\u00e1n las feministas para apuntalar programas de campa\u00f1a y tolerancia cero a la violencia de g\u00e9nero. Urge lanzar una cruzada para que todas las mexicanas conozcan y se apropien de sus derechos y los defiendan. Derechos humanos plasmados en ley, obligados para los partidos pol\u00edticos. Tenemos que recorrer ese camino con convicci\u00f3n y construir un pa\u00eds en paz y no dividido. Veremos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*Periodista, directora del portal informativo SemM\u00e9xico.mx<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La historia es muy clara: las mexicanas hemos avanzado en derechos, siempre que actuamos unidas<\/p>\n","protected":false},"author":3,"featured_media":27667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[691,35,95,69],"tags":[],"class_list":["post-28355","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-opinion","category-palabra-de-antigona","category-sara-lovera"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/28355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=28355"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/28355\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/27667"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=28355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=28355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=28355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}