{"id":2801,"date":"2018-04-05T06:18:08","date_gmt":"2018-04-05T06:18:08","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=2801"},"modified":"2023-07-21T14:30:44","modified_gmt":"2023-07-21T19:30:44","slug":"estereotipos-e-imagenes-negativas-sobre-la-vejez-obstaculizan-su-visibilidad","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/estereotipos-e-imagenes-negativas-sobre-la-vejez-obstaculizan-su-visibilidad\/","title":{"rendered":"Estereotipos e im\u00e1genes negativas sobre la vejez obstaculizan su visibilidad"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.semmexico.com\/gallery-post.php?id=4443#\">Elda Montiel<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 5 abril 2018.- Las personas mayores, principalmente las mujeres, son manejadas de manera clientelar en las elecciones, ya que estad\u00edsticamente las mujeres de 60 a 64 a\u00f1os son las que m\u00e1s participan en las urnas, sin embargo no se les toma en cuenta en la toma de decisiones, son excluidas desde la familia, se\u00f1al\u00f3 la activista por los derechos humanos y presidenta del Comit\u00e9 de Derechos Humanos Ajusco, Mar\u00eda de los \u00c1ngeles Fuentes Vera.&nbsp;<br>Angelita, como se conoce a Mar\u00eda de los \u00c1ngeles Fuentes Vera, l\u00edder comunitaria de 76 a\u00f1os de edad, quien particip\u00f3 en el \u201cForo de las Personas Mayores: Viviendo mis Derechos Plenos\u201d, realizado en la C\u00e1mara de Diputados, exigi\u00f3 que las personas mayores sean consideradas y se asuman como tomadores de decisiones.<br>Es importante que se deje de reproducir la pr\u00e1ctica pol\u00edtica que niega la posibilidad de hacer una reflexi\u00f3n cr\u00edtica de los prejuicios sobre la vejez y de construir un marco normativo que valore positivamente este periodo de vida a la que todos tenemos que llegar.&nbsp;<br>Agreg\u00f3 que los estereotipos e im\u00e1genes negativas que hay sobre la vejez obstaculizan las posibilidades de visibilidad, valoraci\u00f3n positiva y reconocimiento personal y social de esta etapa de la vida a la que se teme llegar. Visibilizar y revalorar la vejez que ocurrir\u00e1 \u2013 u ocurre ya- es indispensable para generar una cultura de reconocimiento y ejercicio de nuestros derechos como personas mayores.<br>Al participar en la mesa de los avances para la ratificaci\u00f3n por parte del gobierno de M\u00e9xico, de la Convenci\u00f3n Interamericana para la Protecci\u00f3n de los Derechos de las Personas Mayores, asegur\u00f3 que los mayores son inexistentes para el estado y pidi\u00f3 que dejen de ser carne de ca\u00f1\u00f3n.<br>Se debe de dejar de ser invisibles por razones de edad y reconocer a las personas mayores como factores de cambio conformando redes en b\u00fasqueda de un bien com\u00fan. Asimismo, solicit\u00f3 a la academia espacios para la discusi\u00f3n y ser tomados en los espacios de an\u00e1lisis para la toma de decisiones, dijo la activista.<br>El foro fue inaugurado por el diputado Luis Fernando Mesta, presidente de la Comisi\u00f3n de Grupos Vulnerables de la C\u00e1mara de Diputados, y participaron la maestra Eunice Arias, ex delegada del INAPAM; la maestra Alondra Mendoza Carlos, directora general adjunta de Pol\u00edtica Internacional de Derechos Humanos II, quien explic\u00f3 que se est\u00e1n realizando los cabildeos para que se ratifique y el an\u00e1lisis presupuestario obligatorio en este tipo de acuerdos internacionales solicitado por la Secretaria de Hacienda.<br>Tambi\u00e9n se cont\u00f3 con la participaci\u00f3n de Sergio Salvador Vald\u00e9s y Rojas, director de Atenci\u00f3n Geri\u00e1trica del INAPAM, y Teresa G\u00f3mez de Le\u00f3n del R\u00edo, directora general de Enlace y Fortalecimiento con la Sociedad Civil de la CNDH. El foro fue organizado tambi\u00e9n por parte de Asome, Asociaci\u00f3n de Enlace Cultural de M\u00e9xico, A.C.<br>SEM\/em\/sj<br><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li>TAGS<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Elda Montiel SemM\u00e9xico, Cd. de M\u00e9xico, 5 abril 2018.- Las personas mayores, principalmente las mujeres, son manejadas de manera clientelar en las elecciones, ya que estad\u00edsticamente las mujeres de 60 a 64 a\u00f1os son las que m\u00e1s participan en las urnas, sin embargo no se les toma en cuenta en la toma de decisiones, son [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[689,33],"tags":[],"class_list":["post-2801","post","type-post","status-publish","format-standard","has-post-thumbnail","category-689","category-elecciones-2018"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/2801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=2801"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/2801\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/2802"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=2801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=2801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=2801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}