{"id":27526,"date":"2020-10-20T20:34:04","date_gmt":"2020-10-20T20:34:04","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=27526"},"modified":"2023-07-21T16:36:58","modified_gmt":"2023-07-21T21:36:58","slug":"la-ira-de-lopez-obrador-pio-el-marido-borracho","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/la-ira-de-lopez-obrador-pio-el-marido-borracho\/","title":{"rendered":"La ira de L\u00f3pez Obrador; P\u00edo, el marido borracho"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Mois\u00e9s S\u00e1nchez Lim\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, 20 de octubre, 2020.- La porosidad del entorno presidencial no es nueva ni hay inmunidad contra perjuicios familiares. \u00bfQui\u00e9n puede presumir de inmaculada gesti\u00f3n ayuna de esc\u00e1ndalos de sus incondicionales?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y, mire usted, las medias verdades o mentiras \u00edntegras visten al discurso presidencial en cada ma\u00f1anera. Dos recientes pautan la ira presidencial y abierta impunidad en materia electoral que el licenciado L\u00f3pez Obrador abord\u00f3 al inicio de semana con falaz pulcritud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De lo ocurrido el domingo electoral en Hidalgo y Coahuila, Andr\u00e9s Manuel lo tom\u00f3 con la conocida respuesta que oculta todo un estado de \u00e1nimo: la ira que puede derivar en infarto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8212;<\/strong>Buenos d\u00edas, presidente (\u2026) retomando el tema electoral del d\u00eda de ayer, quisiera preguntarle si considera como una derrota para Morena los resultados, particularmente de Coahuila\u2014plante\u00f3&nbsp; un reportero al licenciado L\u00f3pez Obrador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8212;<\/strong>No opino de eso, no. Yo creo que es un triunfo para la democracia si la gente participa y hay elecciones limpias y libres, gane quien gane \u2013ataj\u00f3 el se\u00f1orpresidente en la ma\u00f1anera del inicio de semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y del caso de P\u00edo L\u00f3pez Obrador, pillado en la pr\u00e1ctica del deporte de la corrupci\u00f3n con las manos en la lana, tambi\u00e9n al inicio de semana otro reportero pregunt\u00f3 al inquilino de Palacio:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8211;(\u2026)<\/strong> \u00bfQu\u00e9 opini\u00f3n le merece que su hermano Pio L\u00f3pez Obrador haya solicitado investigar penalmente, incluso sancionar hasta con 12 de a\u00f1os de c\u00e1rcel a quienes difundieron los videos en los que se le observa recibir dinero de David Le\u00f3n?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8212;<\/strong>Pues no estoy de acuerdo con \u00e9l \u2013respondi\u00f3 Andr\u00e9s Manuel&#8211;. Yo creo que no debe de pedirse un castigo as\u00ed para nadie. Y m\u00e1s si es mi hermano, porque eso lo utilizan mis adversarios en contra de mi persona y del gobierno que represento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veamos. Pr\u00e1cticamente ning\u00fan Presidente ha estado exento de que alguna de sus declaraciones, de supuesta secrec\u00eda, trascienda y sea p\u00fablica; Andr\u00e9s Manuel L\u00f3pez Obrador no es la excepci\u00f3n y no es la primera vez que se filtran asuntos tratados en privado y que revelan declaraciones y estados de \u00e1nimo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes en Los Pinos, hoy en Palacio Nacional opera <em>Garganta Profunda<\/em> o testigos circunstanciales a quienes la informaci\u00f3n reservada les apura comentarla con el cl\u00e1sico: \u201csi me citas lo desmiento\u201d. \u00bfIntimidad presidencial? Es evidente que el famoso \u201ccisen\u201d personal del licenciado Andr\u00e9s Manuel no cumple con su tarea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfDesmentir\u00e1 la versi\u00f3n del colega Alejandro Aguirre Guerrero publicada en la p\u00e1gina de Carlos Loret de Mola, respecto de su reacci\u00f3n el domingo \u00faltimo cuando se enter\u00f3 que Morena hab\u00eda mordido el polvo en las elecciones de Hidalgo y Coahuila?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno, por lo menos adelant\u00f3 que en el caso de P\u00edo no apoya la demanda contra Loret de Mola. Pero, honor a quien honor merece. Aguirre Guerrero tiene una buena fuente, una garganta profunda de Palacio que con cierta frecuencia le desliza informaci\u00f3n que puede lindar entre la infidencia y temas de suyo relevantes que evidencian ese doble lenguaje con el que acostumbra proceder Andr\u00e9s Manuel L\u00f3pez Obrador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la ma\u00f1anera, la reportera Shaila Rosagel pregunt\u00f3 al licenciado presidente c\u00f3mo vio la elecci\u00f3n de Coahuila e Hidalgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cMire \u2013respondi\u00f3 Andr\u00e9s Manuel&#8211;, yo en este caso lo que celebro es que no hubo violencia, que acudi\u00f3 la gente a votar, muy poca, pero participaron y eso es lo m\u00e1s importante, m\u00e1s destacado. Ya las autoridades electorales van a decidir qui\u00e9n gana y si hay inconformidades hay procedimientos para acudir a esas denuncias, y adelante.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cYo me entero de las elecciones de ayer por la informaci\u00f3n oficial, es decir, a trav\u00e9s de lo que dicen los \u00f3rganos electorales y por los medios de informaci\u00f3n, quiero hacerlo as\u00ed, no quiero estar monitoreando, como era antes, desde la campa\u00f1a c\u00f3mo est\u00e1n los partidos, no me corresponde\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfUsted le cree a Andr\u00e9s Manuel? \u00a1Yo tampoco!, en la par\u00e1frasis de la maestra Elba Esther.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porque, el colega Alejandro Aguirre Guerrero escribi\u00f3, en la p\u00e1gina de Carlos Loret de Mola, una sabrosa cuanto interesante columna que deja mal parado al licenciado presidente en eso de no meterse en asuntos electorales. Y menos cuando se trata de su corporativo Morena, S.A. A saber:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201c<\/strong><strong>Cuando menos tres manotazos dio el Presidente L\u00f3pez Obrador al enterarse de los resultados en Hidalgo y Coahuila. \u201cD\u00edganle a Alfonso (Ram\u00edrez Cu\u00e9llar) que se apresure a desconocerlos; les dije que pusieran atenci\u00f3n en esas elecciones; se descuidaron por andar pele\u00e1ndose la dirigencia\u201d, dijo el tabasque\u00f1o visiblemente molesto.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cEs claro el complot para buscar debilitarnos desde el propio INE, pero no nos vamos a dejar, en mis conferencias seguir\u00e9 hablando, el pueblo me apoya, se los restregar\u00e9 cuando venga la consulta para revocaci\u00f3n de mandato\u201d, afirm\u00f3 AMLO frente a cuatro personas en Palacio Nacional, una de las cuales me comparti\u00f3 lo ocurrido.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cMe hacen saber que apenas se enter\u00f3 de los resultados preliminares, el Presidente pidi\u00f3 le hicieran tres enlaces telef\u00f3nicos: el primero, con Mario Delgado; el segundo, Porfirio Mu\u00f1oz Ledo, y el tercero, Alfonso Ram\u00edrez. La presi\u00f3n de AMLO subi\u00f3 y su m\u00e9dico particular tuvo que revisarlo, \u201ctranquil\u00edcese, Se\u00f1or Presidente, ya no se altere m\u00e1s\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cL\u00f3pez Obrador levant\u00f3 la voz al todav\u00eda dirigente de Morena, \u201capres\u00farate a desconocer esos resultados preliminares, nos hicieron fraude. Diles que no nos dejaremos y que vamos a investigar. Eso les pasa por andar pele\u00e1ndose al interior del movimiento, se los dije\u201d. Hasta aqu\u00ed parte de los publicado por<\/strong> <a href=\"mailto:alejandroaguirre77@gmail.com\">alejandroaguirre77@gmail.com<\/a>, cuyo Twitter es @aaguirre_g y su p\u00e1gina <a href=\"http:\/\/www.alejandroaguirre.com.mx\">www.alejandroaguirre.com.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfNo se mete en asuntos electorales el inquilino de Palacio? \u00bfDem\u00f3crata, dem\u00f3crata, lo que se dice dem\u00f3crata? Bueeeno, lo cierto es que una derrota m\u00e1s y el pr\u00f3cer se nos infarta. El domingo por la noche estaba algo m\u00e1s que encabronado. Y la ira no es buena consejera<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P\u00edo, el marido borracho<\/strong>. Por cierto, en esto de las infidencias y prejuicios de la familia contra los presidentes, en su momento, el caso de P\u00edo L\u00f3pez Obrador es para el psiquiatra o tomarse como el exceso de un personaje que se pasa de listo cubierto por el manto de la complicidad presidencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Frente a la evidencia de que andaba en la pr\u00e1ctica del deporte de la corrupci\u00f3n, dizque levantando contribuciones para pagar gasolina, las tortas, los frutsis y el chivo para la causa de su hermano Andr\u00e9s Manuel, es decir, en la recepci\u00f3n de dinero de manos de David Le\u00f3n, entonces operador del gobernador chiapaneco Manuel Velasco, asumi\u00f3 la postura del marido borracho que llega de madrugada a la casa, patea al perro, golpea la puerta y reclama a la esposa que est\u00e9 dormida mientras \u00e9l anda en la calle expuesto a todo tipo de peligros, luego de bailar con mujeres desconocidas y haber aceptado propuestas indecorosas. \u201c\u00a1No me comprendes, mujer!\u201d, reclama este personaje de cuento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed ha procedido el \u00ednclito y dizque c\u00e9libe en actos de corrupci\u00f3n, P\u00edo L\u00f3pez Obrador con la denuncia hecho contra Carlos Loret de Mola ante la Fiscal\u00eda General de la Rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado domingo 18 Loret escribi\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cP\u00edo L\u00f3pez Obrador, hermano del presidente de la Rep\u00fablica, ha decidido denunciarme ante la Fiscal\u00eda General de la Rep\u00fablica [FGR]. Pide 12 a\u00f1os de c\u00e1rcel para m\u00ed, y, adem\u00e1s, se dice v\u00edctima, despu\u00e9s de que en LatinUs revelamos los dos videos en donde aparece recibiendo paquetes de dinero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa denuncia la hace \u2018contra quien resulta responsable\u2019, pero acto seguido dice, pues que el responsable es el periodista Carlos Loret de Mola, en su espacio de LatinUs, por haber revelado estos videos, dice que invade su vida privada, cuando pues el que los grab\u00f3 es el otro que sal\u00eda en el video, David Le\u00f3n [Romero], el que era funcionario estrella, futuro zar anticorrupci\u00f3n para las medicinas, que hab\u00eda sido ya nombrado por el presidente L\u00f3pez Obrador\u201d, abund\u00f3 el periodista en un video publicado en su cuenta de la red social Twitter\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 le parece? El ladr\u00f3n se llama robado. El marido borracho contra quien no se ha procedido, aunque declar\u00f3 en la FGR igual que David Le\u00f3n, requerido por la denuncia presentada en su contra por legisladores del PAN.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfY el hermano Andr\u00e9s Manuel? En la ma\u00f1anera del 25 de agosto \u00faltimo dijo estar dispuesto a declarar ante la FGR por los videos en los que se capta a David Le\u00f3n Romero entregando dinero en efectivo en bolsas y sobres de papel, a P\u00edo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero cuatro d\u00edas antes pretendi\u00f3 poner a salvo a su hermano con <strong>la referencia de que el dinero <\/strong>fue de \u201caportaciones de la gente para gasolina\u201d de su movimiento pol\u00edtico o para su sueldo. \u00bfCu\u00e1nto cobraba? Y justific\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo somos iguales, en este caso del video, de mi hermano con David Le\u00f3n hay notorias diferencias con relaci\u00f3n a los otros asuntos. No solo es lo cuantitativo, no solo es el monto del dinero porque no es comparar solo una operaci\u00f3n il\u00edcita que est\u00e1 denunciando al se\u00f1or Lozoya, donde cobraron 200 millones de d\u00f3lares de m\u00e1s en la venta de una planta chatarra, que esto que puede significar 2 millones de pesos, no solo es eso\u201d. Es decir, P\u00edo es poquito corrupto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y respecto de que Pio solicit\u00f3 investigar y sancionar hasta con 12 de a\u00f1os de c\u00e1rcel a quienes difundieron los videos en los que se le observa recibir dinero de David Le\u00f3n, Andr\u00e9s Manuel resolvi\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPues no estoy de acuerdo con \u00e9l, yo creo que no debe de pedirse un castigo as\u00ed para nadie. Y m\u00e1s si es mi hermano, porque eso lo utilizan mis adversarios en contra de mi persona y del gobierno que represento. Nada m\u00e1s decirles que yo deslindo lo p\u00fablico de lo familiar. En lo que tiene que ver con las funciones p\u00fablicas no tengo hermanos, son asuntos particulares en este caso\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien, pero qu\u00e9 de la aplicaci\u00f3n de la ley contra su hermano, sorprendido con las manos en la lana y en el papel del marido borracho. Huelga preguntar; doble lenguaje del pr\u00f3cer: \u00a1H\u00e1gase justicia en los bueyes de mi compadre! Pero, no se sofoque presidente. Se nos puede infartar. Conste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:sanchezlimon@gmail.com\">sanchezlimon@gmail.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.entresemana.mx\">www.entresemana.mx<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">@msanchezlimon<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La porosidad del entorno presidencial no es nueva ni hay inmunidad contra perjuicios familiares.<\/p>\n","protected":false},"author":3,"featured_media":15805,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[691,105,83,35],"tags":[],"class_list":["post-27526","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-entresemana","category-moises-sanchez-limon","category-opinion"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/27526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=27526"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/27526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/15805"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=27526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=27526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=27526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}