{"id":27087,"date":"2020-10-10T22:26:00","date_gmt":"2020-10-10T22:26:00","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=27087"},"modified":"2023-07-21T16:35:14","modified_gmt":"2023-07-21T21:35:14","slug":"epidemia-lejos-de-terminarse","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/epidemia-lejos-de-terminarse\/","title":{"rendered":"Epidemia, lejos de terminarse: Silvano Aureoles"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Llama Gobernador a no bajar la guardia en los pr\u00f3ximos meses ante el COVID-19, que a\u00fan no est\u00e1 controlado y la temporada de Influenza<\/strong><\/li><li><strong>Reconoce comportamiento ejemplar de las y los michoacanos, lo que posiciona a Michoac\u00e1n entre los estados con mejor manejo de la crisis epidemiol\u00f3gica&nbsp;<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Morelia, Michoac\u00e1n. 10 de octubre de 2020.- Al reconocer que la epidemia a\u00fan est\u00e1 lejos de ser controlada y ante la presencia de la Influenza en la temporada invernal, el Gobernador de Michoac\u00e1n, Silvano Aureoles Conejo, reiter\u00f3 su llamado a no bajar la guardia en lo que resta del a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cLa epidemia est\u00e1 lejos de terminar y esta realidad nos exige a todas y a todos, no bajar la guardia en los pr\u00f3ximos meses; hoy hago un nuevo llamado a las autoridades municipales, a los diferentes sectores y a toda la sociedad, a mantener el sentido de responsabilidad al m\u00e1ximo en estos tres \u00faltimos meses del a\u00f1o, para evitar que la situaci\u00f3n se complique o se salga de control\u201d, asever\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un mensaje emitido a trav\u00e9s de sus redes sociales a las y los michoacanos, el mandatario explic\u00f3 que en tanto no exista una vacuna confiable \u201cno podemos cantar victoria\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cLa peligrosidad del virus nos obliga a realizar esfuerzos extraordinarios, as\u00ed como lo hacen a diario miles de doctores, doctoras, enfermeras, enfermeros, que no han descansado desde hace m\u00e1s de siete meses para cuidarnos\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aureoles Conejo se dijo orgulloso de la respuesta de las y los michoacanos para solidarizarse y llevar a cabo las medidas sanitarias, lo que junto con las decisiones gubernamentales ha posicionado a Michoac\u00e1n entre los estados con mejor manejo de la crisis epidemiol\u00f3gica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cHasta ahora el manejo de la crisis en el estado es uno de los mejores en el pa\u00eds, y el comportamiento de la mayor\u00eda de las y los michoacanos ha sido ejemplar; Es un verdadero gusto y orgullo ver en la calle que la mayor\u00eda la gente trae el cubrebocas; como Gobernador es un honor enfrentar junto a ustedes, hombres, mujeres, j\u00f3venes, ni\u00f1as, ni\u00f1os, familias, este desaf\u00edo, que es uno de los retos m\u00e1s grandes que ha visto el estado en las \u00faltimas d\u00e9cadas\u201d, destac\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario estatal, record\u00f3 que hasta el momento no hay mejor remedio para no enfermarse, que el uso de cubrebocas, el lavado constante de manos, la sana distancia y mantenernos en casa siempre que se pueda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cEstoy seguro que lo vamos a lograr, porque nuestro estado siempre ha alzado la mano en momentos dif\u00edciles, porque las y los michoacanos no nos rajamos y sabemos estar a la altura de los grandes retos; Michoac\u00e1n es un pueblo solidario y juntos y en solidaridad, vamos a salir de esta\u201d, finaliz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/IL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llama Gobernador a no bajar la guardia en los pr\u00f3ximos meses ante el COVID-19, que a\u00fan no est\u00e1 controlado y la temporada de Influenza<\/p>\n","protected":false},"author":3,"featured_media":27088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[691,51],"tags":[],"class_list":["post-27087","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/27087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=27087"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/27087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/27088"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=27087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=27087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=27087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}