{"id":26786,"date":"2020-10-07T21:33:50","date_gmt":"2020-10-07T21:33:50","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=26786"},"modified":"2023-07-21T16:35:18","modified_gmt":"2023-07-21T21:35:18","slug":"elecciones-en-hidalgo-3","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/elecciones-en-hidalgo-3\/","title":{"rendered":"PRI, PRD y PVEM denuncian violencia de g\u00e9nero a candidatas"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>El Instituto Estatal Electoral (IEEH) inici\u00f3 m\u00e1s de diez procedimientos especiales sancionadores por violencia de g\u00e9nero en la presente contienda electoral<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ignacio Garc\u00eda<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Cd. de M\u00e9xico. 7 de octubre de 2020.- A menos de dos semanas de que concluyan las campa\u00f1as electorales en Hidalgo, candidatas de los partidos Revolucionario Institucional (PRI), de la Revoluci\u00f3n Democr\u00e1tica (PRD) y Verde Ecologista de M\u00e9xico (PVEM) denunciaron que han ocurrido casos de violencia pol\u00edtica de g\u00e9nero en distintos municipios, por lo que pidieron a la Fiscal\u00eda Especializada en Delitos Electorales (Fedeh) investigar dichas acciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La dirigente estatal del PRI, Erika Rodr\u00edguez Hern\u00e1ndez, denunci\u00f3 la violencia que sufri\u00f3 la candidata de ese partido, Erika Saab Lara, a la alcald\u00eda de San Felipe Orizatl\u00e1n, pues frente a su domicilio aparecieron mantas amenazadoras el domingo pasado, as\u00ed como una cabeza de puerco, por lo que condenaron las agresiones contra la aspirante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ex diputada federal refiri\u00f3 que el PRI no permitir\u00e1 la violencia pol\u00edtica de g\u00e9nero, por lo que pidi\u00f3 a las autoridades correspondientes investigar las agresiones para que no se repitan este tipo de actos, aunado a que afirm\u00f3 que la aspirante no se amedrenta y por ello continuar\u00e1 con sus acciones proselitistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la candidata del PRD a la alcald\u00eda de Tlanalapa, Ang\u00e9lica Caba\u00f1as, denunci\u00f3 que se han presentado agresiones en su contra, por lo que proceder\u00e1 legalmente ante la Fedeh, ya que afirm\u00f3 que se han creado perfiles falsos en redes sociales para atacarla constantemente y difundir informaci\u00f3n err\u00f3nea sobre ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, el dirigente estatal del PRD, H\u00e9ctor Ch\u00e1vez Ru\u00edz, denunci\u00f3 que otras cuatro candidatas de esa fuerza pol\u00edtica tambi\u00e9n han sufrido agresiones de violencia pol\u00edtica de g\u00e9nero, por lo cual no permitir\u00e1n que ocurra este tipo de situaciones y por ello llam\u00f3 al gobierno estatal para que contin\u00fae con las indagatorias correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, el secretario de Organizaci\u00f3n del PVEM en el estado, Honorato Rodr\u00edguez Murillo, expres\u00f3 que ha existido guerra sucia contra las candidatas de esa fuerza pol\u00edtica, principalmente en Tecozautla y Tezontepec y por ello pidi\u00f3 a los dem\u00e1s aspirantes de otros partidos pol\u00edticos no incurran en ese tipo de agresiones, para que se garantice un clima de paz social en el estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Instituto Estatal Electoral (IEEH) inici\u00f3 m\u00e1s de diez procedimientos especiales sancionadores por violencia de g\u00e9nero en la presente contienda electoral, no obstante, contin\u00faan las agresiones hacia las candidatas que buscan obtener un cargo de elecci\u00f3n popular el pr\u00f3ximo 18 de octubre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Estatal Electoral (IEEH) inici\u00f3 m\u00e1s de diez procedimientos especiales sancionadores por violencia de g\u00e9nero en la presente contienda electoral<\/p>\n","protected":false},"author":3,"featured_media":26787,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[691,141],"tags":[],"class_list":["post-26786","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-elecciones-2020-2021"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/26786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=26786"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/26786\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/26787"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=26786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=26786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=26786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}