{"id":26783,"date":"2020-10-07T21:25:54","date_gmt":"2020-10-07T21:25:54","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=26783"},"modified":"2023-07-21T16:35:18","modified_gmt":"2023-07-21T21:35:18","slug":"respetar-la-identidad-de-genero-e-inscribirse-en-el-registro-civil-para-personas-trans","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/respetar-la-identidad-de-genero-e-inscribirse-en-el-registro-civil-para-personas-trans\/","title":{"rendered":"Respetar la identidad de g\u00e9nero e inscribirse en el registro civil para personas trans"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Ricardo Monreal \u00c1vila presenta iniciativa de reformas al C\u00f3digo Civil<\/strong><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Reconoce que este grupo poblacional\u00a0enfrenta discriminaci\u00f3n y rechazo<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Libertad L\u00f3pez<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Cd. de M\u00e9xico. 7 de octubre de 2020.- El senador Ricardo Monreal, coordinador del grupo parlamentario de Morena, presentar\u00e1&nbsp;en el pleno iniciativa para reformar el C\u00f3digo Civil Federal a fin facilitar el tr\u00e1mite de rectificaci\u00f3n de nombre y sexo en actas de nacimiento&nbsp;en&nbsp;raz\u00f3n de identidad de g\u00e9nero auto percibida.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reforma busca que sean los jueces del Registro Civil los encargados de ordenar las sentencias para el levantamiento nuevas actas para la concordancia con la identidad sexo-gen\u00e9rica auto-percibida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reforma entiende a la identidad de g\u00e9nero como \u201cla profundamente sentida experiencia interna e individual del g\u00e9nero de cada persona, que puede corresponder o no con el sexo asignado al momento del nacimiento\u201d y establece como requisitos para los solicitantes ser de nacionalidad mexicana, desahogar una comparecencia y manifestar nombre, apellidos y los datos asentados en el acta primigenia, as\u00ed como el nombre solicitado y el g\u00e9nero auto-percibido solicitado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El legislador se\u00f1al\u00f3 que es una injusticia que personas transexuales o transg\u00e9nero no puedan acceder f\u00e1cilmente a la rectificaci\u00f3n de su acta de nacimiento, lo que desafortunadamente las expone a situaciones de discriminaci\u00f3n y rechazo por contar con un nombre y g\u00e9nero con el que no viven en su d\u00eda a d\u00eda: \u201cMujeres trans en cuyos documentos figuran nombres masculinos, pese a que viven las 24 horas del d\u00eda los siete d\u00edas de la semana como mujeres\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta propuesta se podr\u00e1 homologar la identidad jur\u00eddica con la realidad social, otorgando soluci\u00f3n a las demandas hist\u00f3ricas de los grupos de personas transg\u00e9nero y transexuales que piden el reconocimiento y otorgamiento de su derecho al libre desarrollo de su personalidad jur\u00eddica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente las personas trans son quienes m\u00e1s enfrentan cotidianamente escenarios de discriminaci\u00f3n y son el cuarto grupo poblacional m\u00e1s rechazado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ricardo Monreal \u00c1vila presenta iniciativa de reformas al C\u00f3digo Civil<\/p>\n","protected":false},"author":3,"featured_media":26784,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[691,50],"tags":[],"class_list":["post-26783","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-congreso"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/26783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=26783"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/26783\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/26784"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=26783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=26783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=26783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}