{"id":25722,"date":"2020-09-16T10:00:00","date_gmt":"2020-09-16T10:00:00","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=25722"},"modified":"2023-07-21T16:30:51","modified_gmt":"2023-07-21T21:30:51","slug":"evitar-una-nueva-decada-perdida-para-el-bienestar-urge-una-ley-de-ingreso-vital-de-emergencia","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/evitar-una-nueva-decada-perdida-para-el-bienestar-urge-una-ley-de-ingreso-vital-de-emergencia\/","title":{"rendered":"Evitar una nueva d\u00e9cada perdida para el bienestar: urge una ley de Ingreso Vital de Emergencia"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>M\u00e1s pobreza, menos empleo y disminuci\u00f3n a cuidados p\u00fablicos: Patricia Mercado Castro<\/strong><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Durante la Glosa del Segundo Informe del Ejecutivo, la senadora pidi\u00f3 construir un acuerdo pol\u00edtico<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Cd. de M\u00e9xico. 16 de septiembre de 2020.- Durante el an\u00e1lisis de la glosa del segundo informe respecto a la pol\u00edtica social, la senadora Patricia Mercado Castro sostuvo que pese a que una de las prioridades del gobierno actual es elevar el nivel de vida de la poblaci\u00f3n, particularmente, de la m\u00e1s desprotegida y vulnerable, los datos demuestran que las metas est\u00e1n lejos de cumplirse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHoy tenemos una situaci\u00f3n de emergencia donde hay una clara p\u00e9rdida de ingresos y trabajo y no se informa de un programa espec\u00edfico para enfrentarla. Si queremos evitar una ca\u00edda a\u00fan mayor en el consumo; si queremos evitar un deterioro irreversible en los niveles de vida de la poblaci\u00f3n; si queremos evitar una nueva d\u00e9cada perdida para el bienestar, debemos echar a andar el Ingreso Vital de Emergencia\u201d, sostuvo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existe un programa titulado \u201cPara el bienestar de las personas en emergencia social o natural\u201d, que seg\u00fan el Informe del Ejecutivo, atendi\u00f3 apenas a 211,798 personas, el 99 por ciento con apoyos en especie.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La senadora se\u00f1al\u00f3 que ese programa pudo y puede, todav\u00eda, ser la base para desplegar un Ingreso Vital de Emergencia que evite caer en una cat\u00e1strofe social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQuiero pedir expl\u00edcitamente que el grupo de trabajo que hemos integrado aqu\u00ed configure una propuesta, que sea viable para un gran acuerdo pol\u00edtico en este senado de la Rep\u00fablica\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Empleo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La legisladora se\u00f1al\u00f3 que la crisis econ\u00f3mica ha afectado negativamente la vida de millones de mexicanos y mexicanas, puesto que de 12 millones, que seg\u00fan el INEGI en abril dejaron de formar parte de Poblaci\u00f3n Econ\u00f3micamente Activa (PEA), s\u00f3lo 7.2 millones regresaron en julio. Adem\u00e1s, la mayor\u00eda regres\u00f3 a empleos con salarios precarios, con deudas, menores ingresos y sin prestaciones b\u00e1sicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, indic\u00f3 que 150 mil peque\u00f1os comercios han quebrado, sus empleados han quedado en el desamparo o se han lanzado a la informalidad. \u201dFrente a esta realidad, no vemos en el informe medidas de emergencia o extraordinarias para detener esta ca\u00edda libre donde, seg\u00fan CONEVAL, las consecuencias ser\u00e1n el aumento de la pobreza y la extrema pobreza\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que de acuerdo con el Consejo Nacional de Evaluaci\u00f3n de la Pol\u00edtica de Desarrollo Social, CONEVAL, casi la mitad de los programas prioritarios no tienen claro el problema que plantean resolver; 8 de 17 no han alcanzado ni siquiera la mitad de la poblaci\u00f3n objetivo que se fijaron o bien no presentan informaci\u00f3n sobre el grado de cobertura alcanzado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;En cuanto a la pol\u00edtica social, el informe se presenta en un formato tradicional. Acumula cifras, enlista acciones. \u201cQuisi\u00e9ramos compartir el optimismo del Ejecutivo, pero la desigualdad se est\u00e1 profundizando. Ustedes, nosotras, senadoras y senadores, conocemos muy bien el territorio, imaginemos el riesgo inminente de que 16 millones de personas caigan en la pobreza o en la extrema pobreza\u201d, puntualiz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pol\u00edtica para el cuidado<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su participaci\u00f3n, la senadora refiri\u00f3 que seg\u00fan datos del Instituto Belisario Dom\u00ednguez, los recursos asignados a servicios de cuidado p\u00fablicos para poblaci\u00f3n abierta y derechohabiente disminuyeron 17 por ciento de 2018 a 2019, y 11 por ciento de 2019 a 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El Programa de Estancias Infantiles para Madres Trabajadoras que cubr\u00eda a m\u00e1s de 300 mil beneficiarias, hoy con el nuevo programa de transferencias apenas llega a 115 mil ni\u00f1as y ni\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detall\u00f3 que el programa de fomento a la econom\u00eda social apenas se menciona, por lo cual podr\u00eda ser una excelente estrategia como proponen economistas feministas para desarrollar una robusta econom\u00eda del cuidado, que genere empleos, ingresos, seguridad social y garantice el derecho de las personas vulnerables a ser cuidadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Medio ambiente<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La senadora Patricia Mercado Castro celebr\u00f3 la nueva relaci\u00f3n del Estado con los pueblos ind\u00edgenas y afromexicanos; sin embargo, indic\u00f3 que la amenaza del cambio clim\u00e1tico y la inversi\u00f3n p\u00fablica no puede separarse de los derechos, de la sostenibilidad y de la justicia social.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl territorio es mucho m\u00e1s que un sitio de aprovechamiento; es, sobre todo, el espacio de convivencia de estas comunidades, por lo que se vuelve de vital importancia escuchar y consultar a todas las expresiones de quienes se organizan en defensa de la tierra y del territorio\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Programas sociales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respecto a los programas J\u00f3venes construyendo el Futuro y Sembrando Vidas, la legisladora se\u00f1al\u00f3 que son dos programas que pese a generar empleo y capacidades laborales para quienes tienen menos oportunidades no tienen una buena evaluaci\u00f3n de CONEVAL respecto a sus objetivos, metas y resultados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa l\u00f3gica de la pol\u00edtica social es corregir una situaci\u00f3n de injusticia o desigualdad. Se detecta la desventaja, por ejemplo, que enfrentan mujeres, estudiantes, personas j\u00f3venes, ind\u00edgenas, adultas mayores, y surgen programas para corregir esa desigualdad\u201d, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, la legisladora se\u00f1al\u00f3 que el proyecto de presupuesto para el 2021 ilustra la gravedad de la crisis. \u201cProponemos no hablar de ganadores y perdedores, pues hasta ahora las p\u00e9rdidas no distinguen niveles. El gran acuerdo planetario de \u201cNo dejar a nadie atr\u00e1s\u201d nos obliga a incluir todas las oportunidades y posibilidades de desarrollo, con todas y todos sus actores, los que m\u00e1s tienen y los que no, y as\u00ed dise\u00f1ar con orden, transparencia y rendici\u00f3n de cuentas las puertas de salida de la pobreza, la carencia y desigualdad en el acceso a los derechos\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPara hacer una transformaci\u00f3n hist\u00f3rica, obras son amores, y no buenas razones. Acompa\u00f1emos con instituciones s\u00f3lidas y recursos suficientes esa aspiraci\u00f3n de igualdad en la que coincidimos al llevar los derechos sociales y econ\u00f3micos a la Constituci\u00f3n. Hag\u00e1moslo cada d\u00eda, en cada acto, sin desacreditar a quienes reclaman. Hag\u00e1moslo reconociendo nuestra representaci\u00f3n diversa y plural\u201d, finaliz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Urge Ley del Ingreso M\u00ednimo Vital<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En mayo pasado la legisladora de Movimiento Ciudadano propuso la Ley de Ingreso M\u00ednimo Vital, pretende hacer frente a situaciones especiales de emergencia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de ella, se conceder\u00edan tres mil 600 pesos como m\u00ednimo, a las personas que perdieron su empleo o vieron disminuidos sus ingresos de manera considerable, por un periodo de tres a cinco meses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esos recursos no representan m\u00e1s del uno por ciento del Producto Interno Bruto y menos del cuatro por ciento del presupuesto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En M\u00e9xico, hay una gran cantidad de personas en el autoempleo y m\u00e1s de la mitad de quienes trabajan por un ingreso, lo hacen desde la informalidad, los cuales, no tienen ning\u00fan derecho laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ingreso es un derecho que est\u00e1n perdiendo las personas que fueron despedidas, se quedaron sin empleo o las descansaron. No nos podemos quedar en casa si no tenemos los recursos para poder tener una vida cotidiana m\u00e1s o menos saludable, puntualiz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s pobreza, menos empleo y disminuci\u00f3n a cuidados p\u00fablicos: Patricia Mercado Castro<\/p>\n","protected":false},"author":3,"featured_media":25723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[691,50],"tags":[],"class_list":["post-25722","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-congreso"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/25722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=25722"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/25722\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/25723"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=25722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=25722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=25722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}