{"id":23804,"date":"2020-08-10T16:42:43","date_gmt":"2020-08-10T16:42:43","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=23804"},"modified":"2023-07-21T16:27:08","modified_gmt":"2023-07-21T21:27:08","slug":"oaxaca-212","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/oaxaca-212\/","title":{"rendered":"Para que se pusiera a barrer, le dieron la regidur\u00eda de Ornato"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Rosita Aguilar, un caso de violencia pol\u00edtica en raz\u00f3n de g\u00e9nero<\/strong><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Un a\u00f1o ocho meses despu\u00e9s y dos JDC a su favor no hacen la diferencia, sigue sin asumir su cargo de regidora<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Soledad Jarqu\u00edn Edgar<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 10 de agosto, 2020.- \u201cPara que se ponga a barrer\u201d, le dijeron a Rosita Aguilar cuando asumi\u00f3 su cargo como regidora de Ornato, una que no exist\u00eda y que asegura a\u00fan no existe porque un a\u00f1o ocho meses despu\u00e9s, se le sigue negando la oportunidad de ejercer el cargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A diferencia del resto del Cabildo, a Rosa Mar\u00eda Aguilar Antonio se le neg\u00f3 tomar protesta el 1 de enero de 2019, tras obtener, por la v\u00eda independiente un lugar como regidora, luego de ser derrotada en su intenci\u00f3n de reelegirse como presidenta municipal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue el pleno del Tribunal Electoral del Estado de Oaxaca (TEEO) quien resolvi\u00f3 a su favor el 19 de marzo de 2019 (Expediente JDC 15\/2019), lo anterior en consideraci\u00f3n que se le hab\u00edan conculcado sus derechos a ser votada, en la vertiente de ejercicio del cargo. Finalmente, y despu\u00e9s de muchos tr\u00e1mites, tom\u00f3 protesta el 1 de junio de 2019, es decir, seis meses despu\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El problema fundamental es que jam\u00e1s la actual presidenta municipal, Araceli Garc\u00eda Hern\u00e1ndez, de extracci\u00f3n priista, le permiti\u00f3 sumir realmente su cargo, no tiene un lugar de trabajo, no es llamada a las sesiones de Cabildo ni tampoco recibe remuneraci\u00f3n alguna por su trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe se\u00f1alar que de acuerdo con la entonces magistrada ponente Elizabeth Bautista Velasco, en dicha resoluci\u00f3n del Juicio para la Protecci\u00f3n de Derechos Pol\u00edtico Electorales del Ciudadano (JDC), cuando Rosita Aguilar, todav\u00eda no le tomaban la protesta al cargo, ninguno de los actos anteriores era constitutivos de violencia pol\u00edtica por razones de g\u00e9nero, esto en base al Protocolo para Atender la Violencia Pol\u00edtica contra las Mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rosa Mar\u00eda Aguilar Antonio, quien fuera presidenta municipal de Reforma de Pineda &#8211; un municipio de unos dos mil 500 habitantes ubicado en la regi\u00f3n del Istmo de Tehuantepec- en el bienio 2017-2018, fue la primera presidenta municipal electa en M\u00e9xico por la v\u00eda de las candidaturas independientes, lo que ocurri\u00f3 en 2017, cuando por dos votos gan\u00f3 a su m\u00e1s cercana contrincante y con una ministraci\u00f3n de apenas mil 300 pesos.<\/p>\n\n\n\n<figure class=\"wp-block-embed-facebook aligncenter wp-block-embed is-type-video is-provider-facebook\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.facebook.com\/rosamariai.aguilarantonio\/videos\/3500612563304714\/?t=28\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Durante ese tiempo, Rosita Aguilar, recuerda que hizo una gesti\u00f3n apegada a las demandas de su pueblo, \u201cyo no hice promesas a mi pueblo, yo hice compromisos\u201d, dice en entrevista telef\u00f3nica con SemM\u00e9xico,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por la falta de espacio para trabajar y la falta de pago de las dietas correspondientes, Rosa Mar\u00eda Aguilar inici\u00f3 un nuevo JDC\/125\/2019. En este \u00faltimo tambi\u00e9n exig\u00eda el cambio de regidur\u00eda ya que la mun\u00edcipe priista Araceli Garc\u00eda Hern\u00e1ndez, refuerza con los estereotipos de g\u00e9nero.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-09-at-2.07.18-PM-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-23805\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El resultado nuevamente favorece a Rosita Aguilar Antonio y se\u00f1ala que s\u00ed hay violencia polic\u00eda en raz\u00f3n de g\u00e9nero, ordena medidas de protecci\u00f3n que no se han cumplido y que la presidenta municipal, Garc\u00eda Hern\u00e1ndez que le pague las dietas que no ha cubierto. El cambio de regidur\u00eda, un espacio para el desempe\u00f1o de sus actividades y que se a convocada a las sesiones de cabildo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta ahora dice Rosita Aguilar no ha sucedido nada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me queda claro que a la presidenta municipal no le importan las resoluciones del TEEO ni que la multen\u2026lo que ella no quiere escuchar en el Cabildo es mi nombre, asienta la regidora electa que no ha desempe\u00f1ado su encargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aguilar Antonio sostiene que tampoco hay inter\u00e9s de otras instancias de gobierno por resolver el problema, como es el caso del Ejecutivo, donde la oficina responsable de la pol\u00edtica interna de Oaxaca, la Secretar\u00eda General de Gobierno, a cargo de H\u00e9ctor Anuar Mafud Mafud, donde desde el primer momento la reconocen como regidora, no les interesa dar un paso m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indignada, Rosita Aguilar dice que hace poco pens\u00f3 en dejarlo todo, pero un grupo de amigas le aconsejaron seguir adelante, hacer visible esta injusticia cometida en su contra por una actora priista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La expresidenta municipal de Reforma de Pineda, maestra jubilada, reconoce que perdi\u00f3 en su pretensi\u00f3n de ser reelecta en las elecciones de julio de 2017 y acusa que la entonces candidata priista hoy presidenta municipal habr\u00eda ofrecido entre tres y cuatro mil pesos a cada persona que votara por ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que en su momento hizo la denuncia de lo que ocurri\u00f3, pero no pas\u00f3 nada, excepto que ha sido amenazada de muerte en m\u00e1s de una ocasi\u00f3n, adem\u00e1s de los muchos insultos que ha recibido de parte de la presidenta municipal priista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Rosita Aguilar le toc\u00f3 enfrentar el duro reto de hacer todas las gestiones necesarias, tocar puerta tras puerta, organizar a la gente y tras los da\u00f1os ocasionados por el terremoto del 8 de septiembre de 2017, donde los da\u00f1os en casas habitaci\u00f3n alcanzaron a unas 500 viviendas, de acuerdo con una entrevista que en febrero de 2018 le hizo esta reportera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA diferencia de otros municipios, en Reforma de Pineda la gente se organiz\u00f3 desde el primer d\u00eda para atender la emergencia de las primeras horas y para resolver la alimentaci\u00f3n de la gente de ese municipio y de otras poblaciones aleda\u00f1as que llegaron buscando ayuda\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En aquella misma entrevista para SemM\u00e9xico, Rosita Aguilar adelant\u00f3 su intenci\u00f3n de buscar ser reelecta como mun\u00edcipe, por la v\u00eda independiente, pero esta vez los votos no alcanzaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy, cuenta con orgullo que de aquella tragedia salieron librados en su pueblo, al menos 150 viviendas fueron totalmente reconstruidas, se reestablecieron los servicios de agua potable y electricidad, as\u00ed como el alumbrado p\u00fablico da\u00f1ado por aquel movimiento tel\u00farico de m\u00e1s de 8 grados de intensidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n realiz\u00f3 otras obras importantes de infraestructura, abri\u00f3 una casa de la cultura e impuls\u00f3 el deporte, pero hoy, dice ella, lo que m\u00e1s extra\u00f1a la gente son las despensas que cada mujer, de cualquier edad, recib\u00edan y las becas que reparti\u00f3 a los y las estudiantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso, asegura Rosita Aguilar no la quiere la actual presidenta municipal, \u201cno quiere ni o\u00edr mi nombre, mientras yo hice m\u00e1s de 20 obras en dos a\u00f1os, es claro para la gente que ella no ha hecho nada\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/sje<\/p>\n","protected":false},"excerpt":{"rendered":"<p> \u201cPara que se ponga a barrer\u201d, le dijeron a Rosita Aguilar cuando asumi\u00f3 su cargo como regidora de Ornato<\/p>\n","protected":false},"author":3,"featured_media":23806,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[691,54],"tags":[],"class_list":["post-23804","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/23804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=23804"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/23804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/23806"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=23804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=23804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=23804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}