{"id":2364,"date":"2018-07-13T23:11:31","date_gmt":"2018-07-13T23:11:31","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=2364"},"modified":"2023-07-21T14:32:18","modified_gmt":"2023-07-21T19:32:18","slug":"haremos-politica-con-honestidad-dice-hernandez-mora","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/haremos-politica-con-honestidad-dice-hernandez-mora\/","title":{"rendered":"Haremos pol\u00edtica con honestidad, dice Hern\u00e1ndez Mora"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.semmexico.com\/gallery-post.php?id=5303#\">Lizbeth \u00c1lvarez<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Cd. de M\u00e9xico, 12 julio 2018.- Minerva Citlalli Hern\u00e1ndez Mora, Senadora electa por la colaci\u00f3n Juntos Haremos Historia, asegur\u00f3 que esta es una oportunidad para discutir todas las leyes desde una perspectiva de g\u00e9nero, entre ellas cit\u00f3 el derecho a decidir y legalizar la interrupci\u00f3n del embarazo en todo el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entrevistada al t\u00e9rmino de la reuni\u00f3n de legisladores de ambas c\u00e1maras electas por la coalici\u00f3n Juntos Haremos Justicia (Morena, PT y PES) con el presidente electo Andr\u00e9s Manuel L\u00f3pez Obrador, la futura Senadora apunt\u00f3 que al haber obtenido por primera vez el triunfo un gobierno de izquierda se debe traducir en una oportunidad para garantizar todos los derechos a las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cArgentina ya puso el ejemplo, se tiene que empezar la discusi\u00f3n sobre el aborto\u201d, apunt\u00f3 Hern\u00e1ndez Mora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAndr\u00e9s est\u00e1 interesado en que todos los que llegamos por el voto de la Coalici\u00f3n Juntos Haremos Historia, tengamos claridad de lo que la gente espera de nosotros. Se tiene que hacer pol\u00edtica con honestidad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La joven senadora de 28 a\u00f1os de edad, asegur\u00f3 que, para L\u00f3pez Obrador, as\u00ed como para las y los futuros diputados y senadores de esa coalici\u00f3n se tomar\u00e1n las decisiones con la gente y sin que afecten a la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/la\/sj<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lizbeth \u00c1lvarez SemM\u00e9xico, Cd. de M\u00e9xico, 12 julio 2018.- Minerva Citlalli Hern\u00e1ndez Mora, Senadora electa por la colaci\u00f3n Juntos Haremos Historia, asegur\u00f3 que esta es una oportunidad para discutir todas las leyes desde una perspectiva de g\u00e9nero, entre ellas cit\u00f3 el derecho a decidir y legalizar la interrupci\u00f3n del embarazo en todo el pa\u00eds. Entrevistada [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2365,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[689,33],"tags":[],"class_list":["post-2364","post","type-post","status-publish","format-standard","has-post-thumbnail","category-689","category-elecciones-2018"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/2364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=2364"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/2364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/2365"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=2364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=2364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=2364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}