{"id":21310,"date":"2020-05-29T22:53:08","date_gmt":"2020-05-29T22:53:08","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=21310"},"modified":"2023-07-21T16:23:15","modified_gmt":"2023-07-21T21:23:15","slug":"veracruz-59","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/veracruz-59\/","title":{"rendered":"En riesgo mujeres ind\u00edgenas de Zongolica por recorte de Gobierno Federal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por: Ana Alicia\nOsorio<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/Testigo P\u00farpura. Xalapa, Veracruz. 29 de mayo\n2020.- En Zongolica hay 14 mujeres que ayudan a otras a salir de la violencia:\nles dan asesor\u00eda legal, hacen traducciones del nahual al espa\u00f1ol en la Fiscal\u00eda\ny otras dependencias, dan charlas para identificar la violencia y un sin fin de\nactividades. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ellas forman parte de la Casa de la Mujer Ind\u00edgena\n\u201cichikahualistli&nbsp; sihuame\u201d (La Fortaleza\nde las Mujeres) que ahora no sabe c\u00f3mo seguir\u00e1n en operaci\u00f3n ante el recorte\ndel Gobierno Federal realiz\u00f3 y que dej\u00f3 sin recurso a las 35 sitios de ese tipo\nque existen en el pa\u00eds. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Karina Thiel Cano, coordinadora de la Casa de la Mujer\nInd\u00edgena en Zongolica, explic\u00f3 que este recorte afectar\u00e1 de manera directa a\nlas cientos de mujeres que atienden al a\u00f1o para darles asesor\u00eda y a las otras\ncientos a quienes les dan talleres para ense\u00f1arles a identificar la violencia. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cAl a\u00f1o vamos\nateniendo de 900 a mil mujeres, a la semana se est\u00e1n atendiendo de tres,\ncuatro, hasta cinco casos al d\u00eda, aproximadamente son unos 20 casos a la\nsemana, son much\u00edsimas mujeres en riego (\u2026) acuden con nosotras porque somos\nalgo neutral y sin en cambio si van a los ayuntamientos ya el esposo es\ncompadre del presidente, de la s\u00edndica o que trabaja en el ayuntamiento y ya no\nles da el mismo servicio, la misma atenci\u00f3n y por eso acuden con nosotras\u201d, cont\u00f3.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La regi\u00f3n de Zongolica es una zona ind\u00edgena en el centro de\nVeracruz donde una parte importante de la poblaci\u00f3n no habla espa\u00f1ol y est\u00e1 en\nla sierra que se conoce por el mismo nombre. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">All\u00ed, en 2007 fue asesinada Ernestina Ascencio (una mujer\nind\u00edgena de 73 a\u00f1os que presuntamente fue violada y asesinada por soldados y\ncuyo caso permanece en la impunidad) y luego vinieron otros asesinatos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces algunas organizaciones voltearon a la regi\u00f3n y\nempezaron&nbsp; a juntar y capacitar a las\nmujeres que ejerc\u00edan alg\u00fan liderazgo en las comunidades para que atendieran la\nviolencia contra las mujeres: as\u00ed naci\u00f3 la Casa de la Mujer Ind\u00edgena. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cEmpezamos a\ncapacitarnos en diferentes temas, empezamos a asistir a especialidades (\u2026)\nestamos recibiendo diferentes capacitaciones, nos estamos actualizando tanto en\nderecho, en leyes, porque como somos mujeres de haber vivido violencia pues no\nten\u00edamos esa sensibilidad de poder escuchar a otra mujer que te cuente lo que\nest\u00e1 viviendo m\u00e1s sin en cambio ahorita ya las podemos escuchar\u201d, narr\u00f3 Thiel\nCano. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde entonces reciben durante seis meses (de julio a\ndiciembre) recursos el Instituto Nacional de los Pueblos Ind\u00edgenas; el resto\ndel a\u00f1o lo hacen con dinero propio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero este a\u00f1o es distinto: el gobierno federal decidi\u00f3\nredigirir ese dinero para atender la contingencia sanitaria por el coronavirus\ny dej\u00f3 sin recursos a las Casas de la Mujer Ind\u00edgena. El propio gobierno se\u00f1al\u00f3\nque buscar\u00e1n fondos internacionales para subsanar el faltante, pero est\u00e1 en\nincertidumbre. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cEs necesario que\nnosotras tengamos un recurso ya etiquetado para nosotras y que no se nos menee,\nporque todas somos la mayor\u00eda de las que laboramos ah\u00ed somos madres solteras y\npues tenemos necesidades m\u00e1s que nada, somos de diferentes comunidades\u201d, sentenci\u00f3\nThiel Cano. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cAhorita con lo del\nCOVID mantenemos cerradas las instalaciones m\u00e1s sin en cambio no nos\ndesatendemos de esa labor, en nuestras propias viviendas hemos atendido a\nmujeres que vienen a buscarnos a pedir asesor\u00eda (\u2026) somos mujeres que ya nos\nreconoce la zona, ya nos ubica donde vivimos y dicen fui a la oficina estaba\ncerrado y vine a buscarla hasta ac\u00e1\u201d, dijo sobre la importancia de su labor. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La labor que ellas hacen no la cumple ning\u00fan organismo en la\nzona. La Fiscal\u00eda General del Estado no tiene peritos traductores suficientes\n(solo cuenta con uno para toda la regi\u00f3n seg\u00fan la coordinadora del CAMI) por lo\nque son ellas quienes deben acudir a las denuncias o los juicios de las mujeres\nque vivieron violencia. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los talleres que brindan en&nbsp;\nlas comunidades m\u00e1s remotas para que otras mujeres detecten la violencia\ntampoco los hacen otras instituciones. Y as\u00ed sucede con sus otras funciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cLa mujer que se\nacerque a nosotras ser\u00e1 atendida pero ya no asistir\u00edamos a las comunidades que\nes lo que se requiere m\u00e1s, es prevenir la violencia, no nada m\u00e1s atenderla, es\nprevenir\u201d, asever\u00f3 Thiel Cano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Zongolica hay 14 mujeres que ayudan a otras a salir de la violencia: les dan asesor\u00eda legal, hacen traducciones del nahual al espa\u00f1ol en la Fiscal\u00eda y otras dependencias.<\/p>\n","protected":false},"author":3,"featured_media":21311,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[691,54],"tags":[],"class_list":["post-21310","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/21310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=21310"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/21310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/21311"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=21310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=21310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=21310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}