{"id":20945,"date":"2020-05-21T20:11:35","date_gmt":"2020-05-21T20:11:35","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=20945"},"modified":"2023-07-21T16:19:52","modified_gmt":"2023-07-21T21:19:52","slug":"con-funerales-virtuales-despiden-a-personas-migrantes-fallecidas-por-covid-19","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/con-funerales-virtuales-despiden-a-personas-migrantes-fallecidas-por-covid-19\/","title":{"rendered":"Con funerales virtuales despiden a personas migrantes fallecidas por COVID 19"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Una manera de preservar la tradici\u00f3n cat\u00f3lica y una costumbre de las poblaciones<\/strong><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Buscan la proximidad con sus familias y paisanos como estrategia para la sobrevivencia <\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Patricia Brise\u00f1o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico,\nOaxaca, 21 de mayo, 2020.- Familiares de personas de origen oaxaque\u00f1o fallecidas\npor COVID-19 en algunas ciudades de los Estados Unidos, durante la contingencia\npor la pandemia, realizaron funerales virtuales para que estuvieran presentes amistades\ny familiares desde su comunidad de origen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las\nrestricciones por la distancia social y la lejan\u00eda entre pa\u00edses, no fueron\nobst\u00e1culo para que personas migrantes buscaran la proximidad con su gente en el\nduelo, con reservas cumplieron con el rito de la velaci\u00f3n, rezos y \u201clevantada\nde la cruz\u201d como es costumbre en la pr\u00e1ctica de la religi\u00f3n cat\u00f3lica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En\nel municipio conurbado de Tlacolula de Matamoros, a unos 30 kil\u00f3metros al\noriente de la capital, habitantes participaron en los funerales virtuales y\n\u201cacompa\u00f1aron\u201d a las y los dolientes al velorio desde cualquier dispositivo\nm\u00f3vil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elizabeth\nS\u00e1nchez, habitante de esta localizada zapoteca del Valle de Oaxaca, coment\u00f3 que\neste tipo de \u201cacompa\u00f1amiento\u201d a distancia con quienes no viven en la localidad,\nocurr\u00eda de manera espor\u00e1dica desde el a\u00f1o 2019, aprovechando las redes\nsociales, as\u00ed como la aplicaci\u00f3n gratuita de WhatsApp.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3\nque los y las migrantes buscan la proximidad con los suyos como estrategia para\nla sobrevivencia y la reproducci\u00f3n identitaria en un medio diferente; una\nmayor\u00eda desea mantener viva sus tradiciones y costumbres\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo\nque a pesar de la distancia f\u00edsica, prevalece el v\u00ednculo con lo que consideran\nsuyo, por lo que en tiempos de la pandemia fue posible sumarse a la transmisi\u00f3n\n\u201cen tiempo real\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\npartir de los decesos presentados por el COVID-19, se ha vuelto com\u00fan recibir\nla invitaci\u00f3n a sumarse al funeral del o la connacional, sin el cuerpo presente\ny con un n\u00famero reducido de personas .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En\nlos funerales virtuales se comparten fotos y frases de quien ha perecido.\nAsimismo, se ofrece apoyo solidario y econ\u00f3mico a las familias, como se\nacostumbre en su tierra natal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las\ny los deudos tuvieron que despedir a su ser querido \u201cacompa\u00f1ados\u201d por un\ntel\u00e9fono celular, que de vez en cuando \u201ccongelaba\u201d la imagen y requer\u00eda cargar\nla pila, pero esto no mengu\u00f3 la tradici\u00f3n apegada a los usos y costumbres del pueblo.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta\nhace unos a\u00f1os, las familias enviaban videos de las fiestas o funerales a sus\npaisanas y paisanos radicados en Estados Unidos, ahora se hace forma\ninstant\u00e1nea a trav\u00e9s de redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nota relativa:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El\nInstituto Oaxaque\u00f1o de Atenci\u00f3n al Migrante (IOAM) dio a conocer que son 71 el\nn\u00famero preliminar de migrantes oaxaque\u00f1os fallecidos por COVID-19 en Estados\nUnidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La\ndirectora general del IOAM, A\u00edda Ruiz Garc\u00eda, refiri\u00f3 que su administraci\u00f3n\ntrabaja de manera coordinada con los 50 consulados de M\u00e9xico en el vecino pa\u00eds\ndel norte, con el objetivo de brindar una atenci\u00f3n oportuna a los migrantes que\nas\u00ed lo necesiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indic\u00f3\nque al corte del 10 de mayo, el gobierno de Oaxaca ha gestionado la\nrepatriaci\u00f3n de seis migrantes fallecidos por Covid-19, puesto que la mayor\u00eda\nhan sido reclamados por familiares que radican tambi\u00e9n en los Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/pb\/sj&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una manera de preservar la tradici\u00f3n cat\u00f3lica y una costumbre de las poblaciones<\/p>\n","protected":false},"author":3,"featured_media":20946,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[691,135],"tags":[],"class_list":["post-20945","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-emergencia-sanitaria-covid-19"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/20945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=20945"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/20945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/20946"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=20945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=20945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=20945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}