{"id":20399,"date":"2020-05-08T21:50:31","date_gmt":"2020-05-08T21:50:31","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=20399"},"modified":"2023-07-21T16:18:46","modified_gmt":"2023-07-21T21:18:46","slug":"oaxaca-190","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/oaxaca-190\/","title":{"rendered":"Importante que mujeres embarazadas se realicen la prueba del VIH: Coesida"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Advierten que es importante no amamantar al beb\u00e9 en caso de que la madre sea portadora del VIH<\/strong><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Los CAPACITS brindan atenci\u00f3n durante el embarazo para prevenir la transmisi\u00f3n vertical <\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico, Oaxaca, 8 de mayo, 2020.- Aunque la leche materna es un alimento ideal para un o una beb\u00e9, por\nlos nutrientes que contiene y que necesita para su crecimiento y desarrollo;\nmujeres con el Virus de Inmunodeficiencia Humana (VIH), deben evitarlo, inform\u00f3\nla directora general del Consejo Estatal para la Prevenci\u00f3n y Control del Sida\n(Coesida), Gabriela Vel\u00e1squez Rosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior indic\u00f3, es con el fin de evitar la transmisi\u00f3n vertical\ndel VIH, el cual se da cuando la mam\u00e1 desconoce su estado ante el virus y lo\ntransmite a su beb\u00e9 durante el embarazo, parto o lactancia, explica en un\nbolet\u00edn de prensa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn el caso de que una mujer con VIH se encuentre embarazada y no\nreciba el tratamiento y la atenci\u00f3n m\u00e9dica adecuada, es altamente probable que\nsu beb\u00e9 nazca con la infecci\u00f3n\u201d, mencion\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tambi\u00e9n Responsable Estatal del Programa de VIH\/Sida, destac\u00f3 que,\nen el caso de dar positivo a la prueba de detecci\u00f3n del VIH, en los Centros\nAmbulatorios para la Prevenci\u00f3n y Atenci\u00f3n del Sida e Infecciones de\nTransmisi\u00f3n Sexual (CAPASITS), se les brinda la atenci\u00f3n necesaria durante el\nembarazo, esto con el fin de prevenir la transmisi\u00f3n de la madre a su beb\u00e9, as\u00ed\ncomo un tratamiento antirretroviral para el reci\u00e9n nacido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando a una mujer embarazada se le detecta el virus, inmediatamente\nse le proporciona el tratamiento antirretroviral y se le da seguimiento, de\nigual manera se le indica que el parto debe ser por ces\u00e1rea, as\u00ed como que\ndeber\u00e1 evitar amamantar a su beb\u00e9, ya que la leche materna es un fluido\naltamente infeccioso.\u201d, destac\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello exhort\u00f3 a toda la poblaci\u00f3n a realizarse la prueba del VIH\ndos veces al a\u00f1o, y en especial a todas las mujeres que planean embarazarse o\nque ya lo est\u00e9n, a que se la realicen cada trimestre, esto con el prop\u00f3sito de\nevitar que su beb\u00e9 nazca con la infecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Oaxaca, la prueba de detecci\u00f3n, pueden ser realizada en los\nCAPASITS de San Bartolo Coyotepec, Salina Cruz y Santiago Pinotepa Nacional, o\na trav\u00e9s de la Unidades M\u00f3viles de detecci\u00f3n del VIH; sin embargo, por\ncontingencia del Covid-19, es importante llamar al 800 713 4741 para informarse\nsobre los horarios de atenci\u00f3n\u201d mencion\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los CAPACITS brindan atenci\u00f3n durante el embarazo para prevenir la transmisi\u00f3n vertical <\/p>\n","protected":false},"author":3,"featured_media":20400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[691,51],"tags":[],"class_list":["post-20399","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-ejecutivo"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/20399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=20399"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/20399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/20400"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=20399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=20399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=20399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}