{"id":20272,"date":"2020-05-06T02:02:49","date_gmt":"2020-05-06T02:02:49","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=20272"},"modified":"2023-07-21T16:18:48","modified_gmt":"2023-07-21T21:18:48","slug":"se-apaga-la-vida-de-jaime-montejo-fundador-de-brigada-callejera","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/se-apaga-la-vida-de-jaime-montejo-fundador-de-brigada-callejera\/","title":{"rendered":"Se apaga la vida de Jaime Montejo, fundador de Brigada Callejera"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li>E<strong>lvira Madrid se recupera en casa de enfermedad respiratoria, llueven mensajes de solidaridad.<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Redacci\u00f3n La Coperacha<\/strong><br>SemM\u00e9xico\/La Coperacha. Ciudad de M\u00e9xico \/\/ 05 de mayo de 2020.- Este d\u00eda a las 03 de la madrugada la vida de Jaime Montejo se apag\u00f3. Hospitalizado con s\u00edntomas de Covid-19 en el Hospital General de M\u00e9xico, Jaime ven\u00eda recuper\u00e1ndose con ox\u00edgeno hasta ayer. Brigada Callejera dio a conocer el deceso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elvira Madrid, en tanto, se recupera en su domicilio y le llueven mensajes de solidaridad. \u201cTenemos que hacer que Elvira se aferre a la vida\u201d,&nbsp; escribi\u00f3 Brigada Callejera, organizaci\u00f3n fundada por Jaime y Elvira hace m\u00e1s de dos d\u00e9cadas en momentos de lucha contra otros virus como el VIH y la desinformaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer reporte m\u00e9dico fue de neumon\u00eda aguda. La Torre Quir\u00fargica del Hospital General lo recibi\u00f3 luego de un periplo de tres d\u00edas en m\u00e1s de ocho hospitales de la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa lucha de toda su vida desde Colombia hasta M\u00e9xico fue de insurgencia, fue de revolucionar, fue como su madera y su tenacidad para crear cambios\u201d, describi\u00f3 a Jaime Montejo la Brigada Callejera en un mensaje por redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las \u00faltimas acciones de Jaime y de la Brigada Callejera fueron organizar de manera autogestiva ayuda (despensas y un comedor comunitario) para miles de trabajadoras sexuales que comenzaron a quedarse en situaci\u00f3n de calle y sin ingresos econ\u00f3micos por la emergencia sanitaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adherentes a la Sexta, denunciaron juntos, incontables veces, los abusos de polic\u00edas, de autoridades y de redes de padrotes y madrotas que explotaban a las trabajadoras sexuales en varias ciudades del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contribuyeron a organizar colectivamente a mujeres y trans. De ese esfuerzo&nbsp;<strong><a href=\"https:\/\/lacoperacha.org.mx\/de-prostitutas-a-trabajadoras-20-anios-de-lucha-por-reconocimiento\/\" target=\"_blank\" rel=\"noreferrer noopener\">nacieron &nbsp;cooperativas de trabajo sexual<\/a><\/strong>&nbsp;como \u00c1ngeles en Busca de la Libertad, as\u00ed como Mujer Libertad Sociedad Cooperativa, \u00e9sta la primera de Latinoam\u00e9rica. &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2014, junto con el bufete de abogados Tierra y Libertad y la Red Mexicana de Trabajo Sexual, lograron el reconocimiento del trabajo sexual en la Ciudad de M\u00e9xico como actividad l\u00edcita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los encuentros anuales de la Red Mexicana de Trabajo Sexual comenzaba en catarsis y lluvia de denuncias y conclu\u00edan en una comilona festiva, no faltaban los chilaquiles verdes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La antrop\u00f3loga Marta Lamas expresaba de Jaime y Elvira su respeto y agradecimiento por abrirle la oportunidad de investigar y conocer al sector de la calle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Implementaron en 2006 un proyecto de mercadeo social a partir de la f\u00e1brica de condones El Encanto, con su venta generan ingresos para las cl\u00ednicas de atenci\u00f3n para trabajadoras sexuales del pa\u00eds y para personas migrantes, as\u00ed como centros comunitarios en CDMX y Tapachula, Chiapas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ambiente de abusos en el entorno del trabajo sexual en La Merced, en Tlalpan, en Metro Revoluci\u00f3n, en la Zona Gal\u00e1ctica, se contrapon\u00eda con el festivo de las mujeres y trans que hac\u00edan la calle.&nbsp;<strong><a rel=\"noreferrer noopener\" href=\"https:\/\/archive.org\/details\/15.CumbiaDeBrigadaCallejera\" target=\"_blank\">La Cumbia de la Brigada Callejera<\/a><\/strong>, compuesta por Joel Castro dio cuenta de ello.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elvira Madrid se recupera en casa de enfermedad respiratoria, llueven mensajes de solidaridad.<\/p>\n","protected":false},"author":3,"featured_media":20273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[691,56],"tags":[],"class_list":["post-20272","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-redes"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/20272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=20272"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/20272\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/20273"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=20272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=20272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=20272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}