{"id":19364,"date":"2020-04-14T20:59:38","date_gmt":"2020-04-14T20:59:38","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=19364"},"modified":"2023-07-21T15:26:11","modified_gmt":"2023-07-21T20:26:11","slug":"chiapas-25","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/chiapas-25\/","title":{"rendered":"Hospitalizan a regidora de Chalchihuit\u00e1n tras accidente; denuncia atentado instruido por el ex-Consejo Municipal"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>La Secretar\u00eda General de Gobierno y Congreso del Estado de Chiapas son responsables por las graves omisiones en garantizarle medidas de protecci\u00f3n y respaldar al grupo que constituy\u00f3 el ex Consejo Municipal y permitir que sigan accionando con total impunidad, menciona Digna Ochoa.<\/strong><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong> Se requiri\u00f3 la realizaci\u00f3n de un ultrasonido de regi\u00f3n cervical, tele del t\u00f3rax, pierna y una tomograf\u00eda del cr\u00e1neo.<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por Yessica Morales\/Chiapas\nParalelo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/Chiapas Paralelo. Chiapas. 14 de abril 2020.- El\nComit\u00e9 de Derechos Humanos de Base \u201cDigna Ochoa\u201d inform\u00f3 de un atentado contra\nla regidora ind\u00edgena Gloria D\u00edaz G\u00f3mez del municipio de Chalchihuit\u00e1n, quien se\nencuentra internada en un hospital privado de San Crist\u00f3bal de Las Casas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Comit\u00e9 recibi\u00f3 el d\u00eda 4 de abril por la noche, un\ncomunicado urgente donde les solicitaban que se trasladaran de inmediato al\nhospital antes mencionado, ya que la regidora ind\u00edgena hab\u00eda sido v\u00edctima de un\natentado en contra de su vida y se encontraba internada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El CDH Digna Ochoa se traslad\u00f3 a las 21:00 horas, en la cual\nexpresan que la regidora se encuentra bajo observaci\u00f3n neurol\u00f3gica, estable al\nmomento del ingreso, con un dictamen m\u00e9dico de haber sufrido m\u00faltiples\ncontusiones provocado por \u201caccidente\u201d automovil\u00edstico, con una sutura en la\nregi\u00f3n frontal, policontundida, pron\u00f3stico reservado de evoluci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agust\u00edn D\u00edaz G\u00f3mez esposo de la v\u00edctima relat\u00f3 que alrededor\nde las 5:00 horas del d\u00eda 4 de abril ellos ven\u00edan en un autom\u00f3vil tipo Sentra\ncon Raymundo N como chofer, ambos situados en la parte trasera del conductor,\nal igual que su hijo, nuera y nieto de 2 a\u00f1os, cuando sin previo aviso un auto\ntipo Tsuru los embisti\u00f3 del lado donde iba su esposa, a la altura de la tijera\nde Tzabal\u00f3, municipio de Chenalh\u00f3, luego de embestirlos se dio a la fuga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El esposo se\u00f1ala que todos salieron con lesiones menores y\ns\u00f3lo la regidora recibi\u00f3 el impacto directo del autom\u00f3vil; cuenta que fueron\nauxiliados por autoridades de Chenalh\u00f3 y trasladaron a Gloria D\u00edaz al Centro de\nSalud de ese municipio, al no poder atenderla por carecer de insumos les\nsugirieron trasladarla a San Crist\u00f3bal de Las Casas, al ver el riesgo de vida\ndecidieron llevarla a un hospital privado para la inmediata atenci\u00f3n llegando a\nlas 11:00 de la ma\u00f1ana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se omite el nombre del hospital para protecci\u00f3n de la vida,\nseguridad e integridad personal de la regidora Gloria D\u00edaz G\u00f3mez quien se\nencuentra en estado estable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed mismo, manifiesta que gente cercana a la regidora\nquisieron advertirles que no se movieran, ellos ten\u00edan informaci\u00f3n acerca de\nsujetos pertenecientes al ex Consejo Municipal de ese municipio, quienes act\u00faan\ncon protecci\u00f3n de la Secretar\u00eda de Gobierno y el Congreso del Estado de\nChiapas, ellos la buscaban para atentar contra su vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda General de Gobierno del Estado ya tiene\nconocimiento sobre este suceso, miembros del Ayuntamiento de Chalchihuit\u00e1n les\nnotificaron v\u00eda tarjeta informativa, mencionan que no pueden se\u00f1alar lo\ncontrario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este hecho tiene antecedente al anuncio del 30 de marzo de\nlos regidores ind\u00edgenas de Chalchihuit\u00e1n de constituir una oficina alterna de\nla Presidencia Municipal en un domicilio particular de esa jurisdicci\u00f3n, no\nexisten condiciones para trabajar en el edificio por encontrarse ocupado de manera\nilegal por los exintegrantes del Consejo Municipal que sigue siendo respaldados\npor funcionarios del Gobierno y diputados del Congreso, menciona Digna Ochoa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Comit\u00e9 expresa que parte de la responsabilidad por no\nintervenir en la situaci\u00f3n y luego de que la Sala Superior del Tribunal\nElectoral del Poder Judicial de la Federaci\u00f3n (TEPJF) emiti\u00f3 sentencia que\nordenaba la restituci\u00f3n de regidores, a F\u00e9lix Santana Director General de\nEstrategias para la Atenci\u00f3n de Derechos Humanos de la Secretar\u00eda de Gobernaci\u00f3n;\nMisael Rojas Subsecretar\u00eda de Derechos Humanos, Migraci\u00f3n y Poblaci\u00f3n de la\nSecretar\u00eda de Gobernaci\u00f3n y Patricia Rojas secretaria particular del\nsubsecretario Alejandro Encinas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por todo lo anterior, el Comit\u00e9 Digna Ochoa les hace un\nllamado de atenci\u00f3n p\u00fablico para que asuman sus responsabilidades e intervengan\nen estos hechos graves violatorios de Derechos Humanos. Su indiferencia y\nnegligencia los hace c\u00f3mplices y responsables de lo que ocurra en ese municipio\njunto a la Secretaria de Gobernaci\u00f3n Olga S\u00e1nchez Cordero y Alejandro Encinas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Toman presidencia y\nexigen renuncia de la alcaldesa de Chalchihuit\u00e1n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recordemos que, la TEPJF revoc\u00f3 la sentencia emitida por la\nSala Regional Xalapa y la dictada por el Tribunal Electoral del Estado y dej\u00f3 sin\nefectos el Decreto 257 del Congreso, para desaparecer el Ayuntamiento de\nChalchihuit\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed mismo, el Comit\u00e9 alert\u00f3 de la tensi\u00f3n que se viv\u00eda en\nChalchihuit\u00e1n, por la retenci\u00f3n de 2 exregidores y 3 habitantes, as\u00ed como, el\nriesgo a la vida, seguridad e integridad personal de las exregidoras Glor\u00eda\nD\u00edaz G\u00f3mez y Marcela P\u00e9rez N\u00fa\u00f1ez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La regidora tambi\u00e9n llego a denunciar en el pasado la\nfalsificaci\u00f3n de documentos donde asume y renuncia a su puesto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cEs totalmente falso,\nya que nunca me present\u00e9 y fui convocada a esa supuesta comparecencia y sigo\nmanifestando p\u00fablicamente que se contin\u00faan violentando mis derechos pol\u00edticos y\nde g\u00e9nero al negarme a tomar protesta y que se han falsificado documentos y mi\nfirma\u201d dijo Gloria Diaz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 26 de julio del 2019 un grupo de personas que se\nidentificaron como militantes del Partido Revolucionario Institucional (PRI),\nentre ellos polic\u00edas municipales, la abordaron y amenazaron de muerte, ese\nmismo d\u00eda intentaron secuestrar a su esposo quien regresaba de San Crist\u00f3bal de\nLas Casas hacia su comunidad Jolitontic.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La regidora y su esposo refirieron tiempo atr\u00e1s que\nrecibieron amenazas de muerte, acciones de hostigamiento y seguimiento por\nparte de Ger\u00f3nimo Luna excandidato a presidente municipal del PT-Morena, V\u00edctor\nP\u00e9rez D\u00edaz, Rafael P\u00e9rez Orozco, Wilo Dom\u00ednguez, Nicodemo Aguilar abogado del\nmunicipio, para presionarla y presentar su renuncia en ese entonces.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se requiri\u00f3 la realizaci\u00f3n de un ultrasonido de regi\u00f3n cervical, tele del t\u00f3rax, pierna y una tomograf\u00eda del cr\u00e1neo.<\/p>\n","protected":false},"author":3,"featured_media":19365,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[691,56],"tags":[],"class_list":["post-19364","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-redes"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/19364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=19364"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/19364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/19365"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=19364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=19364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=19364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}