{"id":18995,"date":"2020-04-02T21:46:19","date_gmt":"2020-04-02T21:46:19","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=18995"},"modified":"2023-07-21T15:23:23","modified_gmt":"2023-07-21T20:23:23","slug":"taquilleras-del-metro-advierten-peligro-para-su-salud-por-covid-19","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/taquilleras-del-metro-advierten-peligro-para-su-salud-por-covid-19\/","title":{"rendered":"Taquilleras del Metro advierten peligro para su salud por COVID 19"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>* No cuentan con medidas de protecci\u00f3n\nen su trabajo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>* Piden a jefa de Gobierno que cierren\nlas taquillas en tanto pasa la emergencia<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lorena Vaniezcot<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico,\nCd. de M\u00e9xico, 2 de abril, 2020.- Trabajadoras de las taquillas del Metro\nsolicitan el cierre temporal de la venta de boletos ya que pone en peligro a\nlas trabajadoras de ser contagiadas por COVID 19 y aseguran que no cuentan con\nlo m\u00ednimo para protegerse de la pandemia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Casi\nmil personas han firmado la solicitud enviada a Claudia Sheimbaun, jefa de\ngobierno de la Ciudad de M\u00e9xico \u201cPor el derecho a la vida de las taquilleras\ndel Metro de la CDMX\u201d, que se public\u00f3 en la plataforma digital Avaaz.org<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ella se explica que ante la contingencia por el virus COVID 19, las taquilleras del STC METRO \u201cestamos en gran peligro. \u00a1Necesitamos ayuda urgente!\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1alan la importancia de este medio de transporte y que este siga operando por sr dicen \u201cla columna vertebral de la ciudad\u201d, sin embargo, \u201clas taquilleras, somos el \u00e1rea que tenemos el contacto directo con los usuarios, que en los pr\u00f3ximos d\u00edas, ser\u00e1n potencialmente, portadores de Covid19\u201d.<br> <br> Sin embargo refieren que no cuentan con los m\u00ednimos materiales para esta contingencia, como son: cubrebocas, guantes y el gel adecuado, para protegernos. Incluso, afirman que ni siquiera hay agua en varias estaciones, para lavarse las manos.<br> <br> \u201cConsideramos que el intercambio de dinero, as\u00ed como la manipulaci\u00f3n de las tarjetas para las recargas, son un foco de infecci\u00f3n (ya que muchas personas al entregar el dinero y la tarjeta, los traen en la boca)\u201d.<br> <br> Aseguran que a pesar de los anuncios hechos por la Secretar\u00eda de Salud, de \u201cquedarse en casa\u201d, ellas han tenido que seguir trabajando porque las autoridades del STC no han permitido que el personal de taquilla, que pertenece a grupos vulnerables, se retire en su totalidad.<br> <br> \u201cAdicionalmente ya tenemos casos de taquilleras con probabilidad de haber adquirido COVID-19, seg\u00fan sus diagn\u00f3sticos\u201d por ello pidieron el cierre temporal de las taquillas porque no quieren ser contagiadas ni ser el\u00a0 veh\u00edculo para que otras personas se contagien.<br> <br> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM\/lv\/sj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No cuentan con medidas de protecci\u00f3n en su trabajo<\/p>\n","protected":false},"author":3,"featured_media":18996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[691,54],"tags":[],"class_list":["post-18995","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/18995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=18995"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/18995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/18996"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=18995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=18995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=18995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}