{"id":18987,"date":"2020-04-02T21:16:08","date_gmt":"2020-04-02T21:16:08","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=18987"},"modified":"2023-07-21T15:23:23","modified_gmt":"2023-07-21T20:23:23","slug":"opinion-422","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/opinion-422\/","title":{"rendered":"R\u00e1faga"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Un virus nos cambia la vida <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>* Sonriamos y Cuid\u00e9monos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jorge Herrera Vale Nzuela<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico,\n2 de abril 2020.- La rutina de nuestra vida se rompi\u00f3. Est\u00e1bamos preparando las\nmaletas para las vacaciones de Semana Santa y hay que deshacerlas para mejores\nd\u00edas. Se frustr\u00f3 el viaje a los Juegos Ol\u00edmpicos de Tokio 2020. No pocos\naplazaron el d\u00eda cumbre del noviazgo, el matrimonio. Se suspendieron los jueves\nde caracoles en la cantina. Pospusimos el d\u00eda de campo dominical. Nos quedamos\nsin partidos de futbol, de b\u00e9isbol, de basquetbol y sin carreras de la F\u00f3rmula\n1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace\na\u00f1os en el diario <em>La Prensa<\/em> el cart\u00f3n\neditorial, dibujado por Don Yo, se titulaba \u201cAs\u00ed es la Vida\u201d. Lo recuerdo, como\nrecuerdo a don Chucho Nieto, el cartonista, porque efectivamente as\u00ed es la vida\ny tenemos que enfrentarla y crear conciencia de lo grave que es la actual\nsituaci\u00f3n para nuestra salud, adem\u00e1s de la crisis econ\u00f3mica que habremos de\nafrontar en corto tiempo. Y todo por culpa de\u2026\u00a1un virus!, bautizado como\n\u201ccoronavirus\u201d o&nbsp; COVID 19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por\nahora no nos importa de d\u00f3nde vino, c\u00f3mo apareci\u00f3 y qui\u00e9n lo llev\u00f3 hasta la\npoblaci\u00f3n China para luego esparcirlo por todo el mundo. Empezaron a surgir\nversiones para contestar esas interrogantes y muchas que estar\u00e1n en el tapete\nde las discusiones. En nuestro pa\u00eds las medidas sanitarias se tomaron a la\nmexicana o sea cuando el problema entraba en su apogeo. A todos se nos pidi\u00f3, sugiri\u00f3,\ny se propuso que debemos de PERMANECER EN CASA, especialmente los mayores de 60\na\u00f1os, los hipertensos, los que sufran alguna enfermedad respiratoria, los\nobesos y los diab\u00e9ticos, entre otros. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\ntrav\u00e9s de las noticias televisivas nos enteramos de que no falt\u00f3 el jefe de\nfamilia irresponsable que se llev\u00f3 a esposa e hijos a la playa, a divertirse, a\ntomar vacaciones. Ojal\u00e1 que no sean contagiados y despu\u00e9s contaminadores del\ncoronavirus. Cierto es que muchas personas no pueden estar en el encierro\ncasero, porque tienen que salir a trabajar, &nbsp;porque viven al d\u00eda. M\u00e9dicos, enfermeras,\nafanadoras, camilleros, operadores de transporte p\u00fablico, polic\u00edas y bomberos,\nreporteros y lectores de noticias siguen en plena actividad. En oficinas de\ngobierno, se aplica \u201cel criterio\u201d del jefe y muchos empleados tienen que \u201chacer\nguardias\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor, sonr\u00edamos y adelante<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta\nocasi\u00f3n decid\u00ed no referirme a la doble crisis que padecemos: la de la salud y\nla econ\u00f3mica, porque estamos ampliamente informados del desarrollo de la\npandemia, n\u00fameros de casos confirmados, de los sospechosos y de los que\nlamentablemente han fallecido. Las noticias llegan minuto a&nbsp; minuto de Espa\u00f1a, de Italia, de Alemania, de\nChina y de los vecinos del Norte, donde las cifras ya superaron a las\nregistradas en el pa\u00eds asi\u00e1tico. Vivimos en ambiente de inquietud, de\nconfusi\u00f3n, as\u00ed como sucesos incre\u00edbles como el caso del Presidente de M\u00e9xico\nque no suspenden sus actividades para no dejar el poder a \u201clos conservadores\u201d o\na los empresarios corruptos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno,\ncreo que, salvo su mejor opini\u00f3n, tenemos que ser optimistas, ver con sentido\npositivo hacia adelante, no dedicar el tiempo a criticar, sino a contribuir\npara que el cambio de vida nos sea leve, pues estaremos en el encierro casero\nhasta el jueves 30 de abril se nos dir\u00e1 que ya podemos poner fin a la\nreclusi\u00f3n. Mientras tanto que les parece si nos re\u00edmos unos minutos leyendo lo\nque circula en redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El\ningenio del mexicano es agudo en todo momento y de un humorismo que heredamos\nde quienes lo fueron en el Siglo XIX. He aqu\u00ed \u201cdefiniciones modernas\u201c de\nalgunas palabras:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">INESTABLE,\nMesa de In\u00e9s, en ingl\u00e9s. BERMUDAS, Observar a las que no hablan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ONDEANDO,\n\u00bfD\u00f3nde estoy? TELEPAT\u00cdA, Aparato de TV para la hermana de mi mam\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CAMARON,\nAparato enorme para sacar fotos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TEL\u00d3N,\nTela de 50 metros o m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DECIMAL,\nPronunciar equivocadamente. Anomal\u00eda,&nbsp;\nHemorroides.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">BECERRO,\nQue ve u observa una loma o colina. POLINESIA, Mujer polic\u00eda que no quiere\nentender nada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay\nmuchas m\u00e1s, pero ser\u00e1n para mi espacio de fin de semana. Por&nbsp; lo pronto les dejo que mediten y respondan a\ntres interrogantes: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQui\u00e9nes\nfueron los 10 generales que gobernaron a M\u00e9xico en el siglo pasado?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfRecuerda\nlos nombres de los 13 Emperadores Aztecas?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1l fue\nel primer Presidente, en el mundo, que viaj\u00f3 en avi\u00f3n?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\ncorrer tras las enciclopedias y el Diccionario Enciclop\u00e9dico Mexicano de m\u00ed\namigo Humberto Musacchio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">jherrerav@live.com.mx<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un virus nos cambia la vida <\/p>\n","protected":false},"author":3,"featured_media":18988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[691,94,107],"tags":[],"class_list":["post-18987","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-jorge-herrera-valenzuela","category-rafaga"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/18987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=18987"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/18987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/18988"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=18987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=18987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=18987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}