{"id":18724,"date":"2020-03-27T03:39:53","date_gmt":"2020-03-27T03:39:53","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=18724"},"modified":"2023-07-21T15:23:29","modified_gmt":"2023-07-21T20:23:29","slug":"gobierno-de-espana-ultima-un-subsidio-extraordinario-a-las-empleadas-domesticas","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/gobierno-de-espana-ultima-un-subsidio-extraordinario-a-las-empleadas-domesticas\/","title":{"rendered":"Gobierno de Espa\u00f1a ultima un subsidio extraordinario a las empleadas dom\u00e9sticas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>* Las organizaciones, que denunciaron\nsu exclusi\u00f3n de las medidas de protecci\u00f3n <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>* Recuerdan que muchas trabajadoras no\nest\u00e1n dadas de alta en la Seguridad Social <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gloria L\u00f3pez<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/AmecoPress,\nMadrid, 26 de marzo 2020.-&nbsp;Medios y redes se hacen eco de la situaci\u00f3n de\nprecariedad y especial desprotecci\u00f3n en la que est\u00e1n las empleadas dom\u00e9sticas.\nEl pasado lunes, estas trabajadoras&nbsp;denunciaron su exclusi\u00f3n de las\nmedidas de protecci\u00f3n decretadas por el Gobierno ante la crisis del\ncoronavirus. Dos d\u00edas m\u00e1s tarde el ejecutivo anuncia un \u201csubsidio\nextraordinario de desempleo de un mes de duraci\u00f3n para las trabajadoras de\nhogar\u201d, que podr\u00eda ver la luz ma\u00f1ana viernes o el pr\u00f3ximo martes. Pero la\nmedida puede ser muy insuficiente si se reduce a las trabajadoras dadas de alta\nen la Seguridad Social, responden las organizaciones, que con rapidez hicieron\ncircular una consigna en las redes: exigimos soluciones para que nadie quede atr\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque\na\u00fan se desconoce con precisi\u00f3n el alcance de la medida, todo apunta a que uno\nde los requisitos de acceso ser\u00e1 estar dada de alta en la Seguridad Social y\ncotizando, con lo que muchas trabajadoras no van a poder acceder a la\nprestaci\u00f3n porque en esta actividad hay un alto componente de trabajo\nsumergido. Al igual que en el caso del subsidio extraordinario para aut\u00f3nomos,\nla ayuda que perciban las empleadas dom\u00e9sticas ser\u00e1 el equivalente al 70 % de\nla base de cotizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn\nel sector hay muchas mujeres que trabajan en la econom\u00eda sumergida, por no\ntener permiso de trabajo o por no estar dadas de alta en la Seguridad Social.\nSi no se les ha permitido regularizarse, si no ha habido controles del alta en\nla Seguridad Social por parte de la Inspecci\u00f3n de Trabajo, como han pedido\nreiteradamente las asociaciones de empleadas de hogar, no pueden ser ahora las\ntrabajadoras quienes lo paguen\u201d, manifiestan desde Territorio Dom\u00e9stico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La\norganizaci\u00f3n, junto a otras entidades del sector, recoge los testimonios de las\ntrabajadoras de hogar y cuidados que se est\u00e1n viendo afectadas en sus\ncondiciones laborales y personales por la crisis del coronavirus para tener\nherramientas para visibilizar y denunciar la desprotecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos\nderechos no reconocidos, como la prestaci\u00f3n por desempleo, la menor protecci\u00f3n\nfrente al despido con el desistimiento (despido libre), la no inclusi\u00f3n en la\nLey de prevenci\u00f3n de riesgos laborales, una ley de extranjer\u00eda que condena a la\nclandestinidad, en otros, se convierten en estos momentos en decisiones\ncriminales, mucho m\u00e1s cuando no han sido incluidas en ninguna de las medidas de\nprotecci\u00f3n extraordinarias aprobadas por el Gobierno\u201d, manifiestan las\norganizaciones que han decidido poner en marcha esta herramienta de denuncia\ncolectiva a la que se puede acceder a trav\u00e9s del&nbsp;<a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeL-UG2CEZy1rIZQFNTP-bcNuMBlmbFkqkjNW_UsWZid8K-dQ\/viewform%E2%80%A6.\">este enlace<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para\norganizaciones como la Asociaci\u00f3n de Trabajadoras del Hogar de Vizcaya o Sedoac\nde Madrid la noticia sobre el posible subsidio de un mes que se dar\u00e1 las\ntrabajadoras del hogar que hayan perdido o visto reducidos sus ingresos debido\nal coronavirus \u201ces positiva y es el resultado de la exigencia de las\norganizaciones del sector\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero\nla medida \u201cse queda muy corta\u201d, porque dicen que se exigir\u00e1 estar de alta en la\nseguridad social en el momento en el que se suspendi\u00f3 el contrato, se redujo la\njornada, o se perdi\u00f3 el empleo. Esto deja fuera muchas de las trabajadoras que\nhoy est\u00e1n en situaci\u00f3n de necesidad, que ven\u00edan prestando sus servicios en la\neconom\u00eda sumergida al no tener permiso de trabajo, o porque no estaban dadas de\nalta en la seguridad social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta\nsituaci\u00f3n no puede volverse en contra de las trabajadoras en estos momentos.\nEra muy conocida, la responsabilidad es de quienes han preferido mantener al\nsector en la informalidad y la falta de derechos\u201d, sostienen las\norganizaciones. \u201cA\u00f1o tras a\u00f1o hemos pedido una y otra vez papeles para todas\nlas trabajadoras y control de la inspecci\u00f3n de trabajo sobre el alta en la\nseguridad social y no se nos ha escuchado; la protecci\u00f3n ante la emergencia, en\nforma de prestaci\u00f3n de desempleo o de subsidio de garant\u00eda de ingresos, tiene\nque llegar a todas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s,\nlas trabajadoras entienden que la \u201cprestaci\u00f3n que se anuncia\u201d deber\u00e1 mantenerse\nel tiempo necesario hasta que las trabajadoras vuelvan al empleo tras la\nsuspensi\u00f3n o bien consigan de nuevo medios de vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Peticiones<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras\nse conocen los detalles del subsidio anunciado por el Gobierno y se produce su\naprobaci\u00f3n, las organizaciones exigen que de manera urgente se activen las\nmedidas necesarias para acabar con la discriminaci\u00f3n y exclusi\u00f3n injustificable\ndel colectivo de trabajadoras de hogar respecto a los siguientes puntos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1.\nReconocimiento de la prestaci\u00f3n por desempleo para las trabajadoras de hogar y\ncuidados, \u00fanico sector excluido de este derecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\n2. Abolici\u00f3n del desistimiento para evitar el despido libre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\n3. Medidas especiales de protecci\u00f3n para las trabajadoras en situaci\u00f3n\nadministrativa irregular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\n4. Medidas de control sobre el r\u00e9gimen de internas para evitar que el\nconfinamiento se convierta en reclusi\u00f3n en sus puestos de trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\n5. Garant\u00edas para el disfrute del derecho al cuidado de sus propias familias en\nigualdad al resto de trabajadoras\/es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\n6. Inclusi\u00f3n del sector en la provisi\u00f3n de equipos de protecci\u00f3n individual\npara evitar la propagaci\u00f3n del contagio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\n7. Integraci\u00f3n inmediata en la Ley de Prevenci\u00f3n de Riesgos Laborales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\n8. Habilitaci\u00f3n de medidas excepcionales para la suspensi\u00f3n de las cuotas de\ncotizaci\u00f3n a la Seguridad social de los y las empleadoras laboralmente\nactivos\/as afectados\/as por la crisis del COVID-19 o, de aquellos\/as que se\nhayan visto obligados a realizar nuevas contrataciones para reforzar los\ncuidados en \u00e9poca de confinamiento, de modo que se eviten sobrecostes que\nconlleven nuevos despidos o reducci\u00f3n de salarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEM-AmecoPress\/gl<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las organizaciones, que denunciaron su exclusi\u00f3n de las medidas de protecci\u00f3n<\/p>\n","protected":false},"author":3,"featured_media":18725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[691,53],"tags":[],"class_list":["post-18724","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-internacional"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/18724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=18724"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/18724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/18725"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=18724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=18724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=18724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}