{"id":18488,"date":"2020-03-20T21:26:19","date_gmt":"2020-03-20T21:26:19","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=18488"},"modified":"2023-07-21T15:23:03","modified_gmt":"2023-07-21T20:23:03","slug":"sindicato-exige-al-gobierno-protocolo-para-trabajadoras-del-hogar","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/sindicato-exige-al-gobierno-protocolo-para-trabajadoras-del-hogar\/","title":{"rendered":"Sindicato exige al gobierno  protocolo para trabajadoras del hogar"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Peligra el empleo para millones, especialmente empleadas de entrada por salida<\/strong><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Detenida por incapacidad del IMSS su regularizaci\u00f3n<\/strong><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>El coronavirus agudiza su situaci\u00f3n de vulnerabilidad laboral\u00a0<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Argelia Guevara<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Cd. de M\u00e9xico. 20 de marzo de 2020.- El Sindicato Nacional de Trabajadores y Trabajadoras del Hogar (Sinactrho) advirti\u00f3 que la crisis del coronavirus afectar\u00e1 a este gremio, luego de que ha sido imposible o dif\u00edcil que sean ingresadas al IMSS y no son claros los contratos de trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Sinactrho tambi\u00e9n pidi\u00f3 respuestas coherentes al gobierno federal y a otras instituciones p\u00fablicas, ya que el riesgo para 2 millones de trabajadoras del hogar es alto. La mayor\u00eda son empleadas o empleados de entrada por salida y ahora ser\u00e1n afectadas por la crisis y la pandemia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Temen despidos, riesgos en la salud y otras afectaciones. Denuncian que es grave la desinformaci\u00f3n y la falta de programas de apoyo desde el gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde sus oficinas en el Sindicato de Telefonistas de la Rep\u00fablica Mexicana voceras del Sindicato Nacional de Trabajadores y Trabajadoras del Hogar (Sinactraho)&nbsp;se\u00f1alaron la importancia de que el&nbsp;gobierno federal&nbsp;&nbsp;haga acciones para proteger a este sector vulnerable, con la aplicaci\u00f3n de un protocolo adecuado durante sus jornadas laborales, adem\u00e1s de que se hagan respetar las reformas a la Ley del Trabajo y del&nbsp;<a href=\"https:\/\/www.milenio.com\/temas\/seguro-social\" target=\"_blank\" rel=\"noreferrer noopener\">Seguro Social<\/a>&nbsp;que desde el a\u00f1o pasado establecen que son acreedores de diversos derechos y prestaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maril\u00fa Padua Orihuela, secretaria de G\u00e9nero y Derechos Humanos del gremio, mencion\u00f3 que en&nbsp;M\u00e9xico&nbsp;solo un promedio de 18 mil 500 trabajadoras del hogar, de las millones que existen a escala nacional, seg\u00fan datos del INEGI no cuentan con programas de salud y la informaci\u00f3n adecuada para ejercer sus derechos durante sus jornadas laborales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl trabajo del hogar siempre ha sido un tema no reconocido, poco valorado y&nbsp;justamente es hasta que llegan este tipo de casos cuando vemos que la limpieza, el aseo y la higiene es lo que nos puede salvar en estas situaciones. A partir de que se desat\u00f3 el&nbsp;<a href=\"https:\/\/www.milenio.com\/temas\/coronavirus-en-mexico\" target=\"_blank\" rel=\"noreferrer noopener\">coronavirus<\/a>&nbsp;hemos recibido de las compa\u00f1eras muchas quejas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEntre las principales denuncias est\u00e1n que se les han aumentado la carga de trabajo, los empleadores les piden limpiar varias veces la misma zona con productos que pueden da\u00f1ar su salud, esto sin que se les pague el tiempo extra\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la&nbsp;<a href=\"https:\/\/www.milenio.com\/temas\/ley-federal-del-trabajo\" target=\"_blank\" rel=\"noreferrer noopener\">Ley Federal del Trabajo<\/a>, las empleadas del hogar que no residan en el lugar donde laboran&nbsp;deben de tener una jornada m\u00e1xima de ocho horas, adem\u00e1s de que tienen derecho a un descanso m\u00ednimo de tres horas en&nbsp;actividades matutinas, horas extra pagadas al doble, vacaciones y d\u00edas de descanso, estas y m\u00e1s indicaciones deben de estar estipuladas en un contrato que sea del conocimiento de las dos partes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maril\u00fa Padua expres\u00f3 que aparte de las afectaciones que normalmente reciben las y los trabajadores del hogar por parte de empleadores, como no estar inscritos en los programas sociales y de salud correspondientes, discriminaci\u00f3n, malos pagos y sin prestaciones, acosos y otras afectaciones a su integridad, en estos meses se han enfrentado a la falta de material adecuado para evitar enfermarse, contagiar a su familia y a las casas donde prestan sus servicios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi se hacen cumplir las leyes y el convenio 189 nosotros podemos ir detectando que no es normal que no te den guantes o uniforme con tela resistente que aguante el calor de la estufa y los qu\u00edmicos, as\u00ed como las cofias para realizar la comida, adem\u00e1s de los largos trayectos que algunas deben recorrer de su casa al&nbsp;trabajo\u201d, destac\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Detenida por incapacidad del IMSS su regularizaci\u00f3n<\/p>\n","protected":false},"author":3,"featured_media":18489,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[691,54],"tags":[],"class_list":["post-18488","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/18488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=18488"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/18488\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/18489"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=18488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=18488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=18488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}