{"id":18075,"date":"2020-03-11T00:05:23","date_gmt":"2020-03-11T00:05:23","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=18075"},"modified":"2023-07-21T15:21:30","modified_gmt":"2023-07-21T20:21:30","slug":"mujeres-sordas-exigen-acabar-con-el-machismo-y-denuncian-las-barreras-de-acceso-a-servicios-basicos","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/mujeres-sordas-exigen-acabar-con-el-machismo-y-denuncian-las-barreras-de-acceso-a-servicios-basicos\/","title":{"rendered":"Mujeres sordas exigen acabar con el \u201cmachismo\u201d y denuncian las barreras de acceso a servicios b\u00e1sicos"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong> La Confederaci\u00f3n Estatal de Personas Sordas (CNSE) ha hecho p\u00fablico un manifiesto que reclama soluciones ante la doble discriminaci\u00f3n a la que se enfrentan las mujeres sordas <\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por Redacci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico\/AmecoPress. Madrid, 10 mar. 20. &#8211; La Confederaci\u00f3n Estatal de Personas Sordas (CNSE) ha apelado a acabar con la \u201cmisoginia\u201d y el \u201cmachismo\u201d y a destruir las barreras de acceso a recursos y servicios b\u00e1sicos a las que tienen que hacer frente cada d\u00eda las mujeres sordas, con motivo de la celebraci\u00f3n del D\u00eda Internacional de la Mujer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo ha hecho p\u00fablico la entidad en un manifiesto en el que reclama soluciones ante la doble discriminaci\u00f3n a la que se enfrentan las mujeres sordas, y exige un \u201ccamino real\u201d hacia la igualdad de g\u00e9nero. En este sentido, hace alusi\u00f3n a la aprobaci\u00f3n, hace 25 a\u00f1os, de la Declaraci\u00f3n y Plataforma de Acci\u00f3n de Beijing que ten\u00eda como objetivo, precisamente, el empoderamiento de todas las mujeres y ni\u00f1as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El documento tambi\u00e9n pone de relieve los estereotipos a los que se enfrentan en su d\u00eda a d\u00eda las mujeres sordas y, en este sentido, reivindica la plena igualdad del colectivo en \u00e1mbitos como el empleo, la educaci\u00f3n, la participaci\u00f3n, la sexualidad o el derecho a una vida sin violencia machista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En relaci\u00f3n a la educaci\u00f3n, la CNSE alude a una ense\u00f1anza no sexista y biling\u00fce en lengua de signos para que \u201cla infancia sorda integre valores como la equidad y la solidaridad, y para tener las mismas oportunidades sin distinci\u00f3n por raz\u00f3n de g\u00e9nero\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, demanda \u201cacciones pol\u00edticas que contribuyan a la cualificaci\u00f3n profesional e inclusi\u00f3n laboral de las mujeres sordas\u201d y aboga por su \u201cplena participaci\u00f3n en cualquier \u00e1mbito\u201d. En esta l\u00ednea, muestra su firme rechazo al audismo y a los prejuicios acerca de las mujeres sordas por el hecho de ser sorda, que solo generan discriminaci\u00f3n y les restan oportunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, la CNSE solicita informaci\u00f3n y recursos accesibles en materia de educaci\u00f3n, salud y libertad sexual, reproducci\u00f3n y maternidad. A este respecto, reclama respeto a la capacidad de elegir y de acceder en igualdad de condiciones a los servicios p\u00fablicos de reproducci\u00f3n asistida \u201cporque la sordera no es una enfermedad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, la entidad hace hincapi\u00e9 en el derecho de las mujeres sordas a tener una vida sin \u201cviolencias machistas,\u201d y urge a contemplar en favor de las mismas las medidas establecidas en el Pacto de Estado contra la Violencia de G\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este a\u00f1o, el D\u00eda Internacional de la Mujer se celebra bajo el lema \u2018Soy de la Generaci\u00f3n Igualdad: Por los derechos de las mujeres\u2019. Para conmemorar la jornada, la CNSE ha generado el hashtag #SomosMujeresSordas para interactuar en redes sociales, que emplear\u00e1 junto a otros como #Beijing25, #Generaci\u00f3nIgualdad y #GenerationEquality.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> La Confederaci\u00f3n Estatal de Personas Sordas (CNSE) ha hecho p\u00fablico un manifiesto que reclama soluciones ante la doble discriminaci\u00f3n a la que se enfrentan las mujeres sordas <\/p>\n","protected":false},"author":3,"featured_media":18076,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[691,53],"tags":[],"class_list":["post-18075","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-internacional"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/18075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=18075"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/18075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/18076"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=18075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=18075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=18075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}