{"id":17176,"date":"2020-02-22T00:21:53","date_gmt":"2020-02-22T00:21:53","guid":{"rendered":"https:\/\/redsemlac.com\/semmexico\/?p=17176"},"modified":"2023-07-21T15:20:39","modified_gmt":"2023-07-21T20:20:39","slug":"undiasinnosotras-inusitada-respuesta-de-gobiernos-universidades-y-medios","status":"publish","type":"post","link":"https:\/\/redsemlac.com\/semmexico\/undiasinnosotras-inusitada-respuesta-de-gobiernos-universidades-y-medios\/","title":{"rendered":"#UnD\u00edaSinNosotras: Inusitada respuesta de gobiernos, universidades y medios"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>Llaman al paro del 9 de\nmarzo, una huelga de mujeres en todo M\u00e9xico<\/strong><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Resultado de la\nmovilizaci\u00f3n, la protesta y el ya no m\u00e1s.<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sara Lovera<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SemM\u00e9xico. Ciudad de M\u00e9xico. 21 de febrero 2020.- Al corte de las 16\nhoras, m\u00e1s de 100 gobiernos estatales, municipales, universidades, partidos\npol\u00edticos, negocios peque\u00f1os, restaurantes y medios de comunicaci\u00f3n anunciaron\nque se suman al paro de mujeres del 9 de marzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque colectivas feministas, mujeres, feministas antiguas y chats privados est\u00e1n sin explicaci\u00f3n, es la primera vez en a\u00f1os, -al menos 20 cada a\u00f1o se llama a una huelga de mujeres alrededor del 8 de marzo-, es la primera vez que cobra tal notoriedad, al lado de millones de palabras, mesas de debate en los medios; expresiones y discursos en el Congreso, y que ha salido a la luz al menos 38 iniciativas legislativas, algunas repetidoras de nuestro marco legal y otras que buscan cambios o perfeccionar lo que hay.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/02\/paro-nacional-corte-5-1024x576.jpg\" alt=\"\" data-id=\"17181\" data-full-url=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/02\/paro-nacional-corte-5.jpg\" data-link=\"https:\/\/redsemlac.com\/semmexico\/?attachment_id=17181\" class=\"wp-image-17181\"\/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Lo cierto es que a partir de agosto en que se conoci\u00f3 un video de una\njoven atacada por polic\u00edas de la Ciudad de M\u00e9xico, en la que la polic\u00eda\ncapitalina filtr\u00f3 fotos e informaci\u00f3n, de ello fue lamentable la respuesta de\nlas autoridades y la fiscal\u00eda capitalina, consideraron la respuesta\/propuesta\nel 24 de agosto, como \u201cuna provocaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A ello sigui\u00f3 la manipulaci\u00f3n de la informaci\u00f3n, las protesta aumentaron,\nno han parado; no pararon las chicas y sus pintas; su diamantina; su\nirreverencia, rompi\u00f3 la l\u00f3gica antigua, donde se sab\u00eda, se o\u00eda, se reportaba,\npero no pasaba nada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En noviembre se iniciaron los paros en las escuelas y facultades de la\nUNAM, sobre la que una nueva andanada encendi\u00f3 los \u00e1nimos, en la Presidencia de\nla Rep\u00fablica se dijo que hab\u00eda mano negra. Los paros, la protesta y tambi\u00e9n la\nnegociaci\u00f3n est\u00e1n vigentes. Los medios han encontrado que vende la noticia\nestad\u00edstica de la violencia contra las mujeres y estamos viviendo una nueva\ndanza de cifras, como las de 1994 cuando se difundi\u00f3, inform\u00f3 y creci\u00f3 la indignaci\u00f3n\npor las desapariciones y asesinatos de mujeres en Ciudad Ju\u00e1rez, narrativa\nolvidada ahora por opinadores, autoridades y congresistas. Ya no se acuerdan de\ndonde surgi\u00f3 el t\u00e9rmino violencia feminicida y feminicidio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo inusitado es una dupla de cuestiones: la respuesta medi\u00e1tica, con\nclaro oscuros y la respuesta pol\u00edtica. De personas, legisladoras y\nlegisladores, de todos los partidos pol\u00edticos. Sin excepci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La indignaci\u00f3n creci\u00f3 luego de las filtraciones de fotograf\u00edas de una\nv\u00edctima y sell\u00f3 el ciclo, agosto-febrero, con el asesinato de F\u00e1tima, una ni\u00f1a\nde 7 a\u00f1os, en los d\u00edas de febrero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese periodo de 6 meses, tambi\u00e9n se ha intentado explicar a fondo y\ncient\u00edficamente de qu\u00e9 estamos hablando cuando hablamos de violencia contra las\nmujeres y asesinatos, el extremo de la violencia, con menos \u00e9xito, pero las que\nsaben, trabajan en ello y han protestado sistem\u00e1ticamente los \u00faltimos 30 a\u00f1os,\ntambi\u00e9n est\u00e1n en los medios, en mesas de an\u00e1lisis serio, y en discursos en las\nc\u00e1maras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El paro para\nel 9 de marzo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese contexto se llam\u00f3 al paro para el 9 de marzo y en forma inmediata\nse desat\u00f3 la solidaridad y tambi\u00e9n discursos en contra, confusos, sin\nconocimiento, lo cierto es que entre ayer y hoy, se hizo una cadena de\nadhesiones al paro que habr\u00e1 de realizarse en 17 d\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Al corte, 16\nhoras, 21 de febrero: 100 gobiernos, universidades y medios se suman al paro.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los primeros fueron los gobiernos del Municipio de Veracruz y el Estatal \u00a0de Michoac\u00e1n, ayer y esta ma\u00f1ana, junto al programa de Ciro G\u00f3mez Leyva de Radio F\u00f3rmula, el poder judicial; el Senado; la C\u00e1mara de la\u00a0 diputados y diputadas, el gobierno de Tamaulipas; el gobierno de San Luis Potos\u00ed;  el PAN, el PRD;  el Instituto Nacional Electoral (INE) el ayuntamiento de M\u00e9rida; el ayuntamiento de Huixquilucan; el ayuntamiento Quer\u00e9taro; ayuntamiento de Benito Ju\u00e1rez, Canc\u00fan; la Alcald\u00eda de Benito Ju\u00e1rez y el gobierno de la CDMX. <\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/02\/paro-nacional-corte-6-663x1024.jpg\" alt=\"\" data-id=\"17182\" data-full-url=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/02\/paro-nacional-corte-6.jpg\" data-link=\"https:\/\/redsemlac.com\/semmexico\/?attachment_id=17182\" class=\"wp-image-17182\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"672\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/02\/paro-nacional-corte-4.jpg\" alt=\"\" data-id=\"17180\" data-full-url=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/02\/paro-nacional-corte-4.jpg\" data-link=\"https:\/\/redsemlac.com\/semmexico\/?attachment_id=17180\" class=\"wp-image-17180\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"814\" height=\"571\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/02\/paro-nacional-corte-2.jpg\" alt=\"\" data-id=\"17178\" data-full-url=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/02\/paro-nacional-corte-2.jpg\" data-link=\"https:\/\/redsemlac.com\/semmexico\/?attachment_id=17178\" class=\"wp-image-17178\"\/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-embed-twitter alignleft wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">El Gobierno del Estado de San Luis Potos\u00ed se une a la iniciativa <a href=\"https:\/\/twitter.com\/hashtag\/UnDiaSinNosotras?src=hash&amp;ref_src=twsrc%5Etfw\">#UnDiaSinNosotras<\/a>. Respetamos el derecho de las mujeres que laboran en el gobierno estatal, que contar\u00e1n con todas las facilidades para sumarse a este movimiento. <a href=\"https:\/\/t.co\/RnMHuksWdq\">pic.twitter.com\/RnMHuksWdq<\/a><\/p>&mdash; Gobierno del Estado de San Luis Potos\u00ed (@GobEdoSLP) <a href=\"https:\/\/twitter.com\/GobEdoSLP\/status\/1230923714805420033?ref_src=twsrc%5Etfw\">February 21, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-twitter alignleft wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">El <a href=\"https:\/\/twitter.com\/INEMexico?ref_src=twsrc%5Etfw\">@INEMexico<\/a> respeta y apoya la decisi\u00f3n libre, individual, de todas las compa\u00f1eras de trabajo que se sumen al <a href=\"https:\/\/twitter.com\/hashtag\/ParoNacionalDeMujeres?src=hash&amp;ref_src=twsrc%5Etfw\">#ParoNacionalDeMujeres<\/a> del 9 de marzo. <a href=\"https:\/\/t.co\/x4e7OfBKiB\">pic.twitter.com\/x4e7OfBKiB<\/a><\/p>&mdash; Ciro Murayama (@CiroMurayamaMx) <a href=\"https:\/\/twitter.com\/CiroMurayamaMx\/status\/1230972247629860867?ref_src=twsrc%5Etfw\">February 21, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La Universidad Aut\u00f3noma de Quer\u00e9taro; la Universidad Aut\u00f3noma de Yucat\u00e1n;\nla benem\u00e9rita Universidad Aut\u00f3noma de Puebla; la Universidad Veracruzana; la Universidad\nAut\u00f3noma de Chihuahua; Universidad Aut\u00f3noma de Ciudad Ju\u00e1rez; la Universidad\ndel Claustro de Sor Juana y la Universidad Michoacana de San Nicol\u00e1s de Hidalgo.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La respuesta es inusitada,\na las 15 horas Joaqu\u00edn L\u00f3pez D\u00f3riga, anunci\u00f3 que su empresa se suma; El&nbsp;Instituto Polit\u00e9cnico\nNacional IPN respald\u00f3 esta iniciativa y llam\u00f3 la comunidad femenina l que\nparticipe en ella. A las 14 horas, se sum\u00f3 el gobierno de la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;IPN&nbsp;se sensibiliz\u00f3 ante la\ndemanda de alto&nbsp;a la violencia de g\u00e9nero y destac\u00f3 el valor de las mujeres\nen distintos \u00e1mbitos de la sociedad.<strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se inform\u00f3 que la UNAM y el IPN se suman al paro nacional de mujeres &#8216;Un\nd\u00eda sin nosotras&#8217;, convocado para el pr\u00f3ximo 9 de marzo en protesta contra la\nviolencia de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anunciaron los noticieros de TELEVISA; se\nmultiplicaron anuncios como:Crece apoyo de instituciones y clase\npol\u00edtica a paro de mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La UNAM reconoci\u00f3 el valor de todas las acciones de\nla sociedad civil para combatir la desigualdad y la violencia de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa\nUniversidad Nacional Aut\u00f3noma de M\u00e9xico reconoce el valor de todas las acciones\nde la sociedad civil que contribuyan a visibilizar pr\u00e1cticas inadmisibles como\nla desigualdad y la violencia de g\u00e9nero, por lo que siendo un espacio de\nreflexi\u00f3n y autonom\u00eda, se suma a la iniciativa internacional \u201cUn d\u00eda sin\nnosotras\u201d, el 9 de marzo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La m\u00e1xima\ncasa de estudios se\u00f1al\u00f3 que apoya a todas las&nbsp;<strong>mujeres universitarias<\/strong>&nbsp;que\ndecidan no acudir a clases, labores acad\u00e9micas o administrativas, sin que ello\nse vea reflejado como inasistencias ni descuentos salariales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>UNAM<\/strong>&nbsp;reiter\u00f3\nque seguir\u00e1n emprendiendo todas las acciones necesarias que contribuyan a\ncombatir la desigualdad y la&nbsp;<strong>violencia de g\u00e9nero<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s tarde se sumaron\notras instituciones como la Universidad Aut\u00f3noma del Estado de Hidalgo (UAEH),\nla Universidad Aut\u00f3noma Metropolitana (UAM), la Universidad Aut\u00f3noma de\nTabasco, la Universidad Aut\u00f3noma del Estado de M\u00e9xico (UAEM), la Universidad de\nlas Am\u00e9ricas Puebla, la Universidad del Valle de M\u00e9xico (UVM), la Universidad\nJesuita de Guadalajara (ITESO) y la Universidad Iberoamericana de la Ciudad de\nM\u00e9xico y de Puebla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s\nde afirmar que la derecha apoya el paro, AMLO, recul\u00f3: Ni descuentos ni\ncastigos a mujeres que se sumen a paro nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sabemos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta semana,\nagrupaciones feministas y mujeres en general comenzaron a replicar una\nconvocatoria para un paro nacional de mujeres para el d\u00eda 9 de marzo, esto como\nparte de las protestas por los feminicidios y la violencia en contra de las\nmujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La propuesta\n#UnD\u00edaSinNosotras fue hecha por la colectiva Brujas del Mar y publicada en sus\nredes sociales, por lo que feministas independientes y otras personas\ncomenzaron a compartirlo e invitar al paro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfDe qu\u00e9 va esta propuesta?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el cartel se\ninvit\u00f3 a mujeres, ni\u00f1as y j\u00f3venes a no participar en actividades cotidianas,\ncomo el trabajo o la escuela, as\u00ed como no comprar nada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNi una mujer en\nlas calles, ni una mujer en los trabajos, ni una ni\u00f1a en las escuelas, ni una\njoven en las universidades, ni una mujer comprando\u00bb, indica esta convocatoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras ser cuestionadas\npor feministas independientes sobre la idea de no salir a la calle y encerrarse\nen casa, as\u00ed como del privilegio que implica poder parar labores, la colectiva\nescribi\u00f3 este viernes que no se trata de que las mujeres \u00abnos invisibilicemos\u00bb\no del \u00absupuesto privilegio al paro\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLos paros\nhist\u00f3ricamente han sido realizados por la clase obrera\u00bb, apunt\u00f3 la\ncolectiva, y destac\u00f3 tambi\u00e9n el impacto econ\u00f3mico que este llamado podr\u00eda\ntener.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Brujas del Mar\ntambi\u00e9n se\u00f1al\u00f3 que diversas mujeres con ideolog\u00edas distintas han compartido la\nconvocatoria, como Margarita Zavala, Denise Dresser y Mon Laferte <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/redsemlac.com\/semmexico\/wp-content\/uploads\/2020\/02\/paro-nacional-corte-8.jpeg\" alt=\"\" class=\"wp-image-17186\" width=\"306\" height=\"304\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Laura Rojas,\npresidenta de la C\u00e1mara de Diputados, se\u00f1al\u00f3 que las mujeres que trabajan en el\nrecinto legislativo y que quieran unirse a la convocatoria tendr\u00e1n garantizado\nel pago de ese d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, la\nSuprema Corte de Justicia de la Naci\u00f3n anunci\u00f3 que sus empleadas, desde\noficiales judiciales hasta los m\u00e1s bajos rangos, podr\u00e1n ausentarse a sus\ncentros de trabajo sin que haya sanciones en su contra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a que varias\nfeministas han se\u00f1alado que no todas las mujeres pueden parar sus labores, han\nsurgido otras propuestas para realizar en el marco del paro, tales como\nutilizar una prenda morada, fijar una hora espec\u00edfica en el trabajo o la\nescuela para realizar un acto simb\u00f3lico, promover el significado del d\u00eda y\ncompartir mensajes a trav\u00e9s de hashtags c\u00f3mo #SiNoParoEsPorque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, este viernes,\nel presidente Andr\u00e9s Manuel L\u00f3pez Obrador afirm\u00f3 que las trabajadoras del\nGobierno federal tienen la \u00ablibertad plena\u00bb de participar en el paro\nnacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo mismo hizo la jefa de Gobierno de la Ciudad de M\u00e9xico, Claudia Sheinbaum, al anunciar que se publicar\u00e1 en la Gaceta de la Ciudad de M\u00e9xico un acuerdo para que las funcionarias de su administraci\u00f3n no sean sancionadas de ninguna manera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resultado de la movilizaci\u00f3n, la protesta y el ya no m\u00e1s.<\/p>\n","protected":false},"author":3,"featured_media":17183,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[691,54],"tags":[],"class_list":["post-17176","post","type-post","status-publish","format-standard","has-post-thumbnail","category-691","category-mujeres"],"_links":{"self":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/17176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/comments?post=17176"}],"version-history":[{"count":0,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/posts\/17176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media\/17183"}],"wp:attachment":[{"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/media?parent=17176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/categories?post=17176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redsemlac.com\/semmexico\/wp-json\/wp\/v2\/tags?post=17176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}